{"id":14314,"date":"2019-06-19T01:00:05","date_gmt":"2019-06-19T04:00:05","guid":{"rendered":"https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/?p=14314"},"modified":"2019-06-18T21:13:12","modified_gmt":"2019-06-19T00:13:12","slug":"heranca-perigosa","status":"publish","type":"post","link":"https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/heranca-perigosa\/","title":{"rendered":"Heran\u00e7a perigosa"},"content":{"rendered":"<p>VISTO, LIDO E OUVIDO, criada por Ari Cunha (In memoriam)<\/p>\n<p>Desde 1960, com Circe Cunha e Mamfil<\/p>\n<p>jornalistacircecunha@gmail.com<\/p>\n<p>Facebook.com\/vistolidoeouvido<\/p>\n<p>Instagram.com\/vistolidoeouvido<\/p>\n<p>&nbsp;<\/p>\n<figure id=\"attachment_14319\" aria-describedby=\"caption-attachment-14319\" style=\"width: 638px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-14319\" src=\"https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/06\/14054565.jpg\" alt=\"\" width=\"638\" height=\"450\" srcset=\"https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/06\/14054565.jpg 638w, https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/06\/14054565-300x212.jpg 300w, https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/06\/14054565-350x247.jpg 350w, https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/06\/14054565-550x388.jpg 550w, https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/06\/14054565-230x162.jpg 230w\" sizes=\"auto, (max-width: 638px) 100vw, 638px\" \/><figcaption id=\"caption-attachment-14319\" class=\"wp-caption-text\">@ Reuters \/ Adriano Machado<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<p>O seriado transmitido pelas TVs nos anos setenta, intitulado Kung Fu, estrelado pelo ator David Carradine, mostrava, logo durante a abertura, que, dentre os desafios para a prepara\u00e7\u00e3o de um jovem monge Shaolin, era preciso caminhar com leveza e destreza sobre fin\u00edssimas e delicadas folhas de papel de arroz sem danific\u00e1-las.<\/p>\n<p>Guardadas as devidas diferen\u00e7as entre fic\u00e7\u00e3o e realidade, essa parece ser tamb\u00e9m a faculdade principal que ter\u00e1 que ser desenvolvida pelo atual presidente da Rep\u00fablica, se quiser chegar inc\u00f3lume ao fim do mandato e com alguma chance de vir a disputar o pr\u00f3ximo pleito ou fazer, quem sabe, um sucessor.<\/p>\n<p>Pelo muito que se tem visto, lido e ouvido sobre o novo chefe do Executivo, Bolsonaro tem atra\u00eddo a sua volta uma multiplicidade de for\u00e7as e a\u00e7\u00f5es pol\u00edticas que diuturnamente conspiram para seu fracasso, oposi\u00e7\u00e3o ao Brasil sem privil\u00e9gios. Das oposi\u00e7\u00f5es dentro do Congresso, passando pelo Ordem dos Advogados do Brasil, UNE, parte do judici\u00e1rio, universidades, movimentos de prote\u00e7\u00e3o ao meio ambiente, movimentos LGBT e outros, todos miram seus canh\u00f5es contra o presidente, acusando-o, inclusive, pela derrocada nos \u00edndices da economia que herdou de outros governos.<\/p>\n<p>Com tanta gente torcendo contra, e devido \u00e0 fragilidade pol\u00edtica do momento atual, com a reorganiza\u00e7\u00e3o das for\u00e7as de uma contrarreforma, visando a manuten\u00e7\u00e3o do antigo status quo, \u00e9 l\u00edcito afirmar que Bolsonaro caminha literalmente sobre finas folhas de papel de arroz. A aumentar ainda mais essa tens\u00e3o, \u00e9 sabido que o presidente, por diversas vezes parece colocar a l\u00edngua na frente do c\u00e9rebro, falando e afirmando certos desejos, que depois se v\u00ea obrigado a corrigi-los ou ajust\u00e1-los \u00e0 realidade.<\/p>\n<p>Num cen\u00e1rio como esse, a situa\u00e7\u00e3o do atual mandat\u00e1rio pode ainda ser agravada se, por uma dessas tramas do destino, o ex-presidente Lula vier a ser solto. Tendo como demonstrativo uma entrevista dada na pris\u00e3o que nada reverberou, pode ser que, nesse caso, ele comece a perceber que o tempo petista chegou ao fim. Ou pode acontecer que caia numa depress\u00e3o, ou mesmo (Deus nos livre!) venha a falecer. Numa situa\u00e7\u00e3o como essa, que n\u00e3o \u00e9 nada imposs\u00edvel, dada a idade do ex-presidente e as condi\u00e7\u00f5es de indiv\u00edduo com restri\u00e7\u00f5es, isolamento e outras fatores negativos, o caldo pode entornar de vez, com as for\u00e7as do atraso criando uma nova narrativa de que Lula, doravante transformado em m\u00e1rtir, teria sido v\u00edtima dos fascistas ou outra vers\u00e3o qualquer.<\/p>\n<p>O que pode \u00e0 primeira vista parecer fic\u00e7\u00e3o, acaba de acontecer no Egito, agora com o falecimento de Mohamed Morsi, primeiro presidente democraticamente eleito, depois da Primavera \u00c1rabe de 2011, e preso dois anos depois. Morsi era um dos l\u00edderes da Irmandade Mu\u00e7ulmana, movimento com forte ades\u00e3o dos cl\u00e9rigos daquele pa\u00eds. Sua morte num tribunal pode, segundo analistas, deflagrar novas ondas de protesto no pa\u00eds.<\/p>\n<p>\u00c9 necess\u00e1rio salientar que Bolsonaro herdou n\u00e3o s\u00f3 a recess\u00e3o econ\u00f4mica legada pelos governos petistas. De quebra, herdou tamb\u00e9m a pris\u00e3o de seu maior l\u00edder, colocado na cadeia por seu atual ministro da justi\u00e7a. Todo o cuidado nesse caso parece ser pouco, at\u00e9 mesmo lavar as m\u00e3os para um fato que parece dizer respeito somente ao judici\u00e1rio.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><strong>A frase que foi pronunciada:<\/strong><\/p>\n<p><em>\u201cUm dia eu fui trotskista e um dia eu rompi com o trotskismo e com o marxismo, por imaginar, ou, por chegar \u00e0 conclus\u00e3o de que o marxismo se acredita dono do futuro. E a cren\u00e7a de que voc\u00ea tem a chave da hist\u00f3ria, de que voc\u00ea sabe o que vai acontecer e o que deve acontecer no futuro \u00e9 uma cren\u00e7a fundamentalmente totalit\u00e1ria. Porque se voc\u00ea sabe, e os outros n\u00e3o, para onde se dirige a humanidade, ent\u00e3o voc\u00ea tem a justificativa pra calar os outros.\u201d<\/em><\/p>\n<p>Dem\u00e9trio Magnoli, jornalista e ge\u00f3grafo<\/p>\n<figure id=\"attachment_14318\" aria-describedby=\"caption-attachment-14318\" style=\"width: 553px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-14318\" src=\"https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/06\/blog-1806.jpg\" alt=\"\" width=\"553\" height=\"368\" srcset=\"https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/06\/blog-1806.jpg 600w, https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/06\/blog-1806-300x200.jpg 300w, https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/06\/blog-1806-350x233.jpg 350w, https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/06\/blog-1806-550x367.jpg 550w, https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/06\/blog-1806-230x153.jpg 230w\" sizes=\"auto, (max-width: 553px) 100vw, 553px\" \/><figcaption id=\"caption-attachment-14318\" class=\"wp-caption-text\">Foto: gazetadopovo.com.br<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Tormento<\/strong><\/p>\n<p>Quantas vezes os consumidores brasileiros s\u00e3o surpreendidos pelo toque do celular onde, do outro lado, telemarketing ou mesmo rob\u00f4s vendem produtos, insistem em novos pacotes. Muito desagrad\u00e1vel e as reclama\u00e7\u00f5es n\u00e3o surtem efeitos. Isso come\u00e7a a mudar pelo mundo.<\/p>\n<figure id=\"attachment_14316\" aria-describedby=\"caption-attachment-14316\" style=\"width: 553px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-14316\" src=\"https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/06\/20190616235115705268u.jpg\" alt=\"\" width=\"553\" height=\"368\" srcset=\"https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/06\/20190616235115705268u.jpg 820w, https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/06\/20190616235115705268u-300x200.jpg 300w, https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/06\/20190616235115705268u-768x511.jpg 768w, https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/06\/20190616235115705268u-350x233.jpg 350w, https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/06\/20190616235115705268u-550x366.jpg 550w, https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/06\/20190616235115705268u-230x153.jpg 230w\" sizes=\"auto, (max-width: 553px) 100vw, 553px\" \/><figcaption id=\"caption-attachment-14316\" class=\"wp-caption-text\">Foto: Ana Rayssa\/Esp. CB\/D.A Press<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Apoio<\/strong><\/p>\n<p>Nenhuma ag\u00eancia do governo protege liga\u00e7\u00f5es de marketing contra os consumidores. Pelo contr\u00e1rio, o governo d\u00e1 os passos para que os consumidores se protejam. Desligar o telefone imediatamente, n\u00e3o tocar em nenhum n\u00famero durante a grava\u00e7\u00e3o e compartilhar a experi\u00eancia com o portal do Escrit\u00f3rio de Prote\u00e7\u00e3o ao Consumidor, FTC. A grava\u00e7\u00e3o do \u00e1udio \u00e9 feita por Kati Daffan e isso acontece nos Estados Unidos.<\/p>\n<p><iframe loading=\"lazy\" title=\"How to respond if you receive a robocall\" width=\"720\" height=\"405\" src=\"https:\/\/www.youtube.com\/embed\/Z1YVaIPtjzs?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><strong>A vingan\u00e7a<\/strong><\/p>\n<p>Mesmo com esse apoio, parece que as empresas de telemarketing ultrapassam todos os limites, inclusive das leis. Est\u00e1 a caminho dos consumidores mundiais um contra rob\u00f4. Uma nova m\u00e1quina que responde \u00e0s insistentes perguntas: Jolly Roger Telephone. Veja a seguir como a m\u00e1quina faz o atendimento por voc\u00ea, para terror dos atendentes!<\/p>\n<p>Acesso ao canal:\u00a0<a href=\"https:\/\/www.youtube.com\/results?search_query=Jolly+Roger+Telephone\">Jolly Roger Telephone Co<\/a><\/p>\n<p><iframe loading=\"lazy\" title=\"Absolute Proof that Jolly Roger Telephone is Disrupting the Vacation Cruise Telemarketers\" width=\"720\" height=\"405\" src=\"https:\/\/www.youtube.com\/embed\/ezZ2V1CH32E?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><strong>HIST\u00d3RIA DE BRAS\u00cdLIA<\/strong><\/p>\n<p>Como n\u00e3o podia deixar de ser, quem planejou n\u00e3o pensou na extens\u00e3o da plataforma, e p\u00f4s alto falantes somente para os que estavam pr\u00f3ximos ao palanque. <strong>(Publicado em 23\/11\/1961)<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>VISTO, LIDO E OUVIDO, criada por Ari Cunha (In memoriam) Desde 1960, com Circe Cunha e Mamfil jornalistacircecunha@gmail.com Facebook.com\/vistolidoeouvido Instagram.com\/vistolidoeouvido &nbsp; &nbsp; O seriado transmitido pelas TVs nos anos setenta, intitulado Kung Fu, estrelado pelo ator David Carradine, mostrava, logo durante a abertura, que, dentre os desafios para a prepara\u00e7\u00e3o de um jovem monge Shaolin, [&hellip;]<\/p>\n","protected":false},"author":34,"featured_media":14319,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"wpb_read_more":[],"footnotes":""},"categories":[23],"tags":[1307,1601,133,1235,114,553,1321,261,1413,119,68,2,69,16],"class_list":["post-14314","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-integra","tag-congressonacional","tag-crisenapolitica","tag-direitaeesquerdanobrasil","tag-governobolsonaro","tag-historiadebrasilia","tag-lula","tag-petismo","tag-politicanobrasil","tag-presidenciadarepublica","tag-pt","tag-aricunha","tag-brasilia","tag-circecunha","tag-mamfil"],"_links":{"self":[{"href":"https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/posts\/14314","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/comments?post=14314"}],"version-history":[{"count":2,"href":"https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/posts\/14314\/revisions"}],"predecessor-version":[{"id":14320,"href":"https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/posts\/14314\/revisions\/14320"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/media\/14319"}],"wp:attachment":[{"href":"https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/media?parent=14314"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/categories?post=14314"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/tags?post=14314"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}