{"id":14449,"date":"2019-07-07T01:00:00","date_gmt":"2019-07-07T04:00:00","guid":{"rendered":"https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/?p=14449"},"modified":"2019-07-06T01:12:43","modified_gmt":"2019-07-06T04:12:43","slug":"arte-e-alma-das-cidades","status":"publish","type":"post","link":"https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/arte-e-alma-das-cidades\/","title":{"rendered":"Arte e alma das cidades"},"content":{"rendered":"<p>VISTO, LIDO E OUVIDO, criada por Ari Cunha (In memoriam)<\/p>\n<p>Desde 1960, com Circe Cunha e Mamfil<\/p>\n<p>jornalistacircecunha@gmail.com<\/p>\n<p>Facebook.com\/vistolidoeouvido<\/p>\n<p>Instagram.com\/vistolidoeouvido<\/p>\n<p>&nbsp;<\/p>\n<figure id=\"attachment_14454\" aria-describedby=\"caption-attachment-14454\" style=\"width: 765px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-14454\" src=\"https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/07\/20190702152545204000i.jpg\" alt=\"\" width=\"765\" height=\"510\" srcset=\"https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/07\/20190702152545204000i.jpg 820w, https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/07\/20190702152545204000i-300x200.jpg 300w, https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/07\/20190702152545204000i-768x512.jpg 768w, https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/07\/20190702152545204000i-350x233.jpg 350w, https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/07\/20190702152545204000i-550x367.jpg 550w, https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/07\/20190702152545204000i-230x153.jpg 230w\" sizes=\"auto, (max-width: 765px) 100vw, 765px\" \/><figcaption id=\"caption-attachment-14454\" class=\"wp-caption-text\">Foto: Inframerica\/Divulga\u00e7\u00e3o<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<p>Na maioria das principais cidades do mundo, sobretudo nos pa\u00edses desenvolvidos, a exposi\u00e7\u00e3o de objetos de arte ao ar livre, como fontes, esculturas, casarios e outras cria\u00e7\u00f5es hist\u00f3ricas e culturais \u00e9 cultuada e preservada pela popula\u00e7\u00e3o como uma verdadeira riqueza material, que testemunha o talento de sua gente e o empenho de muitos em construir e manter uma cidade civilizada e bela, para ser apresentada ao mundo.<\/p>\n<p>Um exemplo desse empenho em proteger e exibir com orgulho obras de grandes artistas pode ser observada em Roma, na It\u00e1lia. A cidade \u00e9 uma verdadeira galeria de arte a c\u00e9u aberto e essa caracter\u00edstica faz daquele s\u00edtio um dos mais visitados de todo o mundo, gerando enormes lucros para cidade, advindos do turismo. Infelizmente n\u00e3o \u00e9 o que acontece atualmente no Brasil. O inc\u00eandio no Museu Nacional do Rio de Janeiro, uma trag\u00e9dia anunciada por muitos especialistas, deu ao mundo o exato valor que dispensamos \u00e0 cultura, \u00e0 hist\u00f3ria e, sobretudo, \u00e0s artes. O Rio de Janeiro, que no passado chegou a ser comparado em beleza \u00e0 Paris, possu\u00eda, em suas principais pra\u00e7as e avenidas, um conjunto bel\u00edssimo de fontes e esculturas de grande valor art\u00edstico e que foram, ao longo do tempo, sendo depredados por v\u00e2ndalos, sob o olhar displicente das autoridades.<\/p>\n<p>At\u00e9 mesmo os cemit\u00e9rios que abrigavam grande quantidade de trabalhos art\u00edsticos foram vilipendiados e roubados um a um. Nesse sentido, falar em arte num pa\u00eds onde se furtam at\u00e9 tampas de bueiro parece uma perda de tempo ou coisa de alienado.<\/p>\n<p>Vivemos em outro planeta Terra, onde a viol\u00eancia e a ignor\u00e2ncia parecem dar o tom ao nosso modus vivendi. Em Bras\u00edlia, concebida para ser a capital de um Brasil, as coisas n\u00e3o s\u00e3o diferentes. Muitos trabalhos art\u00edsticos espalhados pela cidade, tanto ao ar livre como em muitos lugares de pouco acesso do p\u00fablico, sofrem com o descaso. Nossa desaten\u00e7\u00e3o, com um patrim\u00f4nio que \u00e9 de todos n\u00f3s, j\u00e1 \u00e9 not\u00f3ria.<\/p>\n<p>O roubo de uma grande escultura em a\u00e7o de autoria do consagrado artista Yutaka Toyota, situada no centro do antigo e movimentado Bal\u00e3o do Aeroporto, permanece ainda um mist\u00e9rio, cuja a desimport\u00e2ncia dada ao fato explica muito nosso subdesenvolvimento. O mesmo continua a ocorrer hoje com obras de grandes artistas que contribu\u00edram na eleva\u00e7\u00e3o da capital como patrim\u00f4nio cultural da humanidade. Status, diga-se de passagem, que corremos o risco de perder, a continuar o descaso com essa nossa riqueza. Nesses \u00faltimos dias, tem chamado a aten\u00e7\u00e3o as p\u00e9ssimas condi\u00e7\u00f5es de conserva\u00e7\u00e3o notadas nas obras de azulejos e pain\u00e9is de Athos Bulc\u00e3o, cujo os cento e um anos de nascimento foram comemorados nesse s\u00e1bado, na sede da funda\u00e7\u00e3o que leva seu nome.<\/p>\n<p>A situa\u00e7\u00e3o levou inclusive o Minist\u00e9rio P\u00fablico a intervir, como foi no caso dos pain\u00e9is de a\u00e7o no aeroporto internacional de Bras\u00edlia. H\u00e1 alguns anos, um pr\u00e9dio de uma antiga distribuidora de ve\u00edculos na Asa Norte demoliu os azulejos em seu posto de combust\u00edvel. Outro Painel, na mesma loja, foi coberto com propaganda da empresa, o que chegou a gerar protestos nos clientes. A maioria das obras desse artista, expostas ao ar livre, encontra-se em situa\u00e7\u00e3o que requer reparos por conta dos maus tratos e pela a\u00e7\u00e3o de v\u00e2ndalos. Para os especialistas, \u00e9 necess\u00e1ria uma ampla a\u00e7\u00e3o de educa\u00e7\u00e3o patrimonial nas escolas e em toda a parte, de modo a chamar a aten\u00e7\u00e3o para essa riqueza que \u00e9 a alma da cidade.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><strong>A frase que foi pronunciada:<\/strong><\/p>\n<p><em>&#8220;Arquitetura \u00e9 m\u00fasica congelada&#8221;.<\/em><\/p>\n<p>Arthur Schopenhauer, fil\u00f3sofo alem\u00e3o do s\u00e9culo XIX.<\/p>\n<figure id=\"attachment_14453\" aria-describedby=\"caption-attachment-14453\" style=\"width: 300px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-14453\" src=\"https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/07\/Arthur-Schopenhauer.jpg\" alt=\"\" width=\"300\" height=\"358\" srcset=\"https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/07\/Arthur-Schopenhauer.jpg 300w, https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/07\/Arthur-Schopenhauer-251x300.jpg 251w, https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/07\/Arthur-Schopenhauer-293x350.jpg 293w, https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/07\/Arthur-Schopenhauer-230x274.jpg 230w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><figcaption id=\"caption-attachment-14453\" class=\"wp-caption-text\">Arthur Schopenhauer. Pintura de Jules Luntesch\u00fctz, 1855.<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Ponte Norte<\/strong><\/p>\n<p>Com a expans\u00e3o desenfreada das habita\u00e7\u00f5es e a quantidade de carros extrapolando a capacidade das pistas do Parano\u00e1, Varj\u00e3o e da Bragueto, o projeto da ponte do Lago Norte volta \u00e0 tona. Ou deveria voltar. O problema \u00e9 que terrenos j\u00e1 desapropriados para esse fim est\u00e3o misteriosamente ocupados.<\/p>\n<p><iframe loading=\"lazy\" title=\"Projeto da ponte do Lago Norte ligando a UnB e Sobradinho\" width=\"720\" height=\"405\" src=\"https:\/\/www.youtube.com\/embed\/aFlEXKzLang?start=17&amp;feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Em 30 dias<\/strong><\/p>\n<p>Sa\u00edram duas resolu\u00e7\u00f5es da ANP que determinam mais clareza nos pre\u00e7os de combust\u00edveis l\u00edquidos e g\u00e1s natural. Quem produz ou importa os derivados ser\u00e3o obrigados a publicar os pre\u00e7os de cada ponto de suprimento do mercado brasileiro. J\u00e1 as distribuidoras continuam obrigadas a encaminhar seus pre\u00e7os apenas para uso interno da ag\u00eancia.<\/p>\n<figure id=\"attachment_14452\" aria-describedby=\"caption-attachment-14452\" style=\"width: 549px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-14452\" src=\"https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/07\/909044-posto_portesto_gasolina.jpg\" alt=\"\" width=\"549\" height=\"366\" srcset=\"https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/07\/909044-posto_portesto_gasolina.jpg 1140w, https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/07\/909044-posto_portesto_gasolina-300x200.jpg 300w, https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/07\/909044-posto_portesto_gasolina-768x512.jpg 768w, https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/07\/909044-posto_portesto_gasolina-1024x683.jpg 1024w, https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/07\/909044-posto_portesto_gasolina-350x233.jpg 350w, https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/07\/909044-posto_portesto_gasolina-550x367.jpg 550w, https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/07\/909044-posto_portesto_gasolina-230x153.jpg 230w\" sizes=\"auto, (max-width: 549px) 100vw, 549px\" \/><figcaption id=\"caption-attachment-14452\" class=\"wp-caption-text\">Foto: Valter Campanato\/Ag\u00eancia Brasil<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Censo<\/strong><\/p>\n<p>Tarefa que s\u00f3 alguns conseguem. Question\u00e1rios extensos acabam mascarando as respostas, j\u00e1 que o entrevistado come\u00e7a a se sentir incomodado. Com menos or\u00e7amento &#8211; mas n\u00e3o \u00e9 essa a quest\u00e3o -, o IBGE ter\u00e1 pela frente um trabalho interessante: diminuir as perguntas sem perder a qualidade das informa\u00e7\u00f5es. Isso acontecer\u00e1 com o Censo Demogr\u00e1fico de 2020. Susana Guerra, presidente da institui\u00e7\u00e3o, explicou na C\u00e2mara dos Deputados que o mundo est\u00e1 com opera\u00e7\u00f5es mais enxutas e que o trabalho ter\u00e1 a mesma qualidade.<\/p>\n<figure id=\"attachment_14451\" aria-describedby=\"caption-attachment-14451\" style=\"width: 552px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-14451\" src=\"https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/07\/ffraz_abr_28051916268_1.jpg\" alt=\"\" width=\"552\" height=\"368\" srcset=\"https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/07\/ffraz_abr_28051916268_1.jpg 1140w, https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/07\/ffraz_abr_28051916268_1-300x200.jpg 300w, https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/07\/ffraz_abr_28051916268_1-768x512.jpg 768w, https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/07\/ffraz_abr_28051916268_1-1024x683.jpg 1024w, https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/07\/ffraz_abr_28051916268_1-350x233.jpg 350w, https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/07\/ffraz_abr_28051916268_1-550x367.jpg 550w, https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/07\/ffraz_abr_28051916268_1-230x153.jpg 230w\" sizes=\"auto, (max-width: 552px) 100vw, 552px\" \/><figcaption id=\"caption-attachment-14451\" class=\"wp-caption-text\">Foto: Fernando Fraz\u00e3o\/Ag\u00eancia Brasil<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><strong>HIST\u00d3RIA DE BRAS\u00cdLIA<\/strong><\/p>\n<p>Uma das poucas Comiss\u00f5es de Inqu\u00e9rito da C\u00e2mara que devolveram saldo, foi a do caf\u00e9, presidida pelo sr. Dirceu Cardoso, que, findos os trabalhos, devolveu aos cofres da c\u00e2mara a import\u00e2ncia de 80 mil cruzeiros. <strong>(Publicado em 24\/11\/1961)<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>VISTO, LIDO E OUVIDO, criada por Ari Cunha (In memoriam) Desde 1960, com Circe Cunha e Mamfil jornalistacircecunha@gmail.com Facebook.com\/vistolidoeouvido Instagram.com\/vistolidoeouvido &nbsp; &nbsp; Na maioria das principais cidades do mundo, sobretudo nos pa\u00edses desenvolvidos, a exposi\u00e7\u00e3o de objetos de arte ao ar livre, como fontes, esculturas, casarios e outras cria\u00e7\u00f5es hist\u00f3ricas e culturais \u00e9 cultuada e [&hellip;]<\/p>\n","protected":false},"author":34,"featured_media":14454,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"wpb_read_more":[],"footnotes":""},"categories":[23],"tags":[1650,1648,1653,1649,1652,114,1651,68,2,69,16],"class_list":["post-14449","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-integra","tag-arquitetura","tag-artenascidades","tag-artenobrasil","tag-artenomundo","tag-athosbulcao","tag-historiadebrasilia","tag-urbanismo","tag-aricunha","tag-brasilia","tag-circecunha","tag-mamfil"],"_links":{"self":[{"href":"https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/posts\/14449","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/comments?post=14449"}],"version-history":[{"count":2,"href":"https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/posts\/14449\/revisions"}],"predecessor-version":[{"id":14455,"href":"https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/posts\/14449\/revisions\/14455"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/media\/14454"}],"wp:attachment":[{"href":"https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/media?parent=14449"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/categories?post=14449"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/tags?post=14449"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}