{"id":14590,"date":"2019-07-28T01:00:00","date_gmt":"2019-07-28T04:00:00","guid":{"rendered":"https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/?p=14590"},"modified":"2019-07-26T18:38:49","modified_gmt":"2019-07-26T21:38:49","slug":"reparando-os-danos","status":"publish","type":"post","link":"https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/reparando-os-danos\/","title":{"rendered":"Reparando os danos"},"content":{"rendered":"<p>VISTO, LIDO E OUVIDO, criada por Ari Cunha (In memoriam)<\/p>\n<p>Desde 1960, com Circe Cunha e Mamfil<\/p>\n<p>jornalistacircecunha@gmail.com<\/p>\n<p>Facebook.com\/vistolidoeouvido<\/p>\n<p>Instagram.com\/vistolidoeouvido<\/p>\n<p>&nbsp;<\/p>\n<figure id=\"attachment_14597\" aria-describedby=\"caption-attachment-14597\" style=\"width: 429px\" class=\"wp-caption alignright\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-14597\" src=\"https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/07\/Ed-Mercosul.jpg\" alt=\"\" width=\"429\" height=\"654\" srcset=\"https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/07\/Ed-Mercosul.jpg 429w, https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/07\/Ed-Mercosul-197x300.jpg 197w, https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/07\/Ed-Mercosul-230x351.jpg 230w\" sizes=\"auto, (max-width: 429px) 100vw, 429px\" \/><figcaption id=\"caption-attachment-14597\" class=\"wp-caption-text\">Edif\u00edcio sede do Mercosul (Foto: mercosur.int)<\/figcaption><\/figure>\n<p>Com as prioridades impostas pelo petismo nas rela\u00e7\u00f5es internacionais do Brasil, voltadas para o eixo Sul-Sul, com aten\u00e7\u00e3o especial para nosso continente e a seguir para os pa\u00edses africanos e do Oriente M\u00e9dio, surgiram novos blocos como Brics, Unasul, Celac e outros de import\u00e2ncia mais ideol\u00f3gicos do que pr\u00e1ticos e econ\u00f4micos.<\/p>\n<p>A reanima\u00e7\u00e3o de um bloco como o Mercosul, uma entidade at\u00e9 ent\u00e3o natimorta, entrou tamb\u00e9m na mira do governo, apenas sob o \u00e2ngulo de afinidade ideol\u00f3gica. Com o desmanche no ar do petismo, transmutado em lulismo, o que ainda era s\u00f3lido naquele governo foi se juntar no transatl\u00e2ntico \u00e0 deriva, que se tornaram as esquerdas mundo afora, principalmente aquelas que ficaram presas nos anos sessenta, quando o tempo era outro e o mundo, obviamente, era outro tamb\u00e9m.<\/p>\n<p>Desfazer mais de uma d\u00e9cada de equ\u00edvocos nos mecanismos complexos das rela\u00e7\u00f5es internacionais n\u00e3o ser\u00e1 tarefa das mais f\u00e1ceis. Nesse sentido, e abrindo aqui um par\u00eantese, a pretensa nomea\u00e7\u00e3o de um consangu\u00edneo do atual presidente para o mais importante posto das rela\u00e7\u00f5es internacionais, conforme tem sido anunciado, atrapalha muito esse processo de reparo nos estragos feitos e n\u00e3o ajuda, absolutamente, no processo do chamado concerto das na\u00e7\u00f5es em que o Brasil, num passado recente, ocupou lugar de destaque. Ainda \u00e9 cedo para avaliar, com mais acuidade, a nova orienta\u00e7\u00e3o que vem sendo dada \u00e0s rela\u00e7\u00f5es do Brasil com as outras na\u00e7\u00f5es.<\/p>\n<p>Mas uma quest\u00e3o, nesse momento, tamb\u00e9m se imp\u00f5e: \u00e9 preciso aprender com o passado recente e n\u00e3o repetir os mesmos erros que levaram essas rela\u00e7\u00f5es a trilhar um caminho de fundo ideol\u00f3gico com o sinal trocado, obrigando esse minist\u00e9rio a seguir numa dire\u00e7\u00e3o com vi\u00e9s de direita. Antes de tudo \u00e9 preciso retirar esse minist\u00e9rio de orienta\u00e7\u00f5es pol\u00edtico-partid\u00e1rias do momento, livrando esse importante servi\u00e7o para o Pa\u00eds as amarras da pequena pol\u00edtica. Pelo o que se tem visto, n\u00e3o ser\u00e1 tarefa f\u00e1cil. Para tanto, a ideologia dever\u00e1 ser substitu\u00edda pela raz\u00e3o. Uma raz\u00e3o de Estado, conforme \u00e9 visto em todo o mundo desenvolvido do Ocidente. Claro que n\u00e3o baseada apenas em aspectos materiais e quantitativos e na busca cega pelo lucro a qualquer pre\u00e7o, o que nos for\u00e7aria a retornar ao per\u00edodo do mercantilismo do s\u00e9culo XVI, dos super\u00e1vits e do protecionismo. Pelo o que se tem visto, lido e ouvido do atual ministro das Rela\u00e7\u00f5es Exteriores, Ernesto Ara\u00fajo, n\u00e3o se pode mais estabelecer uma pol\u00edtica externa num terreno cercado de grades (ideol\u00f3gicas) onde a raz\u00e3o e pensamento livres n\u00e3o penetrem. Para tanto, em sua opini\u00e3o, \u00e9 preciso, antes de tudo, n\u00e3o limitar o racioc\u00ednio a defini\u00e7\u00f5es de ideologias e aprender a escutar a Na\u00e7\u00e3o brasileira para se fazer uma pol\u00edtica externa em conson\u00e2ncia com o que necessita e deseja sua popula\u00e7\u00e3o. Para ele, \u00e9 necess\u00e1rio, antes de tudo, entender nossos paradigmas e nossa identidade para depois nos relacionarmos com o mundo.<\/p>\n<p>Ao retomar a sua identidade, o Brasil pode, na vis\u00e3o desse ministro, trazer, para as suas rela\u00e7\u00f5es externas, um novo enfoque num mundo globalizado que n\u00e3o \u00e9 constru\u00eddo a partir das na\u00e7\u00f5es, onde n\u00e3o h\u00e1 fronteiras e onde todos parecem ter perdido sua pr\u00f3pria personalidade.<\/p>\n<p>Nesse contexto de globaliza\u00e7\u00e3o, desenfreada e irracional, \u00e9 preciso, em seu entender, que o Brasil reafirme sua posi\u00e7\u00e3o em prol de um mundo composto de povos com pretens\u00f5es e desejos nacionais, com liberdade de ideias dentro da pol\u00edtica externa, com soberania e contra essa \u201cgeleia geral\u201d onde n\u00e3o h\u00e1 fronteiras e identidades de seus povos. \u201cA independ\u00eancia nacional, evidentemente, foi conquistada em 1822 e n\u00e3o parece estar diretamente amea\u00e7ada. Ent\u00e3o, \u00e0s vezes, a gente se pergunta por que esse princ\u00edpio continua figurando na Constitui\u00e7\u00e3o, mas acho que o Constituinte de 1988 foi muito s\u00e1bio nesse sentido, porque a independ\u00eancia n\u00e3o se trata apenas da independ\u00eancia jur\u00eddica, mas precisa ser uma atitude, tem que ser uma independ\u00eancia, por exemplo, em frente aos dogmas politicamente corretos que em muitos setores tendem a presidir o relacionamento internacional; tem que ser uma independ\u00eancia frente a essa ideologia de apagamento das fronteiras e de encerramento das na\u00e7\u00f5es; tem que ser tamb\u00e9m uma independ\u00eancia no sentido de capacitar a nossa economia com mais tecnologia, mais investimento, investimento privado gerando abertura econ\u00f4mica, mais competitividade, mais efici\u00eancia e inova\u00e7\u00e3o\u201d, afirmou o ministro.<\/p>\n<p><iframe loading=\"lazy\" title=\"MERCOSUL video institucional\" width=\"720\" height=\"405\" src=\"https:\/\/www.youtube.com\/embed\/AfHWeOelMLY?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<p><iframe loading=\"lazy\" title=\"Di\u00e1logos na USP - Parcerias Globalizadas (Bloco 1)\" width=\"720\" height=\"405\" src=\"https:\/\/www.youtube.com\/embed\/ulp3teQbMtk?start=2&amp;feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><strong>A frase que foi pronunciada:<\/strong><\/p>\n<p><em>\u201cEm todas as eras, a humanidade produz indiv\u00edduos demon\u00edacos e ideias sedutoras de repress\u00e3o. A tarefa do estadismo \u00e9 impedir sua ascens\u00e3o ao poder e sustentar uma ordem internacional capaz de dissuadi-los, se conseguirem alcan\u00e7\u00e1-lo \u201d.<\/em><\/p>\n<p>Henry Kissinger, diplomata dos Estados Unidos<\/p>\n<figure id=\"attachment_14548\" aria-describedby=\"caption-attachment-14548\" style=\"width: 548px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-14548\" src=\"https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/07\/henry.jpg\" alt=\"\" width=\"548\" height=\"385\" srcset=\"https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/07\/henry.jpg 695w, https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/07\/henry-300x211.jpg 300w, https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/07\/henry-350x246.jpg 350w, https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/07\/henry-550x386.jpg 550w, https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/07\/henry-230x161.jpg 230w\" sizes=\"auto, (max-width: 548px) 100vw, 548px\" \/><figcaption id=\"caption-attachment-14548\" class=\"wp-caption-text\">Foto: rocco.com<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Ari Cunha<\/strong><\/p>\n<p>Ser\u00e1 na quarta-feira a missa de um ano sem nosso titular nessa coluna. Na Par\u00f3quia S\u00e3o Francisco de Assis, SGAN 915, \u00e0s 19h.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-13159 aligncenter\" src=\"https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/01\/Ari-Cunha-Frases.jpg\" alt=\"\" width=\"563\" height=\"792\" srcset=\"https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/01\/Ari-Cunha-Frases.jpg 448w, https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/01\/Ari-Cunha-Frases-213x300.jpg 213w, https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/01\/Ari-Cunha-Frases-249x350.jpg 249w, https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/01\/Ari-Cunha-Frases-230x323.jpg 230w\" sizes=\"auto, (max-width: 563px) 100vw, 563px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><strong>HIST\u00d3RIA DE BRAS\u00cdLIA<\/strong><\/p>\n<p>Bras\u00edlia est\u00e1 amea\u00e7ada pela elei\u00e7\u00e3o para vereadores. No regime presidencialista, defend\u00edamos a tese do voto, pelo cidad\u00e3o brasiliense, apenas para presidente e vice-presidente. <strong>(Publicado em 26\/11\/1961)<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>VISTO, LIDO E OUVIDO, criada por Ari Cunha (In memoriam) Desde 1960, com Circe Cunha e Mamfil jornalistacircecunha@gmail.com Facebook.com\/vistolidoeouvido Instagram.com\/vistolidoeouvido &nbsp; Com as prioridades impostas pelo petismo nas rela\u00e7\u00f5es internacionais do Brasil, voltadas para o eixo Sul-Sul, com aten\u00e7\u00e3o especial para nosso continente e a seguir para os pa\u00edses africanos e do Oriente M\u00e9dio, surgiram [&hellip;]<\/p>\n","protected":false},"author":34,"featured_media":14597,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"wpb_read_more":[],"footnotes":""},"categories":[23],"tags":[1533,1700,153,114,1641,68,5,2,69,16],"class_list":["post-14590","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-integra","tag-americalatina","tag-comercio","tag-economia","tag-historiadebrasilia","tag-mercosul","tag-aricunha","tag-brasil","tag-brasilia","tag-circecunha","tag-mamfil"],"_links":{"self":[{"href":"https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/posts\/14590","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/comments?post=14590"}],"version-history":[{"count":4,"href":"https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/posts\/14590\/revisions"}],"predecessor-version":[{"id":14600,"href":"https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/posts\/14590\/revisions\/14600"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/media\/14597"}],"wp:attachment":[{"href":"https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/media?parent=14590"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/categories?post=14590"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/tags?post=14590"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}