{"id":14954,"date":"2019-09-21T01:00:56","date_gmt":"2019-09-21T04:00:56","guid":{"rendered":"https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/?p=14954"},"modified":"2019-09-21T09:22:22","modified_gmt":"2019-09-21T12:22:22","slug":"amazonia-uma-filha-maltratada","status":"publish","type":"post","link":"https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/amazonia-uma-filha-maltratada\/","title":{"rendered":"Amaz\u00f4nia, uma filha maltratada"},"content":{"rendered":"<p>VISTO, LIDO E OUVIDO, criada por Ari Cunha (In memoriam)<\/p>\n<p>Desde 1960, com Circe Cunha e Mamfil<\/p>\n<p>jornalistacircecunha@gmail.com<\/p>\n<p>Facebook.com\/vistolidoeouvido<\/p>\n<p>Instagram.com\/vistolidoeouvido<\/p>\n<p>&nbsp;<\/p>\n<figure id=\"attachment_14958\" aria-describedby=\"caption-attachment-14958\" style=\"width: 624px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-14958\" src=\"https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/09\/108586816_amazoniagetty.jpg\" alt=\"\" width=\"624\" height=\"351\" srcset=\"https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/09\/108586816_amazoniagetty.jpg 624w, https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/09\/108586816_amazoniagetty-300x169.jpg 300w, https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/09\/108586816_amazoniagetty-350x197.jpg 350w, https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/09\/108586816_amazoniagetty-550x309.jpg 550w, https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/09\/108586816_amazoniagetty-230x129.jpg 230w\" sizes=\"auto, (max-width: 624px) 100vw, 624px\" \/><figcaption id=\"caption-attachment-14958\" class=\"wp-caption-text\">Foto: BBC<\/figcaption><\/figure>\n<p align=\"justify\"><span style=\"color: #222222\">Soberania, com o sentido de dom\u00ednio inconteste e irrenunci\u00e1vel sobre um determinado bem, um mantra t\u00e3o caro as alas militares de todo o planeta ao longo da hist\u00f3ria, parece possuir, no mundo atual, que se\u00a0pretende\u00a0globalizado, uma outra sem\u00e2ntica. Essa signific\u00e2ncia mais dilu\u00edda e imprecisa,\u00a0obviamente,\u00a0p\u00f5e de cabelos em p\u00e9\u00a0todos aqueles grupos\u00a0que acreditam que esse dom\u00ednio e posse,\u00a0antes de quaisquer outros sentidos,\u00a0representa uma carta\u00a0branca de alforria\u00a0para, inclusive, pulverizar esse bem , transformando-o em cinzas.<\/span><\/p>\n<p align=\"justify\"><span style=\"color: #222222\">Numa analogia mais aproximada, seria como se um pai, por sua autoridade de progenitor, possu\u00edsse tamb\u00e9m o direito de vida e morte sobre seu filho (ou a m\u00e3e, mas a\u00ed j\u00e1 \u00e9 outra hist\u00f3ria). N\u00e3o s\u00f3 para o mundo moderno, mas em todo o tempo e lugar, o sentido de dom\u00ednio sempre foi imposto pelo poderio da for\u00e7a b\u00e9lica. Ocorre que na atualidade essa posse tamb\u00e9m passou a ser encarada pela no\u00e7\u00e3o de responsabilidade\u00a0e\u00a0respeito\u00a0por esse bem.<\/span><\/p>\n<p align=\"justify\"><span style=\"color: #222222\">Da posse pelo uso,\u00a0do passado,\u00a0passou-se\u00a0agora\u00a0a posse\u00a0pelo zelo. Dono, repetia o fil\u00f3sofo de Mondubim, \u00e9 quem cuida, assim como pai \u00e9 quem cria.\u00a0A dilui\u00e7\u00e3o de fronteiras, a conhecida escassez progressiva\u00a0e alarmante\u00a0de recursos naturais e sobretudo os efeitos indiscut\u00edveis das mudan\u00e7as clim\u00e1ticas, colocam a grande regi\u00e3o amaz\u00f4nica no centro das aten\u00e7\u00f5es mundiais pelas mais diversas raz\u00f5es. Algumas coerentes e\u00a0outras estrat\u00e9gicas,\u00a0decorrentes das presentes e urgentes necessidades da esp\u00e9cie humana.<\/span><\/p>\n<p align=\"justify\"><span style=\"color: #222222\">Com isso, o que se quer clarear aqui, \u00e9 sobre a necessidade de o Estado brasileiro\u00a0passar a ver\u00a0aquela regi\u00e3o, sempre deixada \u00e0 margem,\u00a0com um novo olhar,\u00a0assumindo\u00a0uma responsabilidade para al\u00e9m da ret\u00f3rica da for\u00e7a, considerando aquela metade do pa\u00eds, como um centro de aten\u00e7\u00e3o\u00a0e cuidados\u00a0permanentes. Para tanto, \u00e9 preciso abandonar o passado extrativista, primitivo\u00a0e predador, adotando agora uma moderna estrat\u00e9gia\u00a0que possa, inclusive, servir de par\u00e2metro para o restante do planeta.<\/span><\/p>\n<p align=\"justify\"><span style=\"color: #222222\">Foi preciso que mundo desse um pux\u00e3o de orelhas no novo governo para que ele se conscientizasse de que esse problema hist\u00f3rico do abandono a que sempre foi relegada aquela regi\u00e3o, havia chegado ao limite do toler\u00e1vel. Claro que essa situa\u00e7\u00e3o atual resulta de um passado sistem\u00e1tico de descaso e desaten\u00e7\u00e3o, n\u00e3o s\u00f3 por parte do governo federal, mas sobretudo por parte das lideran\u00e7as daquela regi\u00e3o, tradicionalmente preocupadas mais em enriquecer a si a aos seus em detrimento da floresta e de seus habitantes. Pelo volume que tomou essa quest\u00e3o, \u00e9 que os problemas da regi\u00e3o amaz\u00f4nica, por complexidade\u00a0e grandeza,\u00a0representam\u00a0hoje o maior desafio da atualidade para o pa\u00eds. Bravatas e outros gritos de guerra roucos, de nada adiantam. Dizer aos vizinhos que o filho \u00e9 seu e voc\u00ea o castiga o quanto quer, pode ter um pre\u00e7o impag\u00e1vel.<\/span><\/p>\n<p align=\"justify\"><span style=\"color: #222222\">Uma esp\u00e9cie de conselho tutelar do mundo se formou e pode deitar sua m\u00e3o pesada sobre Estados irrespons\u00e1veis, como \u00e9 hoje o nosso caso.<\/span><\/p>\n<p align=\"justify\">\n<p align=\"justify\">\n<p align=\"justify\"><strong><span style=\"color: #222222\">A frase que foi pronunciada:<\/span><\/strong><\/p>\n<p align=\"justify\"><span style=\"color: #222222\">\u201c<\/span><i><span style=\"color: #222222\">Estamos nos afogando em informa\u00e7\u00f5es, enquanto ansiamos por sabedoria. A partir de agora, o mundo ser\u00e1 dirigido por sintetizadores, pessoas capazes de reunir as informa\u00e7\u00f5es certas no momento certo, pensar criticamente sobre elas e fazer escolhas importantes com sabedoria.<\/span><\/i><span style=\"color: #222222\">\u201d<\/span><\/p>\n<p align=\"justify\"><span style=\"color: #222222\">Edward Osborne Wilson, entomologista norte americano e bi\u00f3logo<\/span><\/p>\n<p align=\"justify\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-14959 aligncenter\" src=\"https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/09\/Edward_O._Wilson_2003_cropped.jpg\" alt=\"\" width=\"380\" height=\"537\" srcset=\"https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/09\/Edward_O._Wilson_2003_cropped.jpg 420w, https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/09\/Edward_O._Wilson_2003_cropped-212x300.jpg 212w, https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/09\/Edward_O._Wilson_2003_cropped-247x350.jpg 247w, https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/09\/Edward_O._Wilson_2003_cropped-230x325.jpg 230w\" sizes=\"auto, (max-width: 380px) 100vw, 380px\" \/><\/p>\n<p align=\"justify\"><strong><span style=\"color: #222222\">Educa\u00e7\u00e3o<\/span><\/strong><\/p>\n<p align=\"justify\"><span style=\"color: #222222\">Embrapa cria uma cartilha<a href=\"https:\/\/www.embrapa.br\/busca-de-publicacoes\/-\/publicacao\/1112087\/tres-familias-e-o-fogo-um-encontro-no-cerrado\"> \u201cTr\u00eas fam\u00edlias e o fogo &#8211; um encontro no Cerrado\u201d<\/a> onde a comunidade come\u00e7a a aprender sobre as estrat\u00e9gias com o fogo para combater o pr\u00f3prio fogo, al\u00e9m de outras t\u00e9cnicas para o manejo de \u00e1reas. Alunos do quinto ano da Escola Classe 111 Sul foram os primeiros a receber a cartilha durante visita do grupo \u00e0 Embrapa Cerrados.<\/span><\/p>\n<p align=\"justify\"><span style=\"color: #222222\">\u00a0<\/span><\/p>\n<p align=\"justify\"><strong><span style=\"color: #222222\">Calor<\/span><\/strong><\/p>\n<p align=\"justify\"><span style=\"color: #222222\">Bras\u00edlia alcan\u00e7ou os 34\u00baC, sendo o mais alto grau da hist\u00f3ria da cidade. A umidade parece menor que os 13% apontados pelos ponteiros. Onde est\u00e3o as cigarras que em setembro chamavam as chuvas?<\/span><\/p>\n<figure id=\"attachment_14960\" aria-describedby=\"caption-attachment-14960\" style=\"width: 551px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-14960\" src=\"https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/09\/Capturar-4.png\" alt=\"\" width=\"551\" height=\"366\" srcset=\"https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/09\/Capturar-4.png 751w, https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/09\/Capturar-4-300x199.png 300w, https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/09\/Capturar-4-350x233.png 350w, https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/09\/Capturar-4-550x365.png 550w, https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/09\/Capturar-4-230x153.png 230w\" sizes=\"auto, (max-width: 551px) 100vw, 551px\" \/><figcaption id=\"caption-attachment-14960\" class=\"wp-caption-text\">Charge: Pelicano<\/figcaption><\/figure>\n<p align=\"justify\"><strong><span style=\"color: #222222\">Boicote<\/span><\/strong><\/p>\n<p align=\"justify\"><span style=\"color: #222222\">Para denunciar o pre\u00e7o abusivo cobrado pelos postos de gasolina est\u00e3o usando tamb\u00e9m o e-mail \u00a0<\/span><a href=\"mailto:151@procon.df.gov.br\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #1155cc\">151@procon.df.gov.br<\/span><\/a><span style=\"color: #222222\">\u00a0. Entende-se que mais de R$4,22 \u00e9 valor acima do normal. A tecnologia ajuda no boicote aos altos pre\u00e7os.<\/span><\/p>\n<figure id=\"attachment_14961\" aria-describedby=\"caption-attachment-14961\" style=\"width: 548px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-14961\" src=\"https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/09\/108586816_amazoniagetty-1.jpg\" alt=\"\" width=\"548\" height=\"329\" srcset=\"https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/09\/108586816_amazoniagetty-1.jpg 820w, https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/09\/108586816_amazoniagetty-1-300x180.jpg 300w, https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/09\/108586816_amazoniagetty-1-768x461.jpg 768w, https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/09\/108586816_amazoniagetty-1-350x210.jpg 350w, https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/09\/108586816_amazoniagetty-1-550x330.jpg 550w, https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/09\/108586816_amazoniagetty-1-230x138.jpg 230w\" sizes=\"auto, (max-width: 548px) 100vw, 548px\" \/><figcaption id=\"caption-attachment-14961\" class=\"wp-caption-text\">foto: Rafaela Gon\u00e7alves\/Esp. CB\/D.A Press<\/figcaption><\/figure>\n<p align=\"justify\"><strong><span style=\"color: #222222\">Dilma<\/span><\/strong><\/p>\n<p align=\"justify\"><span style=\"color: #222222\">Espetacular a entrevista da ex-presidenta Dilma dada ao Juca Kfouri. Ela fala muito bem quando est\u00e1 entre 4 paredes.\u00a0<\/span><\/p>\n<p><iframe loading=\"lazy\" title=\"Dilma Rousseff no Entre Vistas\" width=\"720\" height=\"405\" src=\"https:\/\/www.youtube.com\/embed\/96XSM8aDIR0?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<p align=\"justify\"><span style=\"color: #222222\"><b>HIST\u00d3RIA DE BRAS\u00cdLIA <\/b><\/span><\/p>\n<p align=\"justify\"><span style=\"color: #222222\">E por falar nisto, doutor, seja contra a elei\u00e7\u00e3o para vereadores em Bras\u00edlia. Mesmo que o senhor se desgaste, seja contra. Est\u00e3o fazendo horrores, em mat\u00e9ria de pol\u00edtica, nas cidades sat\u00e9lites. Parece S\u00e3o Jo\u00e3o Del Rey na campanha eleitoral. <strong>(Publicado em 30\/11\/1961)<\/strong><\/span><\/p>\n<p align=\"justify\">\n","protected":false},"excerpt":{"rendered":"<p>VISTO, LIDO E OUVIDO, criada por Ari Cunha (In memoriam) Desde 1960, com Circe Cunha e Mamfil jornalistacircecunha@gmail.com Facebook.com\/vistolidoeouvido Instagram.com\/vistolidoeouvido &nbsp; Soberania, com o sentido de dom\u00ednio inconteste e irrenunci\u00e1vel sobre um determinado bem, um mantra t\u00e3o caro as alas militares de todo o planeta ao longo da hist\u00f3ria, parece possuir, no mundo atual, que [&hellip;]<\/p>\n","protected":false},"author":34,"featured_media":14958,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"wpb_read_more":[],"footnotes":""},"categories":[23],"tags":[1737,1745,1235,114,1573,1550,68,2,69,16],"class_list":["post-14954","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-integra","tag-amazonia","tag-florestaamazonica","tag-governobolsonaro","tag-historiadebrasilia","tag-ministeriodaagriculturaemeioambiente","tag-preservacaodomeioambiente","tag-aricunha","tag-brasilia","tag-circecunha","tag-mamfil"],"_links":{"self":[{"href":"https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/posts\/14954","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/comments?post=14954"}],"version-history":[{"count":5,"href":"https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/posts\/14954\/revisions"}],"predecessor-version":[{"id":14965,"href":"https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/posts\/14954\/revisions\/14965"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/media\/14958"}],"wp:attachment":[{"href":"https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/media?parent=14954"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/categories?post=14954"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/tags?post=14954"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}