{"id":15198,"date":"2019-10-30T01:00:58","date_gmt":"2019-10-30T04:00:58","guid":{"rendered":"https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/?p=15198"},"modified":"2019-10-30T15:23:55","modified_gmt":"2019-10-30T18:23:55","slug":"crimes-comuns","status":"publish","type":"post","link":"https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/crimes-comuns\/","title":{"rendered":"Crimes comuns"},"content":{"rendered":"<p>VISTO, LIDO E OUVIDO, criada por Ari Cunha (In memoriam)<\/p>\n<p>Desde 1960, com Circe Cunha e Mamfil<\/p>\n<p>jornalistacircecunha@gmail.com<\/p>\n<p>Facebook.com\/vistolidoeouvido<\/p>\n<p>Instagram.com\/vistolidoeouvido<\/p>\n<p>&nbsp;<\/p>\n<figure id=\"attachment_15201\" aria-describedby=\"caption-attachment-15201\" style=\"width: 574px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-15201\" src=\"https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/10\/Foto-montagem-Portal-de-Prefeitura-.png\" alt=\"\" width=\"574\" height=\"382\" srcset=\"https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/10\/Foto-montagem-Portal-de-Prefeitura-.png 527w, https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/10\/Foto-montagem-Portal-de-Prefeitura--300x200.png 300w, https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/10\/Foto-montagem-Portal-de-Prefeitura--350x233.png 350w, https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/10\/Foto-montagem-Portal-de-Prefeitura--230x153.png 230w\" sizes=\"auto, (max-width: 574px) 100vw, 574px\" \/><figcaption id=\"caption-attachment-15201\" class=\"wp-caption-text\">Foto Montagem Portal de Prefeitura<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<p>Com a decis\u00e3o adotada agora pelo Parlamento Europeu, igualando e condenando os regimes nazista e comunista como ideologias totalit\u00e1rias, respons\u00e1veis por in\u00fameros casos de genoc\u00eddio e deporta\u00e7\u00f5es \u201cem uma escala nunca vista na hist\u00f3ria da humanidade\u201d, foi dado o primeiro e talvez o mais importante passo para o in\u00edcio de um movimento revisionista que busca enquadrar essas ditaduras pol\u00edticas no rol das bestialidades criadas por nossa esp\u00e9cie.\u00a0 Mais sintom\u00e1tico, talvez, tenha sido o sil\u00eancio imposto a essa importante resolu\u00e7\u00e3o, pelos pa\u00edses e partidos comunistas, o que reafirma o comportamento hist\u00f3rico dessas ideologias de manter longe do debate p\u00fablico qualquer discuss\u00e3o que ouse desafiar os dogmas desses regimes.<\/p>\n<p>Trata-se, sem d\u00favida, de uma resolu\u00e7\u00e3o hist\u00f3rica, aprovada pela esmagadora maioria do mais importante colegiado da Uni\u00e3o Europeia e que foi contido no documento intitulado \u201cImportance of European Remembrance for the Future of\u00a0 Europe\u201d. Na realidade, esse debate teve in\u00edcio ainda em 1956 com as revela\u00e7\u00f5es feitas por Khrushchev, durante o XX Congresso do Partido Comunista da Antiga Uni\u00e3o Sovi\u00e9tica, quando relatou, em discurso famoso, as atrocidades cometidas por Stalin durante seus 33 anos no poder. Esse discurso mudaria a hist\u00f3ria da R\u00fassia e o comunismo mundial, levando muitos intelectuais que at\u00e9 ent\u00e3o apoiavam o regime a revisar seus conceitos. A imensa rela\u00e7\u00e3o de mortos apresentada naquela ocasi\u00e3o, inclusive dos pr\u00f3prios companheiros de luta de Stalin chocou o mundo pelos n\u00fameros e serviu de modo fantasticamente iconoclasta para destruir o mito do guia genial de todos os povos, mostrando aquele l\u00edder como um homem sanguin\u00e1rio e paranoico, respons\u00e1vel por milh\u00f5es de assassinatos e pris\u00f5es.<\/p>\n<p>Em 1989, com a queda do Muro de Berlim, esse debate trouxe mais revela\u00e7\u00f5es sobre o que acontecia por detr\u00e1s da Cortina de Ferro da Europa: milh\u00f5es de outros cad\u00e1veres foram se juntar a conta dos regimes comunistas impostos pela URSS. Em 1997 um grupo de historiadores compilaram, no \u201cLivro Negro do Comunismo\u201d, um balan\u00e7o geral, preciso e extremamente bem documentado sobre as perdas humanas provocadas pelos regimes comunistas em todo o mundo. Desse levantamento surgiu um n\u00famero horripilante de 100 milh\u00f5es de mortos, num per\u00edodo de aproximadamente meio s\u00e9culo.<\/p>\n<p>Pela resolu\u00e7\u00e3o aprovada pelo Parlamento Europeu \u00e9 feito um apelo a essa e \u00e0s novas gera\u00e7\u00f5es \u201cuma cultura comum da mem\u00f3ria que rejeite os crimes dos regimes fascistas e comunistas e de outros regimes totalit\u00e1rios e autorit\u00e1rios do passado como forma de promover a resili\u00eancia contra as amea\u00e7as modernas \u00e0 democracia, em particular entre a gera\u00e7\u00e3o mais jovem\u201d. A condena\u00e7\u00e3o do comunismo como um regime equivalente ao nazismo, coloca no mesmo banco de r\u00e9us dois regimes radicais e antidemocr\u00e1ticos, que usaram o ser humano como pe\u00e7as descart\u00e1veis para compor o poderio ilimitado de l\u00edderes para os quais a dignidade dos indiv\u00edduos n\u00e3o possui valor algum. O tempo em hist\u00f3ria cuida para que cada elemento e cada fato voltem para seu lugar de origem, repondo a ordem do sistema universal, revelando o que foi oculto, abrindo velhas caixas, colocando tudo de volta exposto \u00e0 luz, como deve ser.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>A frase que foi pronunciada:<\/strong><\/p>\n<p><em>\u201cO ministro Celso de Mello n\u00e3o pode condenar o v\u00eddeo do presidente Bolsonaro. Ele precisa aguardar at\u00e9 o tr\u00e2nsito em julgado.\u201d<\/em><\/p>\n<p>Deputada Federal pelo PSL Raquel Stasiaki, em seu perfil pessoal no Twitter<\/p>\n<figure id=\"attachment_15199\" aria-describedby=\"caption-attachment-15199\" style=\"width: 400px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-15199\" src=\"https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/10\/rNtooeO4_400x400.png\" alt=\"\" width=\"400\" height=\"400\" srcset=\"https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/10\/rNtooeO4_400x400.png 400w, https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/10\/rNtooeO4_400x400-150x150.png 150w, https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/10\/rNtooeO4_400x400-300x300.png 300w, https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/10\/rNtooeO4_400x400-350x350.png 350w, https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/10\/rNtooeO4_400x400-230x230.png 230w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><figcaption id=\"caption-attachment-15199\" class=\"wp-caption-text\">Foto: twitter.com\/raquelstasiaki<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Proposta<\/strong><\/p>\n<p>Proposta do Ministro Toffoli contra a prescri\u00e7\u00e3o tem sido recebida, por pol\u00edticos que ainda prezam pelo combate ao crime, como um placebo e uma fantasia para acabar com a impunidade, al\u00e9m de uma maneira de passar a bola para o Congresso de uma discuss\u00e3o t\u00e3o cara aos brasileiros, j\u00e1 que seu voto parece seguir em dire\u00e7\u00e3o ao retrocesso. A sociedade est\u00e1 de olho nessa manobra que pretende vestir a lei com uma roupagem pol\u00edtica de ocasi\u00e3o e sem compromisso s\u00e9rio com a realidade nacional.<\/p>\n<figure id=\"attachment_14556\" aria-describedby=\"caption-attachment-14556\" style=\"width: 549px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-14556\" src=\"https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/07\/x82357352_BSBBrasiliaBrasil24-04-2019Ministro-Dias-Toffoli-preside-sessao-plenaria-do-Sup.jpg.pagespeed.ic_.FLAfzngLz0.jpg\" alt=\"\" width=\"549\" height=\"329\" srcset=\"https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/07\/x82357352_BSBBrasiliaBrasil24-04-2019Ministro-Dias-Toffoli-preside-sessao-plenaria-do-Sup.jpg.pagespeed.ic_.FLAfzngLz0.jpg 1086w, https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/07\/x82357352_BSBBrasiliaBrasil24-04-2019Ministro-Dias-Toffoli-preside-sessao-plenaria-do-Sup.jpg.pagespeed.ic_.FLAfzngLz0-300x180.jpg 300w, https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/07\/x82357352_BSBBrasiliaBrasil24-04-2019Ministro-Dias-Toffoli-preside-sessao-plenaria-do-Sup.jpg.pagespeed.ic_.FLAfzngLz0-768x461.jpg 768w, https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/07\/x82357352_BSBBrasiliaBrasil24-04-2019Ministro-Dias-Toffoli-preside-sessao-plenaria-do-Sup.jpg.pagespeed.ic_.FLAfzngLz0-1024x615.jpg 1024w, https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/07\/x82357352_BSBBrasiliaBrasil24-04-2019Ministro-Dias-Toffoli-preside-sessao-plenaria-do-Sup.jpg.pagespeed.ic_.FLAfzngLz0-350x210.jpg 350w, https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/07\/x82357352_BSBBrasiliaBrasil24-04-2019Ministro-Dias-Toffoli-preside-sessao-plenaria-do-Sup.jpg.pagespeed.ic_.FLAfzngLz0-550x330.jpg 550w, https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/07\/x82357352_BSBBrasiliaBrasil24-04-2019Ministro-Dias-Toffoli-preside-sessao-plenaria-do-Sup.jpg.pagespeed.ic_.FLAfzngLz0-230x138.jpg 230w\" sizes=\"auto, (max-width: 549px) 100vw, 549px\" \/><figcaption id=\"caption-attachment-14556\" class=\"wp-caption-text\">Foto: Jorge William 24\/04\/2019 \/ Ag\u00eancia O Globo<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><strong>\u00d3leo 1<\/strong><\/p>\n<p>Com o reconhecimento tardio de que o vazamento de \u00f3leo no litoral nordestino \u00e9 o maior desastre ambiental j\u00e1 ocorrido na hist\u00f3ria do pa\u00eds, as autoridades brasileiras correm atr\u00e1s dos preju\u00edzos. A medida em que o \u00f3leo avan\u00e7a sobre as praias paradis\u00edacas, com preju\u00edzos inconceb\u00edveis para a flora, a fauna e para o turismo, que \u00e9 a principal fonte de renda de milhares de fam\u00edlias na alta esta\u00e7\u00e3o do ver\u00e3o, vai ficando mais claro de que a imensid\u00e3o de mais de 8 mil quil\u00f4metros do litoral brasileiro est\u00e1 em descoberto, assim como os 15.700 quil\u00f4metros de fronteiras secas.<\/p>\n<figure id=\"attachment_15142\" aria-describedby=\"caption-attachment-15142\" style=\"width: 551px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-15142\" src=\"https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/10\/fotooleo-c74adf025f3f26d377ef0989a2c1e987-1200x600.jpg\" alt=\"\" width=\"551\" height=\"276\" \/><figcaption id=\"caption-attachment-15142\" class=\"wp-caption-text\">Praia de Ipojuc\u00e1 (PE) &#8211; Teresa Maia\/Folhapress<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><strong>\u00d3leo 2<\/strong><\/p>\n<p>Em decorr\u00eancia desse mega crime contra o meio ambiente no litoral nordestino, h\u00e1 a possibilidade de os leil\u00f5es dos campos de pr\u00e9-sal, coordenados pela Petrobras, trazerem de volta, aos brasileiros, a sensa\u00e7\u00e3o de que o litoral do pa\u00eds ficar\u00e1 ainda mais fragilizado e submetido a riscos de novos vazamentos.<\/p>\n<figure id=\"attachment_15090\" aria-describedby=\"caption-attachment-15090\" style=\"width: 548px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-15090\" src=\"https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/10\/mancha.jpg\" alt=\"\" width=\"548\" height=\"294\" srcset=\"https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/10\/mancha.jpg 854w, https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/10\/mancha-300x161.jpg 300w, https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/10\/mancha-768x413.jpg 768w, https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/10\/mancha-350x188.jpg 350w, https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/10\/mancha-550x296.jpg 550w, https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/10\/mancha-230x124.jpg 230w\" sizes=\"auto, (max-width: 548px) 100vw, 548px\" \/><figcaption id=\"caption-attachment-15090\" class=\"wp-caption-text\">Foto: Simone Santos\/Projeto Praia Limpa<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Mercosul<\/strong><\/p>\n<p>Ap\u00f3s as elei\u00e7\u00f5es na Argentina, a impress\u00e3o \u00e9 a de que o futuro do Mercosul ficar\u00e1, mais uma vez, submetido \u00e0s varia\u00e7\u00f5es c\u00edclicas e ideol\u00f3gicas dos pa\u00edses membros. Com a decis\u00e3o agora do Parlamento Europeu de equiparar o comunismo ao nazismo, como doutrinas totalit\u00e1rias e criminosas, o sinal de aprova\u00e7\u00e3o e que pode vir desse colegiado para os acordos entre a Europa e o Mercosul pode n\u00e3o ser dado com base nessa premissa.<\/p>\n<figure id=\"attachment_14597\" aria-describedby=\"caption-attachment-14597\" style=\"width: 429px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-14597\" src=\"https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/07\/Ed-Mercosul.jpg\" alt=\"\" width=\"429\" height=\"654\" srcset=\"https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/07\/Ed-Mercosul.jpg 429w, https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/07\/Ed-Mercosul-197x300.jpg 197w, https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/07\/Ed-Mercosul-230x351.jpg 230w\" sizes=\"auto, (max-width: 429px) 100vw, 429px\" \/><figcaption id=\"caption-attachment-14597\" class=\"wp-caption-text\">Edif\u00edcio sede do Mercosul (Foto: mercosur.int)<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><strong>HIST\u00d3RIA DE BRAS\u00cdLIA<\/strong><\/p>\n<p>Os teletipos dos jornais n\u00e3o funcionam. Na Meridional, a maioria do notici\u00e1rio \u00e9 transmitida por telefone, porque os teletipos est\u00e3o parados. Tanto o internacional como o nacional. <strong>(Publicado em 03\/12\/1961)<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>VISTO, LIDO E OUVIDO, criada por Ari Cunha (In memoriam) Desde 1960, com Circe Cunha e Mamfil jornalistacircecunha@gmail.com Facebook.com\/vistolidoeouvido Instagram.com\/vistolidoeouvido &nbsp; &nbsp; Com a decis\u00e3o adotada agora pelo Parlamento Europeu, igualando e condenando os regimes nazista e comunista como ideologias totalit\u00e1rias, respons\u00e1veis por in\u00fameros casos de genoc\u00eddio e deporta\u00e7\u00f5es \u201cem uma escala nunca vista na [&hellip;]<\/p>\n","protected":false},"author":34,"featured_media":15201,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"wpb_read_more":[],"footnotes":""},"categories":[23],"tags":[1886,1883,114,1884,1888,1887,1885,1642,68,2,69,16],"class_list":["post-15198","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-integra","tag-autoritarismo","tag-comunistmo","tag-historiadebrasilia","tag-nazismo","tag-parlamentoeuropeu","tag-regimestotalitarios","tag-totalitarismo","tag-uniaoeuropeia","tag-aricunha","tag-brasilia","tag-circecunha","tag-mamfil"],"_links":{"self":[{"href":"https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/posts\/15198","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/comments?post=15198"}],"version-history":[{"count":4,"href":"https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/posts\/15198\/revisions"}],"predecessor-version":[{"id":15205,"href":"https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/posts\/15198\/revisions\/15205"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/media\/15201"}],"wp:attachment":[{"href":"https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/media?parent=15198"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/categories?post=15198"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/tags?post=15198"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}