{"id":15271,"date":"2019-11-09T01:00:01","date_gmt":"2019-11-09T04:00:01","guid":{"rendered":"https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/?p=15271"},"modified":"2019-11-09T14:46:00","modified_gmt":"2019-11-09T17:46:00","slug":"o-bolo-preparado-pelo-supremo","status":"publish","type":"post","link":"https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/o-bolo-preparado-pelo-supremo\/","title":{"rendered":"O bolo preparado pelo Supremo"},"content":{"rendered":"<p>VISTO, LIDO E OUVIDO, criada por Ari Cunha (In memoriam)<\/p>\n<p>Desde 1960, com Circe Cunha e Mamfil<\/p>\n<p>jornalistacircecunha@gmail.com<\/p>\n<p>Facebook.com\/vistolidoeouvido<\/p>\n<p>Instagram.com\/vistolidoeouvido<\/p>\n<p>&nbsp;<\/p>\n<figure id=\"attachment_15276\" aria-describedby=\"caption-attachment-15276\" style=\"width: 751px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-15276\" src=\"https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/11\/stf.jpg\" alt=\"\" width=\"751\" height=\"470\" srcset=\"https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/11\/stf.jpg 751w, https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/11\/stf-300x188.jpg 300w, https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/11\/stf-350x219.jpg 350w, https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/11\/stf-550x344.jpg 550w, https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/11\/stf-230x144.jpg 230w\" sizes=\"auto, (max-width: 751px) 100vw, 751px\" \/><figcaption id=\"caption-attachment-15276\" class=\"wp-caption-text\">Imagem: g1.globo.com<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<p>Depois do bolo assado \u00e9 que se pode saber se a receita estava correta. Assim tamb\u00e9m vale para a decis\u00e3o final dada pelo Supremo Tribunal Federal, acabando com a pris\u00e3o em segunda inst\u00e2ncia. Os desdobramentos pr\u00e1ticos dessa decis\u00e3o, com a possibilidade de abertura dos pres\u00eddios e soltura de detentos, incluindo nesse bolo os mais importantes protagonistas dos megaesc\u00e2ndalos de corrup\u00e7\u00e3o, dar\u00e3o o exato alcance dessa medida.<\/p>\n<p>Em 2014, o ex-ministro Joaquim Barbosa, pouco antes de sua sa\u00edda do STF, motivada, entre outras raz\u00f5es, pela sequ\u00eancia de amea\u00e7as que vinha sofrendo, previa que, num futuro n\u00e3o muito distante daquele ano, no qual muitos mensaleiros de alto coturno foram condenados, haveria a forma\u00e7\u00e3o de uma maioria de ocasi\u00e3o dentro da Corte para, obviamente, promover retrocessos e manter o antigo status quo. Como bem observado tamb\u00e9m por colunistas pol\u00edticos de todo o pa\u00eds, todo esse julgamento, por mais que os ministros tenham dissimulado, tinha um objetivo preciso e oculto, traduzido no fim da Lava-Jato para a soltura oficial de Lula, sob a b\u00ean\u00e7\u00e3o da pr\u00f3pria Justi\u00e7a que o havia condenado.<\/p>\n<p>N\u00e3o se pode negar de forma alguma, que nunca antes o bord\u00e3o \u201cn\u00f3s contra eles\u201d fez tanto sentido. De fato, a sociedade se mostra claramente dividida sobre essa decis\u00e3o anacr\u00f4nica. Uma das quest\u00f5es que se coloca agora \u00e9 como retroagir todo um pa\u00eds no tempo. Na verdade, o que foi feito com a aprova\u00e7\u00e3o da medida, equivale, numa imagem, a retirar a escada do pintor, simbolizado pela Justi\u00e7a, deixando-o suspenso no ar, seguro apenas pela broxa. A tal da inseguran\u00e7a jur\u00eddica, potencializada pela aprova\u00e7\u00e3o da Lei contra o Abuso de Autoridade pelo Congresso e, de certa forma, alimentada tamb\u00e9m pela possibilidade de os pol\u00edticos utilizarem as verbas bilion\u00e1rias do fundo partid\u00e1rio para o pagamento de advogados de defesa, \u00e9 hoje um fator a depor contra a pr\u00f3pria Justi\u00e7a em favorecimento direto aos fora da lei.<\/p>\n<p>Com isso, volta a se organizar a contrarreforma, de olho no passado. Imposs\u00edvel para um observador isento, mesmo dotado do mais alto grau de conhecimento jur\u00eddico, n\u00e3o reconhecer que essa decis\u00e3o, por seu peso pol\u00edtico espec\u00edfico, dentro do atual cen\u00e1rio do pa\u00eds, n\u00e3o tenha sido orientada, desde o come\u00e7o, por vi\u00e9s claramente pol\u00edtico.<\/p>\n<p>Os pretensos abusos da Opera\u00e7\u00e3o Lava-Jato, apontados como desculpa para a marcha \u00e0 r\u00e9 na lei, colocam um ponto de interroga\u00e7\u00e3o de dif\u00edcil resposta. A indiferen\u00e7a desse alto tribunal \u00e0s pesquisas de opini\u00e3o p\u00fablica, que apontavam inconteste prefer\u00eancia nacional pela pris\u00e3o em segunda inst\u00e2ncia, contrasta abertamente com o fato de que toda a discuss\u00e3o, desde o primeiro dia, foi amplamente contaminada e absorvida pela assombra\u00e7\u00e3o do chef\u00e3o petista preso.<\/p>\n<p>A tese marota para que haja a pris\u00e3o imediata apenas para condenados de crime contra a vida n\u00e3o se sustenta de p\u00e9, quando se verifica que a corrup\u00e7\u00e3o, como bem lembrou o ministro Barroso em seu voto a favor da pris\u00e3o em segunda inst\u00e2ncia: \u201c\u00c9 um crime violento. Mata na fila do SUS, na falta de leitos, na falta de medicamentos. Mata nas estradas sem manuten\u00e7\u00e3o adequada. O fato de o corrupto n\u00e3o ver nos olhos as v\u00edtimas que provoca, n\u00e3o o torna menos perigoso\u201d. Por enquanto, melhor ficar apenas de olho no bolo sa\u00eddo do forno, desconfiar, sem lev\u00e1-lo \u00e0 boca.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><strong>A frase que n\u00e3o foi pronunciada:<\/strong><\/p>\n<p><em>\u201cEngra\u00e7ado. N\u00e3o estou revoltado. Estou morrendo de vergonha do meu pa\u00eds. Aqui, o certo \u00e9 errado e o errado \u00e9 certo. J\u00e1 nem sei mais como educar meus filhos. Resumindo \u00e9 isso. Brasil: seja corrupto ou deixe-o.\u201d<\/em><\/p>\n<p>Conversa no banco da frente de um \u00f4nibus que parou perto do STF<\/p>\n<figure id=\"attachment_15273\" aria-describedby=\"caption-attachment-15273\" style=\"width: 491px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-15273 \" src=\"https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/11\/WhatsApp-Image-2019-11-08-at-12.33.10-1-e1573240201947.jpeg\" alt=\"\" width=\"491\" height=\"614\" srcset=\"https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/11\/WhatsApp-Image-2019-11-08-at-12.33.10-1-e1573240201947.jpeg 540w, https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/11\/WhatsApp-Image-2019-11-08-at-12.33.10-1-e1573240201947-240x300.jpeg 240w, https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/11\/WhatsApp-Image-2019-11-08-at-12.33.10-1-e1573240201947-280x350.jpeg 280w, https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/11\/WhatsApp-Image-2019-11-08-at-12.33.10-1-e1573240201947-230x288.jpeg 230w\" sizes=\"auto, (max-width: 491px) 100vw, 491px\" \/><figcaption id=\"caption-attachment-15273\" class=\"wp-caption-text\">Cartaz na p\u00e1gina oficial do MBL no Instagram<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Relaxando<\/strong><\/p>\n<p>Domingo \u00e9 dia do Grupo Cultural Azulim. A apresenta\u00e7\u00e3o da Uni\u00e3o Charme Dance, Soul Family e Dan\u00e7a Terapia ser\u00e1 de 12h as 21h, no Estacionamento da Administra\u00e7\u00e3o de Sobradinho 2 &#8211; Quadra, Ar 13 Conjunto 11, 01 &#8211; Sobradinho II. A programa\u00e7\u00e3o contar\u00e1 com feijoada completa dispon\u00edvel a um pre\u00e7o simb\u00f3lico de R$ 15 para ajudar com as despesas do Azulim que \u00e9 uma Organiza\u00e7\u00e3o da Sociedade Civil de Interesse P\u00fablico<\/p>\n<p>https:\/\/www.facebook.com\/GrupoCulturalAzulim\/videos\/421895321769011\/<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><strong>C\u00e9u caiu<\/strong><\/p>\n<p>Um pandem\u00f4nio previsto com a chegada das chuvas. Tomara que os v\u00eddeos amplamente divulgados pelas redes sociais norteiem o governador e equipe para as pr\u00f3ximas obras. N\u00e3o h\u00e1 vaz\u00e3o para \u00e1gua pluvial.<\/p>\n<p>https:\/\/www.youtube.com\/watch?v=fU5hEMol29w<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Movimenta\u00e7\u00e3o<\/strong><\/p>\n<p>Quase tudo pronto para receber os chefes de Estados que integram o BRICS nos dias 13 e 14 de novembro. No Senado, discuss\u00f5es sobre riscos e oportunidades durante a visita.<\/p>\n<figure id=\"attachment_15274\" aria-describedby=\"caption-attachment-15274\" style=\"width: 549px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-15274\" src=\"https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/11\/brics.jpg\" alt=\"\" width=\"549\" height=\"338\" srcset=\"https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/11\/brics.jpg 754w, https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/11\/brics-300x185.jpg 300w, https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/11\/brics-350x215.jpg 350w, https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/11\/brics-550x338.jpg 550w, https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/11\/brics-230x142.jpg 230w\" sizes=\"auto, (max-width: 549px) 100vw, 549px\" \/><figcaption id=\"caption-attachment-15274\" class=\"wp-caption-text\">Foto: Alan Santos\/PR<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Colarinho branco<\/strong><\/p>\n<p>C\u00e2mara aprova em 2\u00b0 turno PEC que cria pol\u00edcias penais. Acabaram de perguntar para qu\u00ea. \u00c9 que, apesar da import\u00e2ncia da iniciativa, o assunto \u00e9 mal relacionado ao recente julgamento do STF que relaxa a pris\u00e3o de quem pode pagar advogados.<\/p>\n<figure id=\"attachment_15275\" aria-describedby=\"caption-attachment-15275\" style=\"width: 549px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-15275\" src=\"https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/11\/pec.jpg\" alt=\"\" width=\"549\" height=\"327\" srcset=\"https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/11\/pec.jpg 759w, https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/11\/pec-300x179.jpg 300w, https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/11\/pec-350x208.jpg 350w, https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/11\/pec-550x328.jpg 550w, https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/11\/pec-230x137.jpg 230w\" sizes=\"auto, (max-width: 549px) 100vw, 549px\" \/><figcaption id=\"caption-attachment-15275\" class=\"wp-caption-text\">Foto: Fabio Rodrigues Pozzebom\/Ag\u00eancia Brasil<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><strong>HIST\u00d3RIA DE BRAS\u00cdLIA<\/strong><\/p>\n<p>O Banco do Brasil, at\u00e9 o fim do ano, ter\u00e1 999 apartamentos prontos. Mudar\u00e1, tamb\u00e9m, mais da metade. E pronto. O resto vem no faro. <strong>(Publicado em 06\/12\/1961)<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>VISTO, LIDO E OUVIDO, criada por Ari Cunha (In memoriam) Desde 1960, com Circe Cunha e Mamfil jornalistacircecunha@gmail.com Facebook.com\/vistolidoeouvido Instagram.com\/vistolidoeouvido &nbsp; &nbsp; Depois do bolo assado \u00e9 que se pode saber se a receita estava correta. Assim tamb\u00e9m vale para a decis\u00e3o final dada pelo Supremo Tribunal Federal, acabando com a pris\u00e3o em segunda inst\u00e2ncia. [&hellip;]<\/p>\n","protected":false},"author":34,"featured_media":15276,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"wpb_read_more":[],"footnotes":""},"categories":[23],"tags":[454,114,1909,946,288,1853,68,2,69,16,65],"class_list":["post-15271","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-integra","tag-corrupcaonobrasil","tag-historiadebrasilia","tag-ministrotoffoli","tag-operacaolavajato","tag-politicosnobrasil","tag-prisaoem2ainstancia","tag-aricunha","tag-brasilia","tag-circecunha","tag-mamfil","tag-stf"],"_links":{"self":[{"href":"https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/posts\/15271","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/comments?post=15271"}],"version-history":[{"count":4,"href":"https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/posts\/15271\/revisions"}],"predecessor-version":[{"id":15280,"href":"https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/posts\/15271\/revisions\/15280"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/media\/15276"}],"wp:attachment":[{"href":"https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/media?parent=15271"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/categories?post=15271"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/tags?post=15271"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}