{"id":15386,"date":"2019-11-24T01:00:58","date_gmt":"2019-11-24T04:00:58","guid":{"rendered":"https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/?p=15386"},"modified":"2019-11-23T14:49:18","modified_gmt":"2019-11-23T17:49:18","slug":"independencia-ou-ignorancia","status":"publish","type":"post","link":"https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/independencia-ou-ignorancia\/","title":{"rendered":"Independ\u00eancia ou ignor\u00e2ncia"},"content":{"rendered":"<p>VISTO, LIDO E OUVIDO, criada por Ari Cunha (In memoriam)<\/p>\n<p>Desde 1960, com Circe Cunha e Mamfil<\/p>\n<p>jornalistacircecunha@gmail.com<\/p>\n<p>Facebook.com\/vistolidoeouvido<\/p>\n<p>Instagram.com\/vistolidoeouvido<\/p>\n<p>&nbsp;<\/p>\n<figure id=\"attachment_15387\" aria-describedby=\"caption-attachment-15387\" style=\"width: 677px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-15387\" src=\"https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/11\/mi_10153756458484662.jpg\" alt=\"\" width=\"677\" height=\"425\" srcset=\"https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/11\/mi_10153756458484662.jpg 483w, https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/11\/mi_10153756458484662-300x188.jpg 300w, https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/11\/mi_10153756458484662-350x220.jpg 350w, https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/11\/mi_10153756458484662-230x144.jpg 230w\" sizes=\"auto, (max-width: 677px) 100vw, 677px\" \/><figcaption id=\"caption-attachment-15387\" class=\"wp-caption-text\">Foto: istoe.com<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<p>No campo econ\u00f4mico, h\u00e1 aqueles que entendem que um bom projeto educacional \u00e9 aquele que estabelece uma autonomia e liberdade or\u00e7ament\u00e1ria. Seria uma solu\u00e7\u00e3o interessante, com as escolas contratando ou demitindo professores sem rendimento. Ideias como o estabelecimento de uma renda para as escolas, de acordo com o n\u00famero de alunos matriculados e aprovados, tamb\u00e9m surge como interessante, o que faria as escolas a cumprirem uma meta pr\u00e9-estabelecida, principalmente se houvesse testes regulares elaborados pelas regionais para atestar se h\u00e1 o conhecimento dos alunos ou se foram empurrados para o ano seguinte.<\/p>\n<p>Outro ponto apontado como importante \u00e9 a fixa\u00e7\u00e3o de uma pol\u00edtica de compliance nas escolas p\u00fablicas, da mesma forma como vem sendo implementado nas grandes organiza\u00e7\u00f5es. O mais surpreendente \u00e9 que o Brasil j\u00e1 experimentou, por um curto espa\u00e7o de tempo, a introdu\u00e7\u00e3o de escolas com educa\u00e7\u00e3o de excel\u00eancia. Um exemplo foram as Escolas Parques criadas por An\u00edsio Teixeira e aquelas estabelecidas pelo educador Darcy Ribeiro, com os CIEPs, Centros Integrados de Educa\u00e7\u00e3o P\u00fablica, que se mostraram plenamente adequados a nossa realidade.<\/p>\n<p>Como esses modelos necessitavam de grande empenho e responsabilidade por parte das autoridades, foram deixados de lado. O que se tem hoje s\u00e3o modelos improvisados, por\u00e9m necess\u00e1rios, como \u00e9 o caso das escolas militarizadas.<\/p>\n<p>Na avalia\u00e7\u00e3o de experts no assunto, como \u00e9 o caso do fil\u00f3sofo e mestre em Ci\u00eancias Pol\u00edticas, Fernando Schuler, s\u00e3o v\u00e1rias as linhas de inova\u00e7\u00f5es poss\u00edveis para a melhoria do ensino p\u00fablico. Segundo ele, \u201cos sistemas de voucher, em que o governo oferece uma bolsa e d\u00e1 direito de escolha \u00e0s fam\u00edlias, ao inv\u00e9s de gerenciar escolas; e o modelo das charters schools, em que o governo assina contratos de gest\u00e3o com institui\u00e7\u00f5es especializadas, de direito privado e sem fins lucrativos. Em ambos casos, o governo passa da condi\u00e7\u00e3o de gestor direto para regulador do sistema.\u201d<\/p>\n<p>Outro pensador atual e importante sobre essa quest\u00e3o \u00e9 o economista Eduardo Giannetti. Para ele, a sociedade brasileira valoriza a educa\u00e7\u00e3o, mas coloca-a em plano abstrato e idealizado, sem que os familiares se envolvam diretamente no dia-a-dia com o processo de aprendizagem de seus filhos. Ou seja, um reconhecimento que fica apenas no discurso, descolado da pr\u00e1tica. Segundo ele \u00e9 preciso entender que o aproveitamento do que a crian\u00e7a e o jovem aprendem depende do suporte que eles t\u00eam ou n\u00e3o em casa, pois \u00e9 isso o que far\u00e1 com que os alunos percebam a permanente intera\u00e7\u00e3o da escola com o mundo.<\/p>\n<p>\u201cGosto muito de citar como exemplo os descendentes de orientais que moram no estado de S\u00e3o Paulo. Eles correspondem a aproximadamente 3% da popula\u00e7\u00e3o paulista e obt\u00eam 12% das vagas disponibilizadas pela Fuvest [processo que seleciona alunos para a Universidade de S\u00e3o Paulo e para a Faculdade de Ci\u00eancias M\u00e9dicas da Santa Casa de S\u00e3o Paulo], o principal vestibular do pa\u00eds. Os orientais vieram para c\u00e1 sem privil\u00e9gio algum, sem nenhum tipo de vantagem especial para viver aqui, e tiveram as mesmas oportunidades educacionais que a maioria da popula\u00e7\u00e3o. No entanto, em poucas gera\u00e7\u00f5es, os descendentes deles apresentam um desempenho escolar que os diferencia\u201d, diz Giannetti.<\/p>\n<p>A escola, na opini\u00e3o de v\u00e1rios educadores, deve ser integral, n\u00e3o apenas no desenvolvimento do que se processa intramuros, mas abrir-se para comunidade em tempo tamb\u00e9m integral, envolvendo todo o entorno social. Deve ainda promover atividades culturais que re\u00fana toda a comunidade, criando um espa\u00e7o aberto e integrativo permanente. Cabe a ela tamb\u00e9m discutir os problemas da comunidade, buscando apoio coletivo.<\/p>\n<p>Em outras palavras, a escola deve ser um lugar em que alunos, pais e toda a comunidade possam confiar e conviver de forma permanente, auxiliando a todos na medida do poss\u00edvel e do imposs\u00edvel. S\u00f3 assim ter\u00e1 sua validade reconhecida. Na realidade, n\u00e3o h\u00e1 nada para ser inventado nessa \u00e1rea que j\u00e1 n\u00e3o foi experimentado com sucesso garantido. Falta apenas um certo compromisso a ser estabelecido entre os cidad\u00e3os brasileiros e seus leg\u00edtimos representantes. Nesse ponto tamb\u00e9m se encontra um outro n\u00f3 dif\u00edcil de desatar e que diz respeito \u00e0 educa\u00e7\u00e3o dos eleitores para o ato de votar, o que nos remete ao in\u00edcio de todo o problema e ao recome\u00e7o desse ciclo fechado. A\u00ed s\u00e3o mais alguns s\u00e9culos de discuss\u00f5es.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><strong>A frase que n\u00e3o foi pronunciada:<\/strong><\/p>\n<p>&#8220;A\u00a0\u00a0educa\u00e7\u00e3o \u00e9 aquilo que sobrevive depois que tudo o que aprendemos foi esquecido.&#8221;<\/p>\n<p>B. F. Skinner, educador<\/p>\n<figure id=\"attachment_15394\" aria-describedby=\"caption-attachment-15394\" style=\"width: 371px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-15394\" src=\"https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/11\/bf.jpg\" alt=\"\" width=\"371\" height=\"595\" srcset=\"https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/11\/bf.jpg 371w, https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/11\/bf-187x300.jpg 187w, https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/11\/bf-218x350.jpg 218w, https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/11\/bf-230x369.jpg 230w\" sizes=\"auto, (max-width: 371px) 100vw, 371px\" \/><figcaption id=\"caption-attachment-15394\" class=\"wp-caption-text\">B.F. Skinner, 1971.<br \/>AP\/REX\/Shutterstock.com<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Tenso<\/strong><\/p>\n<p>\u00c9 preciso ter o cora\u00e7\u00e3o forte para suportar a pol\u00edtica de hoje. Mais uma vez, uma dupla de pol\u00edticos desfalece. Senador Kajuru e Senador Heinze. Os dois ficaram em quartos vizinhos no S\u00edrio Liban\u00eas em Bras\u00edlia.<\/p>\n<figure id=\"attachment_15389\" aria-describedby=\"caption-attachment-15389\" style=\"width: 551px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-15389\" src=\"https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/11\/kaju.jpg\" alt=\"\" width=\"551\" height=\"439\" srcset=\"https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/11\/kaju.jpg 515w, https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/11\/kaju-300x239.jpg 300w, https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/11\/kaju-350x279.jpg 350w, https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/11\/kaju-230x183.jpg 230w\" sizes=\"auto, (max-width: 551px) 100vw, 551px\" \/><figcaption id=\"caption-attachment-15389\" class=\"wp-caption-text\">senado.leg<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Tr\u00e1fico<\/strong><\/p>\n<p>Moradores reclamam do tr\u00e1fico de drogas na 408 Sul. Movimenta\u00e7\u00f5es por toda a noite deixam os vizinhos apreensivos e sem saber o que fazer. A situa\u00e7\u00e3o est\u00e1 bem desagrad\u00e1vel.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><strong>HIST\u00d3RIA DE BRAS\u00cdLIA<\/strong><\/p>\n<p>O Cear\u00e1, este ano, perdeu a iniciativa da \u201cind\u00fastria da seca\u201d. O ministro Virg\u00edlio T\u00e1vora moralizou a hist\u00f3ria, mas os baianos n\u00e3o aderiram. <strong>(Publicado em 06\/12\/1961)<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>VISTO, LIDO E OUVIDO, criada por Ari Cunha (In memoriam) Desde 1960, com Circe Cunha e Mamfil jornalistacircecunha@gmail.com Facebook.com\/vistolidoeouvido Instagram.com\/vistolidoeouvido &nbsp; &nbsp; No campo econ\u00f4mico, h\u00e1 aqueles que entendem que um bom projeto educacional \u00e9 aquele que estabelece uma autonomia e liberdade or\u00e7ament\u00e1ria. Seria uma solu\u00e7\u00e3o interessante, com as escolas contratando ou demitindo professores sem [&hellip;]<\/p>\n","protected":false},"author":34,"featured_media":15387,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"wpb_read_more":[],"footnotes":""},"categories":[23],"tags":[604,1942,1943,114,1177,68,2,69,16],"class_list":["post-15386","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-integra","tag-educacaonobrasil","tag-ensino","tag-escolasnobrasil","tag-historiadebrasilia","tag-ministeriodaeducacao","tag-aricunha","tag-brasilia","tag-circecunha","tag-mamfil"],"_links":{"self":[{"href":"https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/posts\/15386","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/comments?post=15386"}],"version-history":[{"count":3,"href":"https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/posts\/15386\/revisions"}],"predecessor-version":[{"id":15395,"href":"https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/posts\/15386\/revisions\/15395"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/media\/15387"}],"wp:attachment":[{"href":"https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/media?parent=15386"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/categories?post=15386"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/tags?post=15386"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}