{"id":15440,"date":"2019-12-03T01:00:27","date_gmt":"2019-12-03T04:00:27","guid":{"rendered":"https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/?p=15440"},"modified":"2019-12-02T18:23:34","modified_gmt":"2019-12-02T21:23:34","slug":"bem-no-futuro","status":"publish","type":"post","link":"https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/bem-no-futuro\/","title":{"rendered":"Bem no futuro"},"content":{"rendered":"<p>VISTO, LIDO E OUVIDO, criada por Ari Cunha (In memoriam)<\/p>\n<p>Desde 1960, com Circe Cunha e Mamfil<\/p>\n<p>jornalistacircecunha@gmail.com<\/p>\n<p>Facebook.com\/vistolidoeouvido<\/p>\n<p>Instagram.com\/vistolidoeouvido<\/p>\n<p>&nbsp;<\/p>\n<figure id=\"attachment_15442\" aria-describedby=\"caption-attachment-15442\" style=\"width: 649px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-15442\" src=\"https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/12\/cartaz.jpg\" alt=\"\" width=\"649\" height=\"364\" srcset=\"https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/12\/cartaz.jpg 649w, https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/12\/cartaz-300x168.jpg 300w, https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/12\/cartaz-350x196.jpg 350w, https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/12\/cartaz-550x308.jpg 550w, https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/12\/cartaz-230x129.jpg 230w\" sizes=\"auto, (max-width: 649px) 100vw, 649px\" \/><figcaption id=\"caption-attachment-15442\" class=\"wp-caption-text\">Greve pelo clima em Mil\u00e3o, na It\u00e1lia. Cartaz diz: &#8220;Mudemos a pol\u00edtica, e n\u00e3o o clima&#8221;. Em 27 de setembro de 2019. \u2014 Foto: Antonio Calanni\/AP (g1.globo.com)<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<p>Cartaz exibido por uma jovem manifestante em Mil\u00e3o, na It\u00e1lia, durante a marcha realizada em v\u00e1rios pa\u00edses contra o aquecimento global, resume bem o que pretendem as novas gera\u00e7\u00f5es sobre essa quest\u00e3o t\u00e3o delicada e vital para a humanidade: \u201cMudemos a pol\u00edtica, e n\u00e3o o clima\u201d, dizia resumidamente com propriedade o letreiro.<\/p>\n<p>Essa pode n\u00e3o ser a dire\u00e7\u00e3o a ser tomada pelos 200 pa\u00edses representados na COP 25, a c\u00fapula do clima, reunida em Madri de 2 a 13 de dezembro, mas, com certeza, \u00e9 um excelente mote para esse encontro, com mais de 29 mil pessoas, em busca de um caminho vi\u00e1vel e urgente para evitar os impactos catastr\u00f3ficos provocados pelos humanos no clima do planeta. De fato, pouqu\u00edssimos s\u00e3o os pa\u00edses que seguem o cronograma acertado ainda em 2015 pelo Acordo de Paris, quanto \u00e0 redu\u00e7\u00e3o na emiss\u00e3o dos gases de efeito estufa.<\/p>\n<p>A grande maioria dos pa\u00edses que v\u00eam discutindo esses acordos ainda busca internamente meios de reduzir essas emiss\u00f5es sem afetar quest\u00f5es como a produ\u00e7\u00e3o e os empregos. A substitui\u00e7\u00e3o das fontes poluentes por energia limpa e renov\u00e1vel ainda parece uma meta distante para muitos. Os governos sabem que essa quest\u00e3o, no \u00e2mbito interno de cada uma das economias e de suas caracter\u00edsticas b\u00e1sicas de produ\u00e7\u00e3o, permanece sendo um problema pol\u00edtico de dif\u00edcil resolu\u00e7\u00e3o a m\u00e9dio e curto prazo.<\/p>\n<p>Para muitos pol\u00edticos, seguir a cartilha de Paris, na conten\u00e7\u00e3o dos gases de efeito estufa, provocados pelas ind\u00fastrias, sem um desaceleramento no ritmo do crescimento de seus pa\u00edses, \u00e9 um problema que ainda n\u00e3o possui um horizonte seguro. Por outro lado, pressentem tamb\u00e9m que se n\u00e3o agirem a tempo de evitar uma cat\u00e1strofe mundial, estar\u00e3o cometendo um crime contra a humanidade.<\/p>\n<p>O slogan adotado para essa c\u00fapula em Madri, reflete tamb\u00e9m a urg\u00eancia de um problema que \u00e9 de todos igualmente: \u201cHora da A\u00e7\u00e3o\u201d. Os alertas feitos pelos maiores especialistas e cientistas sobre quest\u00f5es clim\u00e1ticas, acerca do progressivo aumento nas temperaturas no planeta, n\u00e3o deixam d\u00favidas de que os avisos s\u00e3o verdadeiramente sinistros e preocupantes.<\/p>\n<p>A possibilidade de que esses acordos avancem, al\u00e9m daqueles que foram fixados h\u00e1 quatro anos, cabe agora \u00e0 forte press\u00e3o que v\u00eam fazendo os jovens em todo o mundo, particularmente nos pa\u00edses industrializados. A conscientiza\u00e7\u00e3o crescente de que ser\u00e3o justamente as pr\u00f3ximas gera\u00e7\u00f5es aquelas que herdar\u00e3o, talvez, um planeta inabit\u00e1vel e in\u00f3spito vem turbinando esses protestos mundo afora. Essa interrup\u00e7\u00e3o secular na guerra contra a natureza \u00e9 o que pretendem os novos herdeiros do planeta, cientes de que essa batalha do bem \u00e9 a \u00fanica que importa nesse momento crucial da humanidade.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><strong>A frase que foi pronunciada:<\/strong><\/p>\n<p><em>\u201cO clima est\u00e1 mudando mais r\u00e1pido do que as a\u00e7\u00f5es para lidar com a quest\u00e3o.\u201d<\/em><\/p>\n<p>Barack Obama, ex-presidente norte-americano<\/p>\n<figure id=\"attachment_15443\" aria-describedby=\"caption-attachment-15443\" style=\"width: 547px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-15443\" src=\"https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/12\/obama.jpg\" alt=\"\" width=\"547\" height=\"362\" srcset=\"https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/12\/obama.jpg 708w, https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/12\/obama-300x198.jpg 300w, https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/12\/obama-350x231.jpg 350w, https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/12\/obama-550x364.jpg 550w, https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/12\/obama-230x152.jpg 230w\" sizes=\"auto, (max-width: 547px) 100vw, 547px\" \/><figcaption id=\"caption-attachment-15443\" class=\"wp-caption-text\">Foto: washingtonpost.com<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Mudan\u00e7a de h\u00e1bito<\/strong><\/p>\n<p>A cada limpeza de bueiros, o pessoal da Caesb encontra pneus, m\u00f3veis e outros objetos que deveriam ser descartados de forma correta. Falta uma campanha educativa para que a popula\u00e7\u00e3o compreenda que ela mesma \u00e9 prejudicada com esse tipo de atitude.<\/p>\n<p>https:\/\/www.youtube.com\/watch?v=2HN2OOLFGSw&#038;feature=emb_logo<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Desrespeito<\/strong><\/p>\n<p>Anote esse n\u00famero: 0800 704 0465; \u00e9 do atendimento da Gol. A lei do telemarketing prev\u00ea v\u00e1rias formas abusivas desse tipo de abordagem. Agora, um passageiro precisar de atendimento e aguardar por mais de 20 minutos ao telefone \u00e9 um desrespeito que pode ser acabado com uma bela multa para as empresas.<\/p>\n<figure id=\"attachment_15444\" aria-describedby=\"caption-attachment-15444\" style=\"width: 548px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-15444\" src=\"https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/12\/totem-03-1-1-1.jpg\" alt=\"\" width=\"548\" height=\"281\" srcset=\"https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/12\/totem-03-1-1-1.jpg 998w, https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/12\/totem-03-1-1-1-300x154.jpg 300w, https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/12\/totem-03-1-1-1-768x394.jpg 768w, https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/12\/totem-03-1-1-1-350x180.jpg 350w, https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/12\/totem-03-1-1-1-550x282.jpg 550w, https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/12\/totem-03-1-1-1-230x118.jpg 230w\" sizes=\"auto, (max-width: 548px) 100vw, 548px\" \/><figcaption id=\"caption-attachment-15444\" class=\"wp-caption-text\">Foto: voegol.com<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><strong>\u00d3cio<\/strong><\/p>\n<p>A\u00e7ougueiros ser\u00e3o demitidos em massa se o pre\u00e7o da carne continuar como est\u00e1. Nos mercados, os pre\u00e7os abusivos foram suficientes para debandar as filas.<\/p>\n<figure id=\"attachment_15445\" aria-describedby=\"caption-attachment-15445\" style=\"width: 550px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-15445\" src=\"https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/12\/charge.jpg\" alt=\"\" width=\"550\" height=\"366\" srcset=\"https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/12\/charge.jpg 620w, https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/12\/charge-300x200.jpg 300w, https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/12\/charge-350x233.jpg 350w, https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/12\/charge-550x366.jpg 550w, https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/12\/charge-230x153.jpg 230w\" sizes=\"auto, (max-width: 550px) 100vw, 550px\" \/><figcaption id=\"caption-attachment-15445\" class=\"wp-caption-text\">Charge do Duke<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Novidade<\/strong><\/p>\n<p>Marconi Gon\u00e7alves Brasileiro de Sant&#8217;anna e Bruna Alencar do Amaral executar\u00e3o o Termo de Coopera\u00e7\u00e3o T\u00e9cnica firmado entre a Defensoria P\u00fablica e a Associa\u00e7\u00e3o Nacional dos Registradores de Pessoas Naturais. O objetivo \u00e9 atender aos pedidos de acesso a certid\u00f5es pela Plataforma da Central de Informa\u00e7\u00f5es de Registro Civil de Pessoas.<\/p>\n<figure id=\"attachment_15446\" aria-describedby=\"caption-attachment-15446\" style=\"width: 553px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-15446\" src=\"https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/12\/download.png\" alt=\"\" width=\"553\" height=\"191\" srcset=\"https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/12\/download.png 382w, https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/12\/download-300x104.png 300w, https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/12\/download-350x121.png 350w, https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/12\/download-230x79.png 230w\" sizes=\"auto, (max-width: 553px) 100vw, 553px\" \/><figcaption id=\"caption-attachment-15446\" class=\"wp-caption-text\">Arte: registrocivil.org<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><strong>HIST\u00d3RIA DE BRAS\u00cdLIA<\/strong><\/p>\n<p>Ainda n\u00e3o se deu uma explica\u00e7\u00e3o, no caso da firma que construiu a rede de esgotos pluviais, porque estas galerias n\u00e3o t\u00eam capacidade de escoamento. Nos dias de chuva a cidade fica inundada, os trevos intransit\u00e1veis, a cidade imunda. <strong>(Publicado em 07\/12\/1961)<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>VISTO, LIDO E OUVIDO, criada por Ari Cunha (In memoriam) Desde 1960, com Circe Cunha e Mamfil jornalistacircecunha@gmail.com Facebook.com\/vistolidoeouvido Instagram.com\/vistolidoeouvido &nbsp; &nbsp; Cartaz exibido por uma jovem manifestante em Mil\u00e3o, na It\u00e1lia, durante a marcha realizada em v\u00e1rios pa\u00edses contra o aquecimento global, resume bem o que pretendem as novas gera\u00e7\u00f5es sobre essa quest\u00e3o t\u00e3o [&hellip;]<\/p>\n","protected":false},"author":34,"featured_media":15442,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"wpb_read_more":[],"footnotes":""},"categories":[23],"tags":[226,1057,402,1962,114,1963,68,2,69,16],"class_list":["post-15440","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-integra","tag-226","tag-alteracoesclimaticas","tag-aquecimentoglobal","tag-cop25","tag-historiadebrasilia","tag-horadaacao","tag-aricunha","tag-brasilia","tag-circecunha","tag-mamfil"],"_links":{"self":[{"href":"https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/posts\/15440","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/comments?post=15440"}],"version-history":[{"count":2,"href":"https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/posts\/15440\/revisions"}],"predecessor-version":[{"id":15447,"href":"https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/posts\/15440\/revisions\/15447"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/media\/15442"}],"wp:attachment":[{"href":"https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/media?parent=15440"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/categories?post=15440"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/tags?post=15440"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}