{"id":15632,"date":"2019-12-29T01:00:39","date_gmt":"2019-12-29T04:00:39","guid":{"rendered":"https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/?p=15632"},"modified":"2019-12-27T19:01:41","modified_gmt":"2019-12-27T22:01:41","slug":"o-brazil-nao-merece-o-brasil","status":"publish","type":"post","link":"https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/o-brazil-nao-merece-o-brasil\/","title":{"rendered":"O Brazil n\u00e3o merece o Brasil"},"content":{"rendered":"<p>VISTO, LIDO E OUVIDO, criada por Ari Cunha (In memoriam)<\/p>\n<p>Desde 1960, com Circe Cunha e Mamfil<\/p>\n<p>jornalistacircecunha@gmail.com<\/p>\n<p>Facebook.com\/vistolidoeouvido<\/p>\n<p>Instagram.com\/vistolidoeouvido<\/p>\n<p>&nbsp;<\/p>\n<figure id=\"attachment_15633\" aria-describedby=\"caption-attachment-15633\" style=\"width: 648px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-15633\" src=\"https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/12\/AGRICULTURA-BAYER.jpg\" alt=\"\" width=\"648\" height=\"433\" srcset=\"https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/12\/AGRICULTURA-BAYER.jpg 500w, https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/12\/AGRICULTURA-BAYER-300x200.jpg 300w, https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/12\/AGRICULTURA-BAYER-350x234.jpg 350w, https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/12\/AGRICULTURA-BAYER-230x154.jpg 230w\" sizes=\"auto, (max-width: 648px) 100vw, 648px\" \/><figcaption id=\"caption-attachment-15633\" class=\"wp-caption-text\">Foto: revistadeagronegocios.com<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<p>Para turbinar a escalada de pre\u00e7os, aumento de demanda mundial por alimentos, restri\u00e7\u00f5es de ofertas e outras inc\u00f3gnitas de dif\u00edcil solu\u00e7\u00e3o, o aquecimento global e as consequentes mudan\u00e7as clim\u00e1ticas elevam \u00e0s alturas tanto as incertezas sobre o futuro como os pre\u00e7os do p\u00e3o de cada dia.<\/p>\n<p>Al\u00e9m dessas vari\u00e1veis de caracter\u00edsticas globais, pode ser acrescentado ainda o aumento exponencial da popula\u00e7\u00e3o mundial, acima dos sete bilh\u00f5es de habitantes. A maioria sem recursos e com fome, muita fome. O agroneg\u00f3cio envolve uma cadeia de produ\u00e7\u00e3o, que pode ser dividido em tr\u00eas grandes atividades b\u00e1sicas. Num primeiro patamar est\u00e3o os grandes produtores de insumos como sementes transg\u00eanicas ou h\u00edbridas), adubos qu\u00edmicos e agrot\u00f3xicos e as empresas que fabricam as m\u00e1quinas agr\u00edcolas.<\/p>\n<p>No segundo est\u00e1gio est\u00e3o os produtores propriamente ditos, que aram a terra, adubam, plantam, pulverizam as planta\u00e7\u00f5es e colhem as safras, e que dentro do mundo fabuloso do agroneg\u00f3cio, se assemelham aos antigos pe\u00f5es ou trabalhadores da ro\u00e7a e que, obviamente, ficam com a menor parte do lucro ou com os preju\u00edzos.<\/p>\n<p>Num terceiro est\u00e1gio est\u00e3o outras enormes atividades, respons\u00e1veis pela recep\u00e7\u00e3o da produ\u00e7\u00e3o, armazenamento, distribui\u00e7\u00e3o dos produtos para o mercado interno e externo, al\u00e9m das ind\u00fastrias de transforma\u00e7\u00e3o dos alimentos para a produ\u00e7\u00e3o de \u00f3leos, ra\u00e7\u00f5es, combust\u00edveis, etc. Existe ainda um outro setor ligado a esse est\u00e1gio que \u00e9 mercado financeiro, que transforma os alimentos em a\u00e7\u00f5es a serem vendidas nas bolsas, especulando e elevando os pre\u00e7os dos alimentos.<\/p>\n<p>Quem controla a primeira etapa, dos insumos, s\u00e3o multinacionais gigantescas e oligopolistas como a Monsanto-Bayer; Dow-Dupont e a Syngenta-Chem China-Adama, al\u00e9m dos dois fabricantes de m\u00e1quinas como a Jhon Deere e New Holland. No est\u00e1gio final da distribui\u00e7\u00e3o log\u00edstica est\u00e1 outro pequeno grupo de multinacionais como a ADM; Bunge; Cargil e Dreyfuss. Finalmente na etapa final ficam as ind\u00fastrias de alimentos, tamb\u00e9m formada por um conjunto de multinacionais poderosas com a Nestl\u00e9, Kraft, Coca-Cola, Unilever, Pepsico e outras.<\/p>\n<p>A parte verdadeiramente nacional dentro do vasto mundo do agroneg\u00f3cio \u00e9 formada por empresas brasileiras e familiares que trabalham, como se diz, da porteira para dentro. Por fora agem as multinacionais que ficam com a maior parte dos lucros. O governo, que conduz uma economia com uma das maiores cargas tribut\u00e1rias do planeta, fica com a outra parte gorda. Tamb\u00e9m os bancos e financeiras cuidam de lucrarem especulando com alimentos. O que sobra mal d\u00e1 para pagar os custos de produ\u00e7\u00e3o.<\/p>\n<p>Correndo por fora desse gigantesco mercado podem ser encontrados ainda outros que direta ou indiretamente acabam lucrando com o agroneg\u00f3cio. S\u00e3o especuladores de todo o tipo, pol\u00edticos das bancadas ruralistas e lobistas prontas a colherem o que n\u00e3o plantaram. Para os produtores, que formam a parte verdadeiramente nacional do agroneg\u00f3cio e que realmente s\u00e3o os respons\u00e1veis por colocar diariamente alimentos no prato de milh\u00f5es de brasileiros, h\u00e1 ainda um indicador preocupante que \u00e9 a possibilidade de venda de extensas \u00e1reas agricult\u00e1veis \u00e0 estrangeiros conforme prev\u00ea o projeto (PL 2963\/2019).<\/p>\n<p>Quando isso acontecer, todo o agroneg\u00f3cio vai estar nas m\u00e3os de estrangeiros, internacionalizando em 100% todo o setor. Nesse ponto o governo perder\u00e1 totalmente a capacidade de regular e fiscalizar o setor. Nesse est\u00e1gio da evolu\u00e7\u00e3o acelerada do agroneg\u00f3cio os brasileiros perder\u00e3o a posse da terra o que pode marcar o in\u00edcio de um outro pa\u00eds, um Brasil com Z.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><strong>A frase que foi pronunciada:\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 <\/strong><\/p>\n<p><em>\u201cA consci\u00eancia fala, mas o interesse grita.\u201d<\/em><\/p>\n<p>Jules Petit-Senn, de Genebra. Poeta.<\/p>\n<figure id=\"attachment_15634\" aria-describedby=\"caption-attachment-15634\" style=\"width: 303px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-15634\" src=\"https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/12\/Jules-Petit-Senn.jpg\" alt=\"\" width=\"303\" height=\"435\" srcset=\"https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/12\/Jules-Petit-Senn.jpg 255w, https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/12\/Jules-Petit-Senn-209x300.jpg 209w, https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/12\/Jules-Petit-Senn-244x350.jpg 244w, https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/12\/Jules-Petit-Senn-230x330.jpg 230w\" sizes=\"auto, (max-width: 303px) 100vw, 303px\" \/><figcaption id=\"caption-attachment-15634\" class=\"wp-caption-text\">Imagem: Reprodu\u00e7\u00e3o da Internet<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Regulado<\/strong><\/p>\n<p>Dado interessante divulgado pelo Ipea. Ipea: trabalho dom\u00e9stico \u00e9 exercido por mulheres mais velhas. Em 2018, 80% das dom\u00e9sticas no Brasil tinham entre 30 e 59 anos.<\/p>\n<figure id=\"attachment_15635\" aria-describedby=\"caption-attachment-15635\" style=\"width: 548px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-15635\" src=\"https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/12\/PNAD-TrabalhoDomestico_home-Licia.jpg\" alt=\"\" width=\"548\" height=\"304\" srcset=\"https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/12\/PNAD-TrabalhoDomestico_home-Licia.jpg 875w, https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/12\/PNAD-TrabalhoDomestico_home-Licia-300x166.jpg 300w, https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/12\/PNAD-TrabalhoDomestico_home-Licia-768x426.jpg 768w, https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/12\/PNAD-TrabalhoDomestico_home-Licia-350x194.jpg 350w, https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/12\/PNAD-TrabalhoDomestico_home-Licia-550x305.jpg 550w, https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/12\/PNAD-TrabalhoDomestico_home-Licia-230x127.jpg 230w\" sizes=\"auto, (max-width: 548px) 100vw, 548px\" \/><figcaption id=\"caption-attachment-15635\" class=\"wp-caption-text\">Foto: Licia Rubinstein\/Ag\u00eancia IBGE Not\u00edcias<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Aos poucos<\/strong><\/p>\n<p>\u00c9 poss\u00edvel ver por Bras\u00edlia diversos meios de transporte el\u00e9tricos. Dados do Sistema de Estimativas de Emiss\u00f5es de Gases de Efeito Estufa, do Observat\u00f3rio do Clima, apontam para 430 milh\u00f5es de toneladas de res\u00edduos no ar no ano passado. Desse total, 48% foram emitidos por transportes.<\/p>\n<figure id=\"attachment_15636\" aria-describedby=\"caption-attachment-15636\" style=\"width: 550px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-15636\" src=\"https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/12\/carro.jpg\" alt=\"\" width=\"550\" height=\"366\" srcset=\"https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/12\/carro.jpg 561w, https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/12\/carro-300x199.jpg 300w, https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/12\/carro-350x233.jpg 350w, https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/12\/carro-550x366.jpg 550w, https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/12\/carro-230x153.jpg 230w\" sizes=\"auto, (max-width: 550px) 100vw, 550px\" \/><figcaption id=\"caption-attachment-15636\" class=\"wp-caption-text\">Foto: Ac\u00e1cio Pinheiro\/Ag\u00eancia Bras\u00edlia<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Consumidor<\/strong><\/p>\n<p>Foi uma cat\u00e1strofe geral o trabalho de encomendas para o Natal na padaria P\u00e3es e Vinhos do Lago Norte. Uma fila enorme, pessoas alteradas com o atendimento sofr\u00edvel e muitos produtos pagos com anteced\u00eancia n\u00e3o estavam prontos na hora marcada.<\/p>\n<figure id=\"attachment_15637\" aria-describedby=\"caption-attachment-15637\" style=\"width: 550px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-15637\" src=\"https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/12\/paes-artesanais.jpg\" alt=\"\" width=\"550\" height=\"412\" srcset=\"https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/12\/paes-artesanais.jpg 550w, https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/12\/paes-artesanais-300x225.jpg 300w, https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/12\/paes-artesanais-350x262.jpg 350w, https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/12\/paes-artesanais-230x172.jpg 230w\" sizes=\"auto, (max-width: 550px) 100vw, 550px\" \/><figcaption id=\"caption-attachment-15637\" class=\"wp-caption-text\">Foto de viajante enviada por: Vinny491, em agosto de 2019 (tripadvisor.com)<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><strong>SUS<\/strong><\/p>\n<p>Sem fonte de custeio, n\u00e3o foi poss\u00edvel aprovar o projeto do deputado Marconi Perillo que garantia a oferta de sangue, hemoderivados, medicamentos e demais recursos necess\u00e1rios para o diagn\u00f3stico, preven\u00e7\u00e3o e tratamento de doen\u00e7as, a todos os pacientes do Sistema \u00danico de Sa\u00fade (SUS).<\/p>\n<figure id=\"attachment_15638\" aria-describedby=\"caption-attachment-15638\" style=\"width: 547px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-15638\" src=\"https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/12\/marconi-perillo.jpg\" alt=\"\" width=\"547\" height=\"364\" srcset=\"https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/12\/marconi-perillo.jpg 640w, https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/12\/marconi-perillo-300x200.jpg 300w, https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/12\/marconi-perillo-350x233.jpg 350w, https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/12\/marconi-perillo-550x366.jpg 550w, https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-content\/uploads\/sites\/13\/2019\/12\/marconi-perillo-230x153.jpg 230w\" sizes=\"auto, (max-width: 547px) 100vw, 547px\" \/><figcaption id=\"caption-attachment-15638\" class=\"wp-caption-text\">Imagem: Reprodu\u00e7\u00e3o da Internet<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><strong>HIST\u00d3RIA DE BRAS\u00cdLIA<\/strong><\/p>\n<p>Rush do Tr\u00e2nsito, contra o excesso de velocidade nas avenidas de Bras\u00edlia. O dr. Valmores Barbosa voltou disposto dos Estados Unidos. <strong>(Publicado em 13\/12\/1961)<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>VISTO, LIDO E OUVIDO, criada por Ari Cunha (In memoriam) Desde 1960, com Circe Cunha e Mamfil jornalistacircecunha@gmail.com Facebook.com\/vistolidoeouvido Instagram.com\/vistolidoeouvido &nbsp; &nbsp; Para turbinar a escalada de pre\u00e7os, aumento de demanda mundial por alimentos, restri\u00e7\u00f5es de ofertas e outras inc\u00f3gnitas de dif\u00edcil solu\u00e7\u00e3o, o aquecimento global e as consequentes mudan\u00e7as clim\u00e1ticas elevam \u00e0s alturas tanto [&hellip;]<\/p>\n","protected":false},"author":34,"featured_media":15633,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"wpb_read_more":[],"footnotes":""},"categories":[23],"tags":[1572,2005,153,114,1719,1432,68,2,69,16],"class_list":["post-15632","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-integra","tag-agronegocio","tag-brasilceleirodomundo","tag-economia","tag-historiadebrasilia","tag-ministeriodaagriculturaedomeioambiente","tag-ministeriodaeconomia","tag-aricunha","tag-brasilia","tag-circecunha","tag-mamfil"],"_links":{"self":[{"href":"https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/posts\/15632","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/comments?post=15632"}],"version-history":[{"count":2,"href":"https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/posts\/15632\/revisions"}],"predecessor-version":[{"id":15644,"href":"https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/posts\/15632\/revisions\/15644"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/media\/15633"}],"wp:attachment":[{"href":"https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/media?parent=15632"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/categories?post=15632"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs2.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/tags?post=15632"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}