{"id":14102,"date":"2019-01-08T09:43:24","date_gmt":"2019-01-08T11:43:24","guid":{"rendered":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/?p=14102"},"modified":"2019-01-08T11:31:59","modified_gmt":"2019-01-08T13:31:59","slug":"rollemberg-orcamento-ibaneis","status":"publish","type":"post","link":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/rollemberg-orcamento-ibaneis\/","title":{"rendered":"Rollemberg deixa san\u00e7\u00e3o do or\u00e7amento para Ibaneis"},"content":{"rendered":"<p><strong>Eixo Capital<\/strong><\/p>\n<p>O ex-governador Rodrigo Rollemberg (PSB) n\u00e3o aceitou sancionar o or\u00e7amento de 2019 aprovado pela C\u00e2mara Legislativa. Ele n\u00e3o aprovou as mudan\u00e7as feitas pelos deputados distritais. Segundo nota t\u00e9cnica elaborada pela equipe da Secretaria de Fazenda, comandada por Wilson de Paula, houve remanejamento de despesas vedadas pela Lei de Diretrizes Or\u00e7ament\u00e1rias (LDO), houve altera\u00e7\u00e3o da carga tribut\u00e1ria da cesta b\u00e1sica em 157% e estimativa da receita tribut\u00e1ria merece avalia\u00e7\u00e3o mais criteriosa. Por isso, Rollemberg comunicou a Ibaneis que n\u00e3o sancionaria o texto. Caber\u00e1 ao atual governador a provid\u00eancia. O prazo \u00e9 ate 11 de janeiro.<\/p>\n<h2><strong>Na defesa do legado<\/strong><\/h2>\n<p>De f\u00e9rias e pelo Twitter, o ex-governador Rodrigo Rollemberg (PSB) comentou a decis\u00e3o do governador Ibaneis Rocha (MDB) de expandir o modelo de gest\u00e3o do Instituto Hospital de Base: \u201cIbaneis desistiu de acabar com o Instituto Hospital de Base. Ao contr\u00e1rio, resolveu expandi-lo. Vai ter muito mais coisa que n\u00e3o far\u00e1 como prometeu. E far\u00e1 como era poss\u00edvel e necess\u00e1rio fazer\u201d. E acrescentou: \u201cVamos aguardar os novos an\u00fancios\u201d. Rollemberg havia dito que faria uma quarentena para ver as coisas acontecerem antes de come\u00e7ar a se manifestar. Mas, pelo visto, o pavio \u00e9 curto.<br \/>\nhttp:\/\/<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"pt\">Ibaneis desistiu de acabar com o Instituto Hospital de Base. Ao contr\u00e1rio, resolveu expand\u00ed-lo. Vai ter muito mais coisa que n\u00e3o far\u00e1 como prometeu. E far\u00e1 como dissemos que era poss\u00edvel e necess\u00e1rio fazer. Vamos aguardar os pr\u00f3ximos an\u00fancios!<\/p>\n<p>\u2014 Rodrigo Rollemberg (@RollembergPSB) <a href=\"https:\/\/twitter.com\/RollembergPSB\/status\/1082362040554008577?ref_src=twsrc%5Etfw\">January 7, 2019<\/a><\/p><\/blockquote>\n<h2><strong>Come\u00e7a resist\u00eancia<\/strong><\/h2>\n<p>Candidata pelo PSol ao Pal\u00e1cio do Buriti, a professora F\u00e1tima Sousa criticou ontem a decis\u00e3o do governador Ibaneis Rocha de ampliar o modelo de gest\u00e3o do Instituto Hospital de Base, como foi anunciado ontem de manh\u00e3. \u201cMudan\u00e7a de discurso entre a campanha e o governo. Privatiza\u00e7\u00e3o geral do SUS-DF vem por a\u00ed. N\u00e3o vamos deixar. O SUS \u00e9 nosso e por ele vamos seguir lutando\u201d, afirmou.<\/p>\n<h2><strong>Da Pol\u00edcia Civil para a advocacia<\/strong><\/h2>\n<p>Ex-diretor-geral da Pol\u00edcia Civil do DF, o delegado Jorge Xavier se aposentou ontem. Agora vai aproveitar a expertise dos anos de investiga\u00e7\u00e3o para atuar do outro lado do balc\u00e3o, como advogado criminalista. Xavier j\u00e1 foi sondado para atuar num caso de grande repercuss\u00e3o e ainda analisa a situa\u00e7\u00e3o antes de dizer se topa. Ele deve atuar como s\u00f3cio do escrit\u00f3rio do advogado Raul Sab\u00f3ia, que funciona no Lago Sul.<\/p>\n<h2><strong>Prote\u00e7\u00e3o divina<\/strong><\/h2>\n<p>O governador Ibaneis Rocha (MDB) aposta em prote\u00e7\u00e3o espiritual para enfrentar os pr\u00f3ximos quatro anos de gest\u00e3o. No seu gabinete, ele colocou um ex\u00e9rcito de santos. Tem para toda f\u00e9, no m\u00f3vel que fica bem atr\u00e1s de sua mesa de despachos. Sem trocadilhos.<\/p>\n<h2><strong>Siga o dinheiro<\/strong><\/h2>\n<p>R$ 8.734.613.305,00<\/p>\n<p>\u00c9 o valor da d\u00edvida p\u00fablica do Distrito Federal, registrada at\u00e9 setembro de 2018, segundo o Portal da Transpar\u00eancia do DF. Desse montante, R$ 4.125.698.893,00 correspondem a precat\u00f3rios.<\/p>\n<h2><strong>Novas delegacias<\/strong><\/h2>\n<p>O diretor-geral da Pol\u00edcia Civil, Robson C\u00e2ndido, pretende construir tr\u00eas delegacias que hoje funcionam em pr\u00e9dios alugados, em Taguatinga (12\u00aa DP), Sobradinho 2 (35\u00aa DP) e no Setor de Ind\u00fastria e Abastecimento (8\u00aa DP). Tamb\u00e9m planeja entregar um novo pr\u00e9dio para o Instituto de Medicina Legal (IML), dentro do Complexo da Pol\u00edcia Civil do DF. \u201cTeremos o melhor IML da Am\u00e9rica Latina\u201d, promete.<\/p>\n<h2><strong>Em Vicente Pires<\/strong><\/h2>\n<p>O presidente do Sindicato dos Delegados de Pol\u00edcia Civil (Sindepo\/DF), Rafael Sampaio, vai chefiar a 38\u00aa Delegacia de Pol\u00edcia (DP), em Vicente Pires.<\/p>\n<h2><strong>Sem verba indenizat\u00f3ria<\/strong><\/h2>\n<p>O deputado distrital Eduardo Pedrosa apresentou of\u00edcio ontem em que abre m\u00e3o de toda a verba indenizat\u00f3ria no mandato na C\u00e2mara Legislativa.<\/p>\n<h2><strong>Adelmir renuncia a presid\u00eancia da Fecom\u00e9rcio<\/strong><\/h2>\n<p>Adelmir Santana renunciou ontem \u00e0 Presid\u00eancia do Sistema Fecom\u00e9rcio\/DF. O ex-senador tinha um projeto de comandar do \u00f3rg\u00e3o nacional, a Confedera\u00e7\u00e3o Nacional do Com\u00e9rcio de Bens, Servi\u00e7os e Turismo (CNC), mas perdeu a elei\u00e7\u00e3o. Depois de 17 anos, decidiu se dedicar a outros projetos. Agora, haver\u00e1 novas elei\u00e7\u00f5es. No lugar de Adelmir, assume interinamente a presid\u00eancia do Sistema Fecom\u00e9rcio-DF o primeiro vice-presidente, Francisco Maia.<\/p>\n<h2><strong>De volta ao MPDFT<\/strong><\/h2>\n<p>O ex-deputado distrital Chico Leite voltou hoje ao trabalho no Minist\u00e9rio P\u00fablico do Distrito Federal e Territ\u00f3rios (MPDFT), de onde saiu em 2002, para se candidatar pela primeira vez \u00e0 C\u00e2mara Legislativa. Foi como promotor de Justi\u00e7a na Ceil\u00e2ndia em v\u00e1rios j\u00faris que ele ficou conhecido. Agora vai atuar na segunda inst\u00e2ncia na 11\u00aa Procuradoria de Justi\u00e7a, em processos criminais. No pr\u00f3ximo dia 24, ele j\u00e1 participa da primeira sess\u00e3o na 2\u00aa Turma do Tribunal de Justi\u00e7a do DF.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Eixo Capital O ex-governador Rodrigo Rollemberg (PSB) n\u00e3o aceitou sancionar o or\u00e7amento de 2019 aprovado pela C\u00e2mara Legislativa. Ele n\u00e3o aprovou as mudan\u00e7as feitas pelos deputados distritais. Segundo nota t\u00e9cnica elaborada pela equipe da Secretaria de Fazenda, comandada por Wilson de Paula, houve remanejamento de despesas vedadas pela Lei de Diretrizes Or\u00e7ament\u00e1rias (LDO), houve altera\u00e7\u00e3o [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":14103,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"wpb_read_more":[],"footnotes":""},"categories":[234],"tags":[],"class_list":["post-14102","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cb-poder"],"_links":{"self":[{"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/posts\/14102","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/comments?post=14102"}],"version-history":[{"count":7,"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/posts\/14102\/revisions"}],"predecessor-version":[{"id":14110,"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/posts\/14102\/revisions\/14110"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/media\/14103"}],"wp:attachment":[{"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/media?parent=14102"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/categories?post=14102"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/tags?post=14102"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}