{"id":14377,"date":"2019-02-01T09:48:05","date_gmt":"2019-02-01T11:48:05","guid":{"rendered":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/?p=14377"},"modified":"2019-02-01T09:48:05","modified_gmt":"2019-02-01T11:48:05","slug":"mulheres-e-novatos-sao-maioria-entre-os-deputados-e-senadores-do-df","status":"publish","type":"post","link":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/mulheres-e-novatos-sao-maioria-entre-os-deputados-e-senadores-do-df\/","title":{"rendered":"Mulheres e novatos s\u00e3o maioria entre os deputados e senadores do DF"},"content":{"rendered":"<h6>Coluna Eixo Capital \/ Por Ana Maria Campos<\/h6>\n<p>&nbsp;<\/p>\n<p>Uma nova bancada de deputados federais e senadores do Distrito Federal toma posse hoje no Congresso. Entre os oito integrantes da legislatura anterior, apenas \u00c9rika Kokay (PT\/DF) se reelegeu. \u00c9 uma frente parlamentar com quatro novatos. A mais votada, Fl\u00e1via Arruda (PR), eleita com 121.340 votos nunca exerceu mandato. O mais pr\u00f3ximo da vida p\u00fablica foi a experi\u00eancia como primeira-dama do DF. Vai atuar muito na \u00e1rea social. Procuradora aposentada, Bia Kicis (PSL) tamb\u00e9m estreia na pol\u00edtica. Tornou-se conhecida como ativista a favor do impeachment de Dilma Rousseff e se aproximou de Jair Bolsonaro. Hoje \u00e9 uma das deputadas mais pr\u00f3ximas do presidente. Ter\u00e1 influ\u00eancia e sonha se eleger presidente da Comiss\u00e3o de Constitui\u00e7\u00e3o e Justi\u00e7a (CCJ). Deve manter v\u00e1rios embates com Kokay, j\u00e1 que ambas t\u00eam discursos contundentes e antag\u00f4nicos. Lu\u00eds Miranda (DEM) tamb\u00e9m \u00e9 novidade. Bom de redes sociais, fez campanha de Miami (EUA), onde morava e representa uma inc\u00f3gnita. Tamb\u00e9m surgiu na vida p\u00fablica depois de uma temporada morando na Europa a deputada Paula Belmonte (PPS). Seu foco ser\u00e1 a educa\u00e7\u00e3o. Os ex-distritais Celina Le\u00e3o (PP), J\u00falio C\u00e9sar (PRB) e Professor Israel (PV) s\u00e3o oriundos da C\u00e2mara Legislativa, mas tamb\u00e9m nunca exerceram cargo no Congresso.<\/p>\n<h2><\/h2>\n<h2>\n<strong>Mulheres s\u00e3o maioria<\/strong><\/h2>\n<p>O Distrito Federal tem uma alta representatividade feminina. S\u00e3o cinco mulheres dos oito integrantes da bancada. M\u00e9dia de 62%, bem acima da composi\u00e7\u00e3o da C\u00e2mara dos Deputados. Dos 513 deputados eleitos e reeleitos, 77 s\u00e3o mulheres, o que representa 15%. E na \u00faltima elei\u00e7\u00e3o o DF fez a primeira senadora, Leila do V\u00f4lei (PSB).<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<h2><strong>A pergunta que n\u00e3o quer calar\u2026.<\/strong><\/h2>\n<p>Com uma d\u00edvida de R$ 7,7 bilh\u00f5es, anunciada ontem, ser\u00e1 poss\u00edvel o governador Ibaneis Rocha (MDB) pagar todos os reajustes e retroativos esperados pelos servidores p\u00fablicos do DF.<\/p>\n<p>&nbsp;<\/p>\n<h2>\n<strong>Amigos de estrada<\/strong><\/h2>\n<p>Sumido das pistas pol\u00edticas, o ex-governador Agnelo Queiroz (PT) foi convidado a integrar grupo de motoqueiros num bate e volta a Una\u00ed (MG) nesta semana. O petista sempre foi apaixonado pelos passeios a duas rodas e dividiu a estrada na quarta-feira com os componentes do Moto Clube Legi\u00e3o da Capital, do qual fazem parte o deputado distrital Cl\u00e1udio Abrantes (PDT) e o coronel na reserva Rog\u00e9rio Le\u00e3o, ex-chefe da Casa Militar do DF.<\/p>\n<p>&nbsp;<\/p>\n<h2>\n<strong>No PSL<\/strong><\/h2>\n<p>O deputado Daniel Donizet trocou o PRP pelo PSL, sigla do presidente Jair Bolsonaro. Como o partido pelo qual o distrital se elegeu n\u00e3o cumpriu a cl\u00e1usula de barreira, ele teve liberdade para troca, como estabelece a emenda constitucional. Seguindo os passos da deputada Bia Kicis, migrou para o PSL.<\/p>\n<p>&nbsp;<\/p>\n<h2><strong>Siga o dinheiro<\/strong><\/h2>\n<p>R$ 590.119.658<\/p>\n<p>\u00c9 o montante do GDF para servidores que converteram licen\u00e7a-pr\u00eamio em pec\u00fania<\/p>\n<h2>\n<p><strong>Carro emprestado<\/strong><\/h2>\n<p>Em meio \u00e0 coletiva do secret\u00e1rio de Fazenda, Planejamento, Or\u00e7amento e Gest\u00e3o, Andr\u00e9 Clemente, o deputado eleito T\u00falio Gadelha (PDT\/PE) esteve ontem no Pal\u00e1cio do Buriti para pegar o carro emprestado do correligion\u00e1rio L\u00e9o Bijos, secret\u00e1rio de Juventude, o corcel amarelo 1974 que estava estacionado na garagem do pr\u00e9dio. Disse que precisava estar motorizado para buscar a namorada, F\u00e1tima Bernardes, no aeroporto. Ela deve vir a Bras\u00edlia para acompanhar a posse hoje.<\/p>\n<h2>\n<p><strong>Nova equipe do Gaeco<\/strong><\/h2>\n<p>Respons\u00e1vel por v\u00e1rias investiga\u00e7\u00f5es de combate \u00e0 corrup\u00e7\u00e3o na \u00e1rea de sa\u00fade, como a Opera\u00e7\u00e3o Genebra, relacionada a contratos da Cruz Vermelha, e a que recentemente provocou a pris\u00e3o do ex-secret\u00e1rio de Sa\u00fade Rafael Barbosa, o promotor de Justi\u00e7a Lu\u00eds Henrique Ishihara ter\u00e1 uma atua\u00e7\u00e3o importante nos trabalhos do Gaeco no novo formato definido pela procuradora-geral de Justi\u00e7a do DF, Fabiana Costa. Ishihara tamb\u00e9m teve uma passagem pelo N\u00facleo de Investiga\u00e7\u00e3o e Controle Externo da Atividade Policial (NCAP), com investiga\u00e7\u00f5es e processos rumorosos, envolvendo policiais, como o agente Luiz Cl\u00e1udio Nogueira e a delegada Martha Vargas, ambos condenados. A equipe contar\u00e1 tamb\u00e9m com os promotores Rodrigo Bezerra e Marcel Bernardi, que vinham atuando no NCAP. Entre v\u00e1rias a\u00e7\u00f5es, eles s\u00e3o respons\u00e1veis, em trabalho conjunto com a Promotoria de Defesa do Patrim\u00f4nio P\u00fablico e Social (Prodep), por a\u00e7\u00f5es criminais e c\u00edveis contra a empresa Forja Taurus S\/A que forneceu para a Pol\u00edcia Civil armas de fogo com risco de disparos acidentais. A nova equipe estreia hoje. No NCAP, assumem os promotores de Justi\u00e7a Gilberto Teles Coelho e Leonardo Borges.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Coluna Eixo Capital \/ Por Ana Maria Campos &nbsp; Uma nova bancada de deputados federais e senadores do Distrito Federal toma posse hoje no Congresso. Entre os oito integrantes da legislatura anterior, apenas \u00c9rika Kokay (PT\/DF) se reelegeu. \u00c9 uma frente parlamentar com quatro novatos. A mais votada, Fl\u00e1via Arruda (PR), eleita com 121.340 votos [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":14378,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"wpb_read_more":[],"footnotes":""},"categories":[234],"tags":[12,179,1599,1715,62],"class_list":["post-14377","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cb-poder","tag-camara","tag-df","tag-mulheres","tag-novatos","tag-senado"],"_links":{"self":[{"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/posts\/14377","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/comments?post=14377"}],"version-history":[{"count":1,"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/posts\/14377\/revisions"}],"predecessor-version":[{"id":14379,"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/posts\/14377\/revisions\/14379"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/media\/14378"}],"wp:attachment":[{"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/media?parent=14377"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/categories?post=14377"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/tags?post=14377"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}