{"id":14431,"date":"2019-02-07T07:47:13","date_gmt":"2019-02-07T09:47:13","guid":{"rendered":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/?p=14431"},"modified":"2019-02-07T07:47:13","modified_gmt":"2019-02-07T09:47:13","slug":"ibaneis-veta-fraudes-bilhetagem","status":"publish","type":"post","link":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/ibaneis-veta-fraudes-bilhetagem\/","title":{"rendered":"Ibaneis veta projeto que facilita fraudes na bilhetagem autom\u00e1tica"},"content":{"rendered":"<p>O governador Ibaneis Rocha (MDB) vetou o projeto aprovado no fim do ano pela C\u00e2mara Legislativa que, segundo o Minist\u00e9rio P\u00fablico do Distrito Federal e Territ\u00f3rios (MPDFT), cria brechas para fraudes no sistema de bilhetagem autom\u00e1tica. Os promotores da Promotoria de Defesa do Patrim\u00f4nio P\u00fablico (Prodep) haviam recomendado o veto por entender que a proposta de ilimitar o prazo para uso dos cr\u00e9ditos dos passageiros facilita o crime desvendado na Opera\u00e7\u00e3o Trickster. Esse dinheiro n\u00e3o utilizado ao longo do tempo \u00e9 considerado a mina de ouro para os desvios. O projeto, de autoria do deputado Wellington Luiz (MDB) era semelhante a outro, apresentado por Celina Le\u00e3o (PP), tamb\u00e9m vetado no ano passado por Rodrigo Rollemberg, por recomenda\u00e7\u00e3o do Minist\u00e9rio P\u00fablico.<\/p>\n<h2><strong>Experiente em crises<\/strong><\/h2>\n<p>A guerra da aprova\u00e7\u00e3o das mudan\u00e7as no Passe Livre Estudantil ser\u00e1 grande, mas nem chega aos p\u00e9s do que enfrentou o secret\u00e1rio de Mobilidade, Valter Casimiro. Ele era o ministro dos Transportes durante a greve dos caminhoneiros no ano passado em protesto pela alta do pre\u00e7o do diesel. Passou v\u00e1rios dias em negocia\u00e7\u00f5es, sem hora para dormir ou comer.<\/p>\n<h2>\n<strong>Mais um processo na primeira inst\u00e2ncia<\/strong><\/h2>\n<p>Com o fim do mandato parlamentar, o ex-deputado Alberto Fraga (DEM\/DF) vai responder na primeira inst\u00e2ncia a mais um processo que tramitava no Supremo Tribunal Federal (STF). Relator do caso, o ministro Celso de Mello declinou a compet\u00eancia em despacho na \u00faltima ter\u00e7a-feira do processo por falsidade ideol\u00f3gica e peculato em que Fraga \u00e9 acusado de contratar na C\u00e2mara dos Deputados a empregada dom\u00e9stica de sua casa.<\/p>\n<h2>\n<strong>PSB e MDB em bloco<\/strong><\/h2>\n<p>Advers\u00e1rios no segundo turno na disputa ao Pal\u00e1cio do Buriti, MDB e PSB se uniram na C\u00e2mara Legislativa. Os deputados do partido do ex-governador Rodrigo Rollemberg, Roosevelt Vilela e Jos\u00e9 Gomes, registraram o \u201cBloco em Evolu\u00e7\u00e3o\u201d, com o deputado Rafael Prudente, presidente da C\u00e2mara Legislativa, que \u00e9 da legenda do governador Ibaneis Rocha. Tamb\u00e9m comp\u00f5e o grupo a deputada Jaqueline Silva (PTB). Os blocos s\u00e3o criados para unidade de posi\u00e7\u00f5es e, geralmente, de votos.<\/p>\n<h2>\n<strong>Reestreia na C\u00e2mara<\/strong><\/h2>\n<p>Na volta \u00e0 C\u00e2mara Legislativa, o primeiro projeto apresentado pela deputada distrital Arlete Sampaio (PT) estabelece uma esp\u00e9cie de blitz contra a viol\u00eancia dom\u00e9stica. O programa, batizado de \u201cRonda Maria da Penha no Distrito Federal\u201d, cria medidas para que a Pol\u00edcia Militar fa\u00e7a visitas regulares, em dias e hor\u00e1rios alternados, \u00e0s mulheres v\u00edtimas de viol\u00eancia. Se for aprovado, o programa ser\u00e1 administrado pela Secretaria da Mulher.<\/p>\n<h2>\n<strong>Resist\u00eancia<\/strong><\/h2>\n<p>Tem sido grande a rea\u00e7\u00e3o de professores \u00e0 ideia de militarizar as escolas. A bronca foi grande em reuni\u00e3o realizada no CED 7 de Ceil\u00e2ndia, nesta semana. A resist\u00eancia tende a aumentar. Os docentes chamam a proposta de \u201cinterven\u00e7\u00e3o militar\u201d.<\/p>\n<h2>\n<strong>Transpar\u00eancia<\/strong><\/h2>\n<p>O governador Ibaneis Rocha e o presidente do BRB, Paulo Henrique Costa, estiveram ontem com o juiz Ricardo Augusto Soares Leite, da 10\u00aa Vara da Justi\u00e7a Federal, onde tramita a Opera\u00e7\u00e3o Circus Maximus. Eles tamb\u00e9m se reuniram com os procuradores da Rep\u00fablica e delegados respons\u00e1veis pela investiga\u00e7\u00e3o sobre fraudes no BRB. A inten\u00e7\u00e3o foi apresentar medidas j\u00e1 adotadas e colocar o banco \u00e0 disposi\u00e7\u00e3o para colabora\u00e7\u00f5es na apura\u00e7\u00e3o.<\/p>\n<h2>\n<strong>Siga o dinheiro<\/strong><\/h2>\n<p><em>R$ 300 milh\u00f5es<\/em><\/p>\n<p>\u00c9 o valor da d\u00edvida herdada pelo atual governo, segundo o secret\u00e1rio de Mobilidade, Valter Casimiro, com subs\u00eddio para gratuidades de passagens do sistema de transporte p\u00fablico do DF.<\/p>\n<h2>\n<strong>Mentores do Passe Livre<\/strong><\/h2>\n<p>O primeiro projeto do passe livre integral para estudantes foi aprovado pela C\u00e2mara Legislativa em 2009. Tinha como autor o ent\u00e3o deputado Paulo Tadeu (PT), hoje conselheiro do Tribunal de Contas do Distrito Federal. Como o texto foi considerado inconstitucional, por v\u00edcio de iniciativa, o ent\u00e3o governador Jos\u00e9 Roberto Arruda enviou um projeto com o mesmo teor. Aprovado pelos distritais, o texto virou lei em 2010. Hoje, o DF \u00e9 a \u00fanica unidade da federa\u00e7\u00e3o com tarifa zero para estudantes.<\/p>\n<h2>\n<strong>S\u00f3 papos<\/strong><\/h2>\n<blockquote><p>\n\u201cO Brasil est\u00e1 deixando de ser o pa\u00eds da impunidade para corruptos. A nova condena\u00e7\u00e3o do Lula, mais do que justa, \u00e9 exemplar e um recado de que o Brasil est\u00e1 mudando para muito melhor, e a Justi\u00e7a est\u00e1 colaborando com isso\u201d<\/p><\/blockquote>\n<p style=\"text-align: right\"><strong>Senador Major Ol\u00edmpio (PSL\/SP), sobre a condena\u00e7\u00e3o do ex-presidente Lula a 12 anos e 11 meses de pris\u00e3o por corrup\u00e7\u00e3o passiva, ativa e lavagem de dinheiro<\/strong><\/p>\n<blockquote><p>\n\u201cA persegui\u00e7\u00e3o a Lula n\u00e3o para. Uma segunda condena\u00e7\u00e3o a jato foi proferida, exatamente quando cresce a possibilidade de Lula ser Nobel da Paz. Na mem\u00f3ria do povo e na hist\u00f3ria, Lula ser\u00e1 sempre maior que seus carrascos\u201d<\/p><\/blockquote>\n<p style=\"text-align: right\"><strong>Deputada Gleisi Hoffmann (PR), presidente nacional do PT<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O governador Ibaneis Rocha (MDB) vetou o projeto aprovado no fim do ano pela C\u00e2mara Legislativa que, segundo o Minist\u00e9rio P\u00fablico do Distrito Federal e Territ\u00f3rios (MPDFT), cria brechas para fraudes no sistema de bilhetagem autom\u00e1tica. Os promotores da Promotoria de Defesa do Patrim\u00f4nio P\u00fablico (Prodep) haviam recomendado o veto por entender que a proposta [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":14432,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"wpb_read_more":[],"footnotes":""},"categories":[234],"tags":[],"class_list":["post-14431","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cb-poder"],"_links":{"self":[{"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/posts\/14431","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/comments?post=14431"}],"version-history":[{"count":1,"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/posts\/14431\/revisions"}],"predecessor-version":[{"id":14433,"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/posts\/14431\/revisions\/14433"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/media\/14432"}],"wp:attachment":[{"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/media?parent=14431"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/categories?post=14431"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/tags?post=14431"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}