{"id":14897,"date":"2019-04-03T10:26:10","date_gmt":"2019-04-03T13:26:10","guid":{"rendered":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/?p=14897"},"modified":"2019-04-03T10:26:10","modified_gmt":"2019-04-03T13:26:10","slug":"troca-casa-militar-vitoria-comandante-geral-da-pm","status":"publish","type":"post","link":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/troca-casa-militar-vitoria-comandante-geral-da-pm\/","title":{"rendered":"Troca de chefe da Casa Militar \u00e9 vit\u00f3ria da comandante-geral da PM"},"content":{"rendered":"<p><strong>Coluna Eixo Capital\/Por Ana Maria Campos<\/strong><\/p>\n<p>A Casa Militar, que foi foco de tens\u00f5es desde a transi\u00e7\u00e3o, continua rendendo. O \u00f3rg\u00e3o que quase foi extinto teve a primeira baixa do alto escal\u00e3o do governo Ibaneis Rocha. O governador limitou-se a dizer que \u201cembates\u201d levaram \u00e0 troca. Nomeado no primeiro dia de janeiro, o coronel J\u00falio C\u00e9sar Lima de Oliveira era um advers\u00e1rio da comandante-geral da PM, coronel Sheyla Sampaio, e defendia a escolha de um oficial mais antigo para a chefia da corpora\u00e7\u00e3o. O novo chefe da Casa Militar, tenente-coronel Marcus Paulo Koboldt, por sua vez, \u00e9 da turma de forma\u00e7\u00e3o da coronel Sheyla. Sinal de que ela est\u00e1 conquistando espa\u00e7o na \u00e1rea de seguran\u00e7a p\u00fablica. A Casa Militar \u00e9 considerada um cargo estrat\u00e9gico na PM, cujo chefe \u00e9 uma pessoa que mant\u00e9m rela\u00e7\u00f5es pr\u00f3ximas com o governador e sua fam\u00edlia.<\/p>\n<h2><strong>Data de validade<\/strong><\/h2>\n<p><a href=\"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/justica-anula-posse-de-fernando-leite-na-caesb\/\">A decis\u00e3o que suspendeu a posse de Fernando Leite como presidente da Caesb<\/a> tem data de validade. O Minist\u00e9rio P\u00fablico do Distrito Federal e Territ\u00f3rios (MPDFT) considera que os efeitos da pena de condena\u00e7\u00e3o por improbidade administrativa, que levaram \u00e0 Justi\u00e7a a suspender a posse, se encerram em setembro. Se a defesa n\u00e3o conseguir cassar a liminar, ele poder\u00e1 voltar ao cargo em quatro meses. De qualquer forma, o advogado Herman Barbosa, que representa Fernando Leite, vai recorrer. O argumento \u00e9 de que no pa\u00eds vale execu\u00e7\u00e3o da pena de pris\u00e3o a partir da condena\u00e7\u00e3o em segunda inst\u00e2ncia e, ent\u00e3o, por que n\u00e3o contaria da mesma forma para casos de suspens\u00e3o dos direitos pol\u00edticos. Nessa l\u00f3gica, a pena foi executada entre 2011 e 2014, quando Fernando Leite deixou de exercer cargos p\u00fablicos.<\/p>\n<h2><strong>Na coordena\u00e7\u00e3o, sem sal\u00e1rio<\/strong><\/h2>\n<p>Na reuni\u00e3o de ontem do governador Ibaneis Rocha com o secretariado, o empres\u00e1rio Jos\u00e9 Humberto Pires foi uma das estrelas. O ex-secret\u00e1rio de Governo, da gest\u00e3o Arruda, \u00e9 o coordenador do programa SOS DF, carro-chefe da atual administra\u00e7\u00e3o, com medidas emergenciais em v\u00e1rias \u00e1reas. Mas ajuda como volunt\u00e1rio, sem receber sal\u00e1rio.<\/p>\n<h2>\n<strong>Volunt\u00e1rios<\/strong><\/h2>\n<p>O governo Ibaneis Rocha tem outros dois colaboradores volunt\u00e1rios: o presidente da Ademi (Associa\u00e7\u00e3o de Empresas do Mercado Imobili\u00e1rio do DF), Paulo Muniz, e a ex-secret\u00e1ria de Trabalho e Desenvolvimento Social do governo Rollemberg Ilda Peliz, ex-presidente da Abrace.<\/p>\n<h2>\n<strong>Prioridade<\/strong><\/h2>\n<p>O recado do governador Ibaneis Rocha ontem na reuni\u00e3o com a sua equipe foi bem claro: n\u00e3o tem dinheiro e a prioridade \u00e9 honrar em dia os sal\u00e1rios. S\u00f3 n\u00e3o entende quem n\u00e3o quer.<\/p>\n<h2>\n<strong>Vida longe da pol\u00edtica partid\u00e1ria<\/strong><\/h2>\n<p>O ex-deputado Chico Leite est\u00e1 gostando da vida longe da C\u00e2mara Legislativa. De volta ao Minist\u00e9rio P\u00fablico do DF, ele est\u00e1 cuidando da sa\u00fade, praticando exerc\u00edcios f\u00edsicos e fazendo um mestrado em direito penal, com foco em combate \u00e0 corrup\u00e7\u00e3o. No fim de 2020, Chico Leite pode se aposentar e, se quiser, tentar novo mandato nas pr\u00f3ximas elei\u00e7\u00f5es. Mas o ex-distrital est\u00e1 longe de tomar uma decis\u00e3o. Nem precisa pensar nisso agora.<\/p>\n<h2>\n<strong>Torneira fechada<\/strong><\/h2>\n<p>O ministro Bruno Dantas, do Tribunal de Contas da Uni\u00e3o (TCU), disse ontem em entrevista ao programa CB.Poder que n\u00e3o h\u00e1 sa\u00edda: o GDF ter\u00e1 de discutir um cronograma de pagamentos para devolver aos cofres da Uni\u00e3o o imposto de renda retido no tesouro local dos servidores da seguran\u00e7a p\u00fablica. S\u00e3o R$ 10 bilh\u00f5es, al\u00e9m do desconto anual de R$ 700 milh\u00f5es que come\u00e7a a valer j\u00e1 em 2019. A decis\u00e3o foi tomada pela corte na semana passada. O governador Ibaneis Rocha prometeu recorrer \u00e0 Justi\u00e7a. Se j\u00e1 n\u00e3o tinha dinheiro suficiente para os reajustes prometidos, agora piorou. E muito. Mas a perda de receita n\u00e3o deixa de ser uma boa sa\u00edda para uma justificativa pol\u00edtica de Ibaneis aos servidores.<\/p>\n<h2>\n<strong>Um brigadeiro na comunica\u00e7\u00e3o da seguran\u00e7a p\u00fablica<\/strong><\/h2>\n<p>A Secretaria de Seguran\u00e7a P\u00fablica tem um novo assessor de comunica\u00e7\u00e3o. \u00c9 o brigadeiro do ar Antonio Ramirez Lorenzo, que comandou a comunica\u00e7\u00e3o social da Aeron\u00e1utica no governo do presidente Michel Temer. O oficial tem um extenso curr\u00edculo. Ao longo da carreira acumulou 2,3 mil horas de voo. Foi Adido de Defesa e Aeron\u00e1utico junto \u00e0 Embaixada da Fran\u00e7a e B\u00e9lgica, chefe da Divis\u00e3o de Opera\u00e7\u00f5es do Comando-Geral de Opera\u00e7\u00f5es A\u00e9reas (COMGAR), comandante do Primeiro Grupo de Avia\u00e7\u00e3o de Ca\u00e7a e chefe da assessoria de imprensa da FAB.<\/p>\n<h2>\n<strong>Incentivos<\/strong><\/h2>\n<p>O senador Jos\u00e9 Ant\u00f4nio Reguffe (Sem partido\/DF) j\u00e1 tem conversado com alguns amigos da pol\u00edtica sobre as elei\u00e7\u00f5es de 2022. N\u00e3o faltam incentivos para que dispute o Pal\u00e1cio do Buriti.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Coluna Eixo Capital\/Por Ana Maria Campos A Casa Militar, que foi foco de tens\u00f5es desde a transi\u00e7\u00e3o, continua rendendo. O \u00f3rg\u00e3o que quase foi extinto teve a primeira baixa do alto escal\u00e3o do governo Ibaneis Rocha. O governador limitou-se a dizer que \u201cembates\u201d levaram \u00e0 troca. Nomeado no primeiro dia de janeiro, o coronel J\u00falio [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":14898,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"wpb_read_more":[],"footnotes":""},"categories":[234],"tags":[],"class_list":["post-14897","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cb-poder"],"_links":{"self":[{"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/posts\/14897","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/comments?post=14897"}],"version-history":[{"count":1,"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/posts\/14897\/revisions"}],"predecessor-version":[{"id":14899,"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/posts\/14897\/revisions\/14899"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/media\/14898"}],"wp:attachment":[{"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/media?parent=14897"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/categories?post=14897"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/tags?post=14897"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}