{"id":14917,"date":"2019-04-06T00:50:10","date_gmt":"2019-04-06T03:50:10","guid":{"rendered":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/?p=14917"},"modified":"2019-04-06T01:57:43","modified_gmt":"2019-04-06T04:57:43","slug":"morre-eri-varela-advogado-de-roriz-e-ex-presidente-da-terracap","status":"publish","type":"post","link":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/morre-eri-varela-advogado-de-roriz-e-ex-presidente-da-terracap\/","title":{"rendered":"Morre Eri Varela, ex-presidente da Terracap e advogado de Roriz"},"content":{"rendered":"<p><a href=\"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-content\/uploads\/sites\/5\/2019\/04\/eri-varela-daniel-alves-cb.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-14918\" src=\"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-content\/uploads\/sites\/5\/2019\/04\/eri-varela-daniel-alves-cb-300x211.jpg\" alt=\"Foto: Daniel Alves\/CB\/D.A Press\" width=\"300\" height=\"211\" srcset=\"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-content\/uploads\/sites\/5\/2019\/04\/eri-varela-daniel-alves-cb-300x211.jpg 300w, https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-content\/uploads\/sites\/5\/2019\/04\/eri-varela-daniel-alves-cb-768x539.jpg 768w, https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-content\/uploads\/sites\/5\/2019\/04\/eri-varela-daniel-alves-cb-1024x719.jpg 1024w, https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-content\/uploads\/sites\/5\/2019\/04\/eri-varela-daniel-alves-cb-350x246.jpg 350w, https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-content\/uploads\/sites\/5\/2019\/04\/eri-varela-daniel-alves-cb-1440x1012.jpg 1440w, https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-content\/uploads\/sites\/5\/2019\/04\/eri-varela-daniel-alves-cb-550x386.jpg 550w, https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-content\/uploads\/sites\/5\/2019\/04\/eri-varela-daniel-alves-cb-230x162.jpg 230w, https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-content\/uploads\/sites\/5\/2019\/04\/eri-varela-daniel-alves-cb.jpg 1909w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>Morreu no in\u00edcio desta noite (5\/4) o advogado Eri Varela em decorr\u00eancia de acidente de carro na estrada para Cristalina (GO). O carro em que ele estava bateu de frente com um \u00f4nibus de turismo na BR 040.<\/p>\n<p>O corpo de Varela est\u00e1 sendo levado para o IML de Formosa (GO). O advogado costumava viajar a Cristalina nos fins de semana a trabalho.<\/p>\n<p>O Corpo de Bombeiros de Cristalina foi chamado para fazer o socorro \u00e0s 19h09. Quando a equipe chegou ao local, constatou que Eri Varela j\u00e1 estava morto. Pouco depois, outro acidente grave ocorreu a apenas oito quil\u00f4metros, na mesma rodovia.<\/p>\n<p>Ex-presidente da Terracap, Eri Varela foi durante muitos anos advogado e conselheiro pol\u00edtico do ex-governador Joaquim Roriz.<\/p>\n<p>Ele deixa quatro filhos e a mulher, tamb\u00e9m advogada, Vera Varela.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Morreu no in\u00edcio desta noite (5\/4) o advogado Eri Varela em decorr\u00eancia de acidente de carro na estrada para Cristalina (GO). O carro em que ele estava bateu de frente com um \u00f4nibus de turismo na BR 040. O corpo de Varela est\u00e1 sendo levado para o IML de Formosa (GO). O advogado costumava viajar [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":14918,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"wpb_read_more":[],"footnotes":""},"categories":[6],"tags":[1747,269,15],"class_list":["post-14917","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-eri-varela","tag-roriz","tag-terracap"],"_links":{"self":[{"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/posts\/14917","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/comments?post=14917"}],"version-history":[{"count":4,"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/posts\/14917\/revisions"}],"predecessor-version":[{"id":14922,"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/posts\/14917\/revisions\/14922"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/media\/14918"}],"wp:attachment":[{"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/media?parent=14917"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/categories?post=14917"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/tags?post=14917"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}