{"id":15041,"date":"2019-04-17T19:30:02","date_gmt":"2019-04-17T22:30:02","guid":{"rendered":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/?p=15041"},"modified":"2019-04-17T19:40:45","modified_gmt":"2019-04-17T22:40:45","slug":"stj-mantem-condenacao-de-conselheiro-do-tcdf-por-improbidade-administrativa","status":"publish","type":"post","link":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/stj-mantem-condenacao-de-conselheiro-do-tcdf-por-improbidade-administrativa\/","title":{"rendered":"STJ mant\u00e9m condena\u00e7\u00e3o de conselheiro do TCDF por improbidade administrativa"},"content":{"rendered":"<p><span style=\"font-weight: 400\">O ministro do Superior Tribunal de Justi\u00e7a (STJ) Mauro Campbell Marques negou recurso e manteve a condena\u00e7\u00e3o por improbidade administrativa do conselheiro do Tribunal de Contas do Distrito Federal (TCDF) Manoel Paulo de Andrade, conhecido como Manoelzinho do T\u00e1xi. <\/span><span style=\"font-weight: 400\">Acusado de retardar o julgamento de um processo envolvendo permiss\u00f5es de t\u00e1xis em 2015, ele ter\u00e1 de pagar multa equivalente a 10 vezes o valor da remunera\u00e7\u00e3o recebida \u00e0 \u00e9poca. <\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400\">De acordo com a a\u00e7\u00e3o do Minist\u00e9rio P\u00fablico do DF e Territ\u00f3rios (MPDFT), Manoelzinho pediu vistas ao processo em 12 de agosto de 2014 e o devolveu apenas em 17 de agosto de 2015.\u00a0Manoel Paulo de Andrade Neto \u00e9 conhecido como aliado dos taxistas. Antes de assumir o cargo vital\u00edcio de conselheiro do TCDF, em 2000, ele liderou a categoria. Presidiu o sindicato dos taxistas, foi vice-presidente da Federa\u00e7\u00e3o Nacional dos Condutores Aut\u00f4nomos de Bens, diretor da Confedera\u00e7\u00e3o dos Transportes e diretor do Sest\/Senat. Eleito deputado distrital, tornou-se secret\u00e1rio de Administra\u00e7\u00e3o do governo de Joaquim Roriz, que o indicou ao TCDF.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400\">Pelo mesmo caso, o conselheiro responde por prevarica\u00e7\u00e3o na esfera penal. <\/span><span style=\"font-weight: 400\">O caso foi revelado pelo <\/span><b>Correio<\/b><span style=\"font-weight: 400\">. \u00c0 \u00e9poca, o jornal mostrou que, al\u00e9m de Manoelzinho ter ocupado cargos de lideran\u00e7a entre taxistas, ele mantinha uma permiss\u00e3o de t\u00e1xi em seu nome, o que \u00e9 proibido pela fun\u00e7\u00e3o de servidor p\u00fablico e por uma portaria do TCDF que n\u00e3o permite que um conselheiro tenha ocupa\u00e7\u00e3o paralela. Dessa forma, pelo interesse pessoal, teria que declarar suspei\u00e7\u00e3o na an\u00e1lise do processo. Entretanto, ele s\u00f3 o fez ap\u00f3s a s\u00e9rie de reportagens. <\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400\">Na decis\u00e3o desta ter\u00e7a-feira (16\/04), o ministro Mauro Campbell Marques ainda ainda manteve a proibi\u00e7\u00e3o imposta a Manoelzinho de contratar com o Poder P\u00fablico, e receber benef\u00edcios, incentivos fiscais ou credit\u00edcios, direta ou indiretamente, ainda que por interm\u00e9dio de empresa da qual seja s\u00f3cio majorit\u00e1rio, pelo prazo de tr\u00eas anos. As penalidades estavam previstas em senten\u00e7a, de 2017, da 5\u00aa Vara C\u00edvel do Tribunal de Justi\u00e7a do DF e dos Territ\u00f3rios (TJDFT). Nenhuma das senten\u00e7as decretou a perda do cargo.<\/span><\/p>\n<p>&nbsp;<\/p>\n<h2><b>\u201cDecis\u00e3o injusta\u201d<\/b><\/h2>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400\">Contatado pelo <\/span><b>Correio<\/b><span style=\"font-weight: 400\">, o TCDF informou que n\u00e3o se manifestar\u00e1 sobre a decis\u00e3o. O advogado de Manoel de Andrade, Juliano Costa Couto, classificou a decis\u00e3o como \u201cinjusta\u201d. \u201cVamos lutar at\u00e9 onde for poss\u00edvel\u201d, disse. \u201cH\u00e1 espa\u00e7o para levar \u00e0 turma a reflex\u00e3o de alguns pontos que n\u00e3o foram t\u00e3o bem abordados na decis\u00e3o\u201d, acrescentou.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O ministro do Superior Tribunal de Justi\u00e7a (STJ) Mauro Campbell Marques negou recurso e manteve a condena\u00e7\u00e3o por improbidade administrativa do conselheiro do Tribunal de Contas do Distrito Federal (TCDF) Manoel Paulo de Andrade, conhecido como Manoelzinho do T\u00e1xi. Acusado de retardar o julgamento de um processo envolvendo permiss\u00f5es de t\u00e1xis em 2015, ele ter\u00e1 [&hellip;]<\/p>\n","protected":false},"author":90,"featured_media":8836,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"wpb_read_more":[],"footnotes":""},"categories":[234],"tags":[99,1769,1770,215,143],"class_list":["post-15041","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cb-poder","tag-conselheiro","tag-improbidade-administrativa","tag-manoelzinho-do-taxi","tag-stj","tag-tcdf"],"_links":{"self":[{"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/posts\/15041","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/users\/90"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/comments?post=15041"}],"version-history":[{"count":2,"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/posts\/15041\/revisions"}],"predecessor-version":[{"id":15043,"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/posts\/15041\/revisions\/15043"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/media\/8836"}],"wp:attachment":[{"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/media?parent=15041"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/categories?post=15041"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/tags?post=15041"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}