{"id":15061,"date":"2019-04-20T11:33:17","date_gmt":"2019-04-20T14:33:17","guid":{"rendered":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/?p=15061"},"modified":"2019-04-20T11:33:17","modified_gmt":"2019-04-20T14:33:17","slug":"com-viagem-de-ibaneis-e-vice-prudente-sera-o-governador-mais-jovem-a-ocupar-o-posto","status":"publish","type":"post","link":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/com-viagem-de-ibaneis-e-vice-prudente-sera-o-governador-mais-jovem-a-ocupar-o-posto\/","title":{"rendered":"Com viagem de Ibaneis e vice, Prudente ser\u00e1 o &#8216;governador&#8217; mais jovem a ocupar o posto"},"content":{"rendered":"<p><strong>Coluna Eixo Capital\/Por Ana Maria Campos<\/strong><\/p>\n<p>Com a viagem do governador Ibaneis Rocha (MDB) e do vice Paco Britto (Avante) \u00e0 Europa na pr\u00f3xima semana, o presidente da C\u00e2mara Legislativa, Rafael Prudente (MDB), assume o comando do Pal\u00e1cio do Buriti e se torna o mais jovem pol\u00edtico a ocupar tal posto. Aos 35 anos, completados em novembro, ele vai responder pelo Executivo at\u00e9 o in\u00edcio de maio. Trata-se, mais do que tudo, de uma defer\u00eancia ao parlamentar do MDB, que poder\u00e1 ter no curr\u00edculo a passagem pelo Executivo.<\/p>\n<h2><strong>Paulo Chagas: \u201cTenho f\u00e9 na Justi\u00e7a\u201d<\/strong><\/h2>\n<p><a href=\"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/incomoda-inseguranca-juridica-paulo-chagas-alvo-do-stf\/\">Alvo de busca e apreens\u00e3o no inqu\u00e9rito sobre fake news<\/a>, o general Paulo Chagas continua se manifestando pelas redes sociais. No Twitter, o oficial da reserva escreveu ontem: \u201cCaros amigos, \u00e9 meu direito n\u00e3o concordar e n\u00e3o calar diante do que sou obrigado a aceitar e cumprir. Poderia faz\u00ea-lo anonimamente, mas isto me \u00e9 vedado pela Constitui\u00e7\u00e3o e pela minha consci\u00eancia\u201d. E acrescentou: \u201cTenho f\u00e9 na Justi\u00e7a porque, como em Berlim, ainda h\u00e1 Ju\u00edzes no Brasil\u201d. A frase, que remete \u00e0 interpreta\u00e7\u00e3o de que ainda h\u00e1 quem respeite a lei, \u00e9 de autoria do poeta e dramaturgo franc\u00eas Fran\u00e7ois Andrieux, que escreveu, em versos, no s\u00e9culo XVIII, o conto O Moleiro de Sans-Souci.<\/p>\n<h2><strong>Coordenador da bancada e os cargos no governo Bolsonaro<\/strong><\/h2>\n<p>A falta de acordo para a elei\u00e7\u00e3o de um coordenador da bancada federal do DF tem um motivo principal: o l\u00edder dos deputados e senadores vai distribuir os cargos destinados pelo governo Jair Bolsonaro aos parlamentares de cada unidade da federa\u00e7\u00e3o como recompensa pelo apoio nas vota\u00e7\u00f5es. O assunto foi tratado com a l\u00edder do governo no Congresso, Joice Hasselmann (PSL-SP).<\/p>\n<h2><strong>Pol\u00edtica interna<\/strong><\/h2>\n<p>Para muita gente no MP, o gesto da procuradora-geral da Rep\u00fablica, Raquel Dodge, de arquivar o inqu\u00e9rito sobre fake news no STF, na crise desta semana, foi uma medida voltada para dentro. A investiga\u00e7\u00e3o do Supremo, aberta de of\u00edcio pelo presidente da Corte, Dias Toffoli, tem sido combatida por procuradores em todo o pa\u00eds, como inconstitucional, por entrar na atribui\u00e7\u00e3o constitucional do MP de denunciar. O clima \u00e9 de racha na institui\u00e7\u00e3o, principalmente com a aproxima\u00e7\u00e3o do fim do mandato de Dodge e a disputa pela sua sucess\u00e3o.<\/p>\n<h2><strong>Frente em defesa dos bancos p\u00fablicos<\/strong><\/h2>\n<p>Entidades representativas mobilizam-se para a cria\u00e7\u00e3o da Frente Parlamentar Mista em Defesa dos Bancos P\u00fablicos. Com 184 das 198 assinaturas necess\u00e1rias para a abertura da Frente, a causa dos bancos p\u00fablicos tem a ades\u00e3o de senadores e deputados de 19 partidos ideologicamente distintos. A Frente ser\u00e1 pauta do Semin\u00e1rio em Defesa dos Bancos P\u00fablicos, que acontecer\u00e1 no pr\u00f3ximo dia 8, no audit\u00f3rio Nereu Ramos, na C\u00e2mara dos Deputados. \u201cAs estrat\u00e9gias e a\u00e7\u00f5es adotadas at\u00e9 o momento sinalizam um inevit\u00e1vel enfraquecimento dos bancos p\u00fablicos. Queremos que a Caixa continue exercendo o seu papel fundamental para a sociedade brasileira\u201d, avalia o presidente da Federa\u00e7\u00e3o Nacional das Associa\u00e7\u00f5es do Pessoal da Caixa (Fenae), Jair Pedro Ferreira.<\/p>\n<h2><strong>Roriz\u00f5es<\/strong><\/h2>\n<p>Sobrinho de Joaquim Roriz, Ded\u00e9 Roriz pediu a Ibaneis Rocha que d\u00ea o nome do ex-governador aos restaurantes comunit\u00e1rios do DF. Muitos moradores j\u00e1 os batizaram de \u201cRoriz\u00e3o\u201d.<\/p>\n<h2>\n<strong>Novas gera\u00e7\u00f5es<\/strong><\/h2>\n<p>Ex-presidente da Terracap, o procurador de Justi\u00e7a aposentado Ant\u00f4nio Gomes foi convidado para assumir um cargo na \u00e1rea social do governo Ibaneis. Mas n\u00e3o topou. Avalia que chegou a hora das novas gera\u00e7\u00f5es.<\/p>\n<h2><strong>A pergunta que n\u00e3o quer calar\u2026.<\/strong><\/h2>\n<p>Quais ser\u00e3o os impactos da crise no Judici\u00e1rio deflagrada com a abertura de inqu\u00e9rito no STF para apurar ataques contra o pr\u00f3prio STF?<\/p>\n<h2><strong>S\u00f3 papos<\/strong><\/h2>\n<blockquote>\n<p style=\"text-align: right\">\u201cFico feliz, \u00e9 uma colabora\u00e7\u00e3o muito bem-vinda. N\u00e3o \u00e9 por nenhum problema na nossa estrutura, mas certamente toda for\u00e7a que vem para c\u00e1 nos ajuda\u201d<\/p>\n<\/blockquote>\n<p style=\"text-align: right\"><strong>Governador Ibaneis Rocha (MDB) sobre a decis\u00e3o do governo Bolsonaro de autorizar o emprego da For\u00e7a Nacional de Seguran\u00e7a para conter manifesta\u00e7\u00f5es na Esplanada<\/strong><\/p>\n<blockquote>\n<p style=\"text-align: right\">\n\u201cEssa atua\u00e7\u00e3o da For\u00e7a Nacional para lidar com as manifesta\u00e7\u00f5es populares \u00e9 um desrespeito \u00e0 PMDF, respons\u00e1vel por garantir a seguran\u00e7a na cidade\u201d<\/p>\n<\/blockquote>\n<p style=\"text-align: right\"><strong>Deputado distrital Leandro Grass (Rede), reagindo \u00e0 portaria assinada pelo ministro da Justi\u00e7a e Seguran\u00e7a P\u00fablica, S\u00e9rgio Moro<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Coluna Eixo Capital\/Por Ana Maria Campos Com a viagem do governador Ibaneis Rocha (MDB) e do vice Paco Britto (Avante) \u00e0 Europa na pr\u00f3xima semana, o presidente da C\u00e2mara Legislativa, Rafael Prudente (MDB), assume o comando do Pal\u00e1cio do Buriti e se torna o mais jovem pol\u00edtico a ocupar tal posto. Aos 35 anos, completados [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":14016,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"wpb_read_more":[],"footnotes":""},"categories":[234],"tags":[],"class_list":["post-15061","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cb-poder"],"_links":{"self":[{"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/posts\/15061","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/comments?post=15061"}],"version-history":[{"count":1,"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/posts\/15061\/revisions"}],"predecessor-version":[{"id":15062,"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/posts\/15061\/revisions\/15062"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/media\/14016"}],"wp:attachment":[{"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/media?parent=15061"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/categories?post=15061"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/tags?post=15061"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}