{"id":15106,"date":"2019-04-24T17:41:01","date_gmt":"2019-04-24T20:41:01","guid":{"rendered":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/?p=15106"},"modified":"2019-04-24T17:42:53","modified_gmt":"2019-04-24T20:42:53","slug":"distritais-aprovam-projeto-que-extingue-agefis-e-cria-df-legal","status":"publish","type":"post","link":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/distritais-aprovam-projeto-que-extingue-agefis-e-cria-df-legal\/","title":{"rendered":"Distritais aprovam projeto que extingue Agefis e cria DF Legal"},"content":{"rendered":"<p><span style=\"font-weight: 400\">Os distritais aprovaram em dois turnos, nesta quarta-feira (24\/04), o projeto de lei que transforma a Ag\u00eancia de Fiscaliza\u00e7\u00e3o do Distrito Federal (Agefis), a qual funciona como autarquia em regime especial, na Secretaria de Estado de Prote\u00e7\u00e3o da Ordem Urban\u00edstica do DF (DF Legal). De acordo com o Executivo local, a proposta assegura integra\u00e7\u00e3o mais pr\u00f3xima e r\u00e1pida entre a nova pasta e os demais \u00f3rg\u00e3os da administra\u00e7\u00e3o p\u00fablica. O texto vai \u00e0 san\u00e7\u00e3o do governador Ibaneis Rocha (MDB).<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400\">A proposi\u00e7\u00e3o coloca nas m\u00e3os do DF Legal as principais atribui\u00e7\u00f5es da Agefis. A pasta dever\u00e1 supervisionar, planejar, coordenar e promover &#8220;a\u00e7\u00f5es que garantam a prote\u00e7\u00e3o da ordem urban\u00edstica, fundi\u00e1ria e ambiental, por meio de a\u00e7\u00f5es e pr\u00e1ticas estrat\u00e9gicas de controle e de combate ao uso, ocupa\u00e7\u00e3o e parcelamento irregular do solo\u201d.<\/span><\/p>\n<p>&nbsp;<\/p>\n<blockquote><p><span style=\"font-weight: 400\">H\u00e1, entretanto, mudan\u00e7as. A mat\u00e9ria extingue o Tribunal de Julgamento Administrativo. Com isso, a atribui\u00e7\u00e3o de julgar em segunda e \u00faltima inst\u00e2ncias os processos administrativos ser\u00e1 exercida por uma Junta de An\u00e1lise de Recursos. A entidade ser\u00e1 composta de seis representantes ocupantes de cargos efetivos das carreiras de auditoria de atividades urbanas e de fiscaliza\u00e7\u00e3o e inspe\u00e7\u00e3o de atividades urbanas e igual n\u00famero de representantes da sociedade civil, para mandato de tr\u00eas anos, como conselheiros da Junta de An\u00e1lise de Recursos.<\/span><\/p><\/blockquote>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400\">Al\u00e9m disso, o projeto abre possibilidade para que o cargo de secret\u00e1rio-adjunto seja ocupado por servidores da Carreira de Fiscaliza\u00e7\u00e3o e Inspe\u00e7\u00e3o de Atividades Urbanas \u2014 antes, o posto equivalente na autarquia, de diretor-geral, era restrito aos profissionais da Carreira de Auditoria de Atividades Urbanas. <\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400\">Os cargos de subsecret\u00e1rio, coordenador, diretor e chefes de atividades fim da Subsecretaria de Fiscaliza\u00e7\u00e3o de Res\u00edduo tamb\u00e9m ser\u00e3o destinados, exclusivamente, aos servidores das duas carreiras. <\/span><span style=\"font-weight: 400\">Todos os funcion\u00e1rios p\u00fablicos e comissionados passar\u00e3o a compor automaticamente o quadro de pessoal do DF Legal.<\/span><\/p>\n<p>&nbsp;<\/p>\n<h2><b>Emendas <\/b><\/h2>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400\">Os parlamentares aprovaram a incorpora\u00e7\u00e3o de 11 emendas ao projeto original. Entre elas, uma de autoria de F\u00e1bio Felix (PSol), que cria um protocolo humanizado de cinco itens para as desocupa\u00e7\u00f5es. Conforme as regras, as remo\u00e7\u00f5es de fam\u00edlias n\u00e3o poder\u00e3o ocorrer em feriados, \u00e0 noite ou sob chuva intensa, a n\u00e3o ser que o procedimento seja realizado para garantir a seguran\u00e7a dos moradores, como em casos de risco de desabamento de terras. <\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400\">Segundo a emenda, o governo ainda precisar\u00e1 assegurar abrigos provis\u00f3rios e de transporte das fam\u00edlias em situa\u00e7\u00e3o de vulnerabilidade socioecon\u00f4mica e de seus bens. Al\u00e9m disso, a nova pasta deve prever tratamento espec\u00edfico e priorit\u00e1rio para mulheres, idosos, crian\u00e7as e deficientes f\u00edsicos. <\/span><\/p>\n<p>&nbsp;<\/p>\n<h2><b>Agefis<\/b><\/h2>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400\">Criada na gest\u00e3o de Jos\u00e9 Arruda (PR), a Ag\u00eancia de Fiscaliza\u00e7\u00e3o do Distrito Federal (Agefis) atua desde 2008. \u00c0quele ano, os distritais aprovaram um projeto de lei que transformou a Subsecretaria de Fiscaliza\u00e7\u00e3o em uma autarquia sob regime especial, com autonomia administrativa e financeira. No texto enviado \u00e0 C\u00e2mara Legislativa, Arruda argumentou que a concentra\u00e7\u00e3o das atividades de fiscaliza\u00e7\u00e3o em uma Ag\u00eancia permitiria \u201cmaior integra\u00e7\u00e3o do sistema, fortalecendo a fun\u00e7\u00e3o desempenhada e promovendo uma maior sistematiza\u00e7\u00e3o e intelig\u00eancia no desenvolvimento das pol\u00edticas fiscalizat\u00f3rias distritais\u201d.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400\">Durante a campanha, a extin\u00e7\u00e3o da autarquia tornou-se o mote de diversos candidatos. Entre eles, Ibaneis. Ap\u00f3s a pol\u00eamica, <\/span><span style=\"font-weight: 400\">o chefe do Executivo decidiu reformular a legisla\u00e7\u00e3o da \u00e1rea de fiscaliza\u00e7\u00e3o, mas manteve as atribui\u00e7\u00f5es centralizadas. Uma das possibilidades era dividir as responsabilidades, passando tarefas \u00e0s administra\u00e7\u00f5es regionais. Mas essa medida foi considerada arriscada.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Os distritais aprovaram em dois turnos, nesta quarta-feira (24\/04), o projeto de lei que transforma a Ag\u00eancia de Fiscaliza\u00e7\u00e3o do Distrito Federal (Agefis), a qual funciona como autarquia em regime especial, na Secretaria de Estado de Prote\u00e7\u00e3o da Ordem Urban\u00edstica do DF (DF Legal). De acordo com o Executivo local, a proposta assegura integra\u00e7\u00e3o mais [&hellip;]<\/p>\n","protected":false},"author":90,"featured_media":15083,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"wpb_read_more":[],"footnotes":""},"categories":[234],"tags":[34,191,1773,917,160],"class_list":["post-15106","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cb-poder","tag-agefis","tag-derrubadas","tag-df-legal","tag-ibaneis-rocha","tag-secretaria"],"_links":{"self":[{"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/posts\/15106","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/users\/90"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/comments?post=15106"}],"version-history":[{"count":2,"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/posts\/15106\/revisions"}],"predecessor-version":[{"id":15110,"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/posts\/15106\/revisions\/15110"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/media\/15083"}],"wp:attachment":[{"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/media?parent=15106"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/categories?post=15106"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/tags?post=15106"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}