{"id":15293,"date":"2019-05-11T09:50:48","date_gmt":"2019-05-11T12:50:48","guid":{"rendered":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/?p=15293"},"modified":"2019-05-11T09:50:48","modified_gmt":"2019-05-11T12:50:48","slug":"cooperativa-que-teria-repassado-propina-a-fraga-e-considerada-inidonea-pelo-governo-ibaneis","status":"publish","type":"post","link":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/cooperativa-que-teria-repassado-propina-a-fraga-e-considerada-inidonea-pelo-governo-ibaneis\/","title":{"rendered":"Cooperativa que teria repassado propina a Fraga \u00e9 considerada inid\u00f4nea pelo governo Ibaneis"},"content":{"rendered":"<p><strong>Coluna Eixo Capital\/Por Ana Maria Campos<\/strong><\/p>\n<p>O governo declarou a idoneidade da Cooperativa dos Profissionais Aut\u00f4nomos de Transporte Alternativo do Gama (Coopatag). A entidade ficar\u00e1 proibida de contratar com a administra\u00e7\u00e3o p\u00fablica em todos os poderes do Estado, pelo prazo de dois anos. A Coopatag esteve no centro de um esc\u00e2ndalo de cobran\u00e7a de propina de cooperativas de micro-\u00f4nibus, em 2009, na gest\u00e3o do ent\u00e3o secret\u00e1rio de Transportes Alberto Fraga.<\/p>\n<h2>\n<strong>Baixo desempenho<\/strong><\/h2>\n<p>Na justificativa, o secret\u00e1rio de Mobilidade, Valter Casimiro, explica que a cooperativa descumpriu o contrato em raz\u00e3o de baixo desempenho e inefici\u00eancia. No processo em que foi condenado a seis anos e oito meses de pris\u00e3o, o ex-deputado Alberto Fraga aparece, em conversas interceptadas na investiga\u00e7\u00e3o, com autoriza\u00e7\u00e3o judicial, reclamando de receber menos propina que subordinados. A permission\u00e1ria teria entrado em opera\u00e7\u00e3o, segundo a den\u00fancia, depois de pagar R$ 200 mil. Fraga nega a acusa\u00e7\u00e3o.<\/p>\n<h2>\n<strong>Revitaliza\u00e7\u00e3o na pauta<\/strong><\/h2>\n<p>Um dos projetos de maior interesse do setor produtivo de Bras\u00edlia, de revitaliza\u00e7\u00e3o do Setor de Ind\u00fastrias Gr\u00e1ficas (SIG), ser\u00e1 debatido em audi\u00eancia p\u00fablica no pr\u00f3ximo dia 3. A proposta do Executivo prev\u00ea a flexibiliza\u00e7\u00e3o dos usos no SIG, permitindo atividades como com\u00e9rcio, servi\u00e7os e uso institucional.<\/p>\n<h2>\n<strong>Reestrutura\u00e7\u00e3o da Pol\u00edcia Civil em estudo<\/strong><\/h2>\n<p>O diretor-geral da Pol\u00edcia Civil do DF, Robson C\u00e2ndido, criou uma comiss\u00e3o para apresentar um projeto de reestrutura\u00e7\u00e3o da Pol\u00edcia Civil. A ideia \u00e9 adequar os departamentos, diretorias, coordena\u00e7\u00f5es e delegacias ao que determina o Supremo Tribunal Federal (STF). Os ministros exigem que a estrutura seja definida por lei federal, uma vez que a seguran\u00e7a p\u00fablica do DF \u00e9 vinculada \u00e0 Uni\u00e3o. De carona nessa discuss\u00e3o, muitas mudan\u00e7as podem ocorrer, com fortalecimento de algumas \u00e1reas.<\/p>\n<h2>\n<strong>Por onde anda?<\/strong><\/h2>\n<p>O ex-presidente da C\u00e2mara Legislativa Joe Valle tem investido todo seu esfor\u00e7o para ampliar os neg\u00f3cios. Sem mandato, o ex-deputado distrital se dedica \u00e0 Malunga, empresa destinada a produtos org\u00e2nicos. Um novo mercado foi inaugurado ontem no Sudoeste.<\/p>\n<h2>\n<strong>Paula Belmonte: \u201cN\u00e3o tenho pol\u00edtico de estima\u00e7\u00e3o\u201d<\/strong><\/h2>\n<p>A deputada Paula Belmonte (Cidadania\/DF) garante que, se a elei\u00e7\u00e3o fosse hoje, n\u00e3o apoiaria o senador Izalci Lucas (PSDB\/DF) como <a href=\"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/os-possiveis-adversarios-na-proxima-disputa-ao-buriti\/\">candidato ao Pal\u00e1cio do Buriti<\/a>. \u201cMesmo meu marido sendo o suplente (do Izalci) n\u00e3o temos nenhum tipo de expectativa e principalmente n\u00e3o apoiaremos algu\u00e9m com atitudes que n\u00e3o correspondam ao que julgamos n\u00e3o ser a melhor para a cidade\u201d, afirma Paula. \u201cMeu marido \u00e9 totalmente independente e n\u00e3o tenho amigo e muito menos pol\u00edtico de estima\u00e7\u00e3o\u201d. O advogado Luiz Felipe Belmonte, marido de Paula, ser\u00e1 senador por quatro anos se Izalci for eleito governador em 2022. Na mudan\u00e7a de comando do Minist\u00e9rio da Educa\u00e7\u00e3o, quando Izalci teve o nome cogitado para o cargo, Belmonte chegou a comentar com pessoas pr\u00f3ximas que a chance de assumir o mandato era real.<\/p>\n<h2>\n<strong>Sobre Fl\u00e1via Arruda: \u201cN\u00e3o fico na bajula\u00e7\u00e3o s\u00f3 porque o marido dela ainda \u00e9 um homem influente\u201d<\/strong><\/h2>\n<p>Sobre o clima de rivalidade com a deputada Fl\u00e1via Arruda (PR\/DF), Paula Belmonte explicou que houve uma interpreta\u00e7\u00e3o equivocada por parte da parlamentar, mulher do ex-governador Jos\u00e9 Roberto Arruda, o que teria causado um distanciamento entre as duas. \u201cA situa\u00e7\u00e3o com a Fl\u00e1via n\u00e3o tem nada a ver com as elei\u00e7\u00f5es de 2022, at\u00e9 porque posso tamb\u00e9m querer concorrer ao governo\u201d, disse Paula. \u201cO temperamento dela n\u00e3o \u00e9 f\u00e1cil, arrogante, e eu n\u00e3o fico na bajula\u00e7\u00e3o, s\u00f3 porque o marido dela ainda \u00e9 um homem influente. Como falei, eu sou totalmente independente\u201d, acrescentou a deputada em mensagem \u00e0 coluna.<\/p>\n<h2><strong><em>S\u00f3 papos<\/em><\/strong><\/h2>\n<blockquote>\n<p style=\"text-align: right\">\u201cSobre o COAF, nunca fiz a perman\u00eancia dele no MJSP uma quest\u00e3o pessoal. Defendi a medida para fortalecer o combate \u00e0 corrup\u00e7\u00e3o, \u00e0 lavagem de dinheiro, ao crime organizado e ao financiamento ao terrorismo\u201d<\/p>\n<\/blockquote>\n<p style=\"text-align: right\"><strong>Ministro da Justi\u00e7a e Seguran\u00e7a P\u00fablica S\u00e9rgio Moro<\/strong><\/p>\n<blockquote>\n<p style=\"text-align: right\">\n\u201cO COAF sempre funcionou bem no antigo Minist\u00e9rio da Fazenda. Desde que o atual Minist\u00e9rio da Economia assegure a autonomia do \u00f3rg\u00e3o, n\u00e3o vejo diferen\u00e7a para seu funcionamento em que ele l\u00e1 permane\u00e7a ou v\u00e1 para o Minist\u00e9rio da Justi\u00e7a. Parece-me indiferente para sua efici\u00eancia\u201d<\/p>\n<\/blockquote>\n<p style=\"text-align: right\"><strong>Procurador regional da Rep\u00fablica Wellington Saraiva<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Coluna Eixo Capital\/Por Ana Maria Campos O governo declarou a idoneidade da Cooperativa dos Profissionais Aut\u00f4nomos de Transporte Alternativo do Gama (Coopatag). A entidade ficar\u00e1 proibida de contratar com a administra\u00e7\u00e3o p\u00fablica em todos os poderes do Estado, pelo prazo de dois anos. A Coopatag esteve no centro de um esc\u00e2ndalo de cobran\u00e7a de propina [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":14994,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"wpb_read_more":[],"footnotes":""},"categories":[234],"tags":[],"class_list":["post-15293","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cb-poder"],"_links":{"self":[{"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/posts\/15293","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/comments?post=15293"}],"version-history":[{"count":1,"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/posts\/15293\/revisions"}],"predecessor-version":[{"id":15294,"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/posts\/15293\/revisions\/15294"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/media\/14994"}],"wp:attachment":[{"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/media?parent=15293"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/categories?post=15293"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/tags?post=15293"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}