{"id":15419,"date":"2019-05-22T07:28:36","date_gmt":"2019-05-22T10:28:36","guid":{"rendered":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/?p=15419"},"modified":"2019-05-22T08:39:04","modified_gmt":"2019-05-22T11:39:04","slug":"mpdft-e-policia-civil-cumprem-mandados-de-busca-no-detran","status":"publish","type":"post","link":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/mpdft-e-policia-civil-cumprem-mandados-de-busca-no-detran\/","title":{"rendered":"MPDFT e Pol\u00edcia Civil cumprem mandados de busca no Detran"},"content":{"rendered":"<h5 style=\"padding-left: 30px;text-align: left\">ANA MARIA CAMPOS<\/h5>\n<p class=\"s5\">A <span class=\"s6\">Pol\u00edcia Civil do DF\u00a0<\/span>por meio da Divis\u00e3o de Repress\u00e3o \u00e0 Corrup\u00e7\u00e3o e aos Crimes Contra a Administra\u00e7\u00e3o P\u00fablica (DICAP\/CECOR) e o <span class=\"s6\">Minist\u00e9rio P\u00fablico do Distrito Federal e Territ\u00f3rios<\/span>, por meio da Promotoria de Justi\u00e7a de Defesa do Patrim\u00f4nio P\u00fablico e Social (PRODEP)deflagraram na manh\u00e3 de hoje (22\/5) a Opera\u00e7\u00e3o \u00a0Blitzkrieg.<\/p>\n<p>&nbsp;<\/p>\n<p class=\"s5\">O objetivo \u00e9 apurar crimes relacionados \u00e0 contrata\u00e7\u00e3o de manuten\u00e7\u00e3o e moderniza\u00e7\u00e3o do sistema de sem\u00e1foros pelo Departamento de Tr\u00e2nsito do Distrito Federal (Detran\/DF).<\/p>\n<p>&nbsp;<\/p>\n<p class=\"s5\">Foram cumpridos sete mandados de busca e apreens\u00e3o no Distrito Federal, expedidos pela 5\u00aa Vara Criminal de Bras\u00edlia, em reparti\u00e7\u00f5es do Detran e nas resid\u00eancias de servidores p\u00fablicos supostamente envolvidos nos il\u00edcitos.<\/p>\n<p>&nbsp;<\/p>\n<p>Entre os alvos est\u00e1 o ex-diretor-geral do Detran Fabr\u00edcio Moura, que deixou o cargo depois que as suspeitas de irregularidades vieram \u00e0 tona.<\/p>\n<p>&nbsp;<\/p>\n<p>Tamb\u00e9m s\u00e3o alvos o irm\u00e3o de Fabr\u00edcio, Felipe Moura, a ex-diretora-adjunta do Detran Ana Cl\u00e1udia Gnone de Oliveira e o ex-diretor de Engenharia Dawton Roberto Batista Gaia.<\/p>\n<p>&nbsp;<\/p>\n<p>As buscas s\u00e3o realizadas no gabinete do dire\u00e7\u00e3o-geral, na dire\u00e7\u00e3o de Engenharia e na casa dos investigados.<\/p>\n<p>&nbsp;<\/p>\n<p>O Minist\u00e9rio P\u00fablico do DF abriu investiga\u00e7\u00e3o depois de receber uma den\u00fancia, embasada por documentos internos do Detran.<\/p>\n<p>&nbsp;<\/p>\n<p>O Minist\u00e9rio P\u00fablico pediu ao Detran c\u00f3pia do processo que levou \u00e0 celebra\u00e7\u00e3o do Contrato Emergencial n\u00ba 1\/2019. Entre os documentos entregues ao MP est\u00e3o \u00e1udios de supostas conversas relacionadas a uma nova licita\u00e7\u00e3o \u2013 mais ampla e mais cara.<\/p>\n<p>&nbsp;<\/p>\n<p>As buscas visam obten\u00e7\u00e3o de provas que ir\u00e3o subsidiar as investiga\u00e7\u00f5es em andamento no Minist\u00e9rio P\u00fablico e na Pol\u00edcia Civil.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>ANA MARIA CAMPOS A Pol\u00edcia Civil do DF\u00a0por meio da Divis\u00e3o de Repress\u00e3o \u00e0 Corrup\u00e7\u00e3o e aos Crimes Contra a Administra\u00e7\u00e3o P\u00fablica (DICAP\/CECOR) e o Minist\u00e9rio P\u00fablico do Distrito Federal e Territ\u00f3rios, por meio da Promotoria de Justi\u00e7a de Defesa do Patrim\u00f4nio P\u00fablico e Social (PRODEP)deflagraram na manh\u00e3 de hoje (22\/5) a Opera\u00e7\u00e3o \u00a0Blitzkrieg. &nbsp; [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":15432,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"wpb_read_more":[],"footnotes":""},"categories":[234],"tags":[170,1802],"class_list":["post-15419","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cb-poder","tag-detran","tag-semaforos"],"_links":{"self":[{"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/posts\/15419","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/comments?post=15419"}],"version-history":[{"count":9,"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/posts\/15419\/revisions"}],"predecessor-version":[{"id":15433,"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/posts\/15419\/revisions\/15433"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/media\/15432"}],"wp:attachment":[{"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/media?parent=15419"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/categories?post=15419"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/tags?post=15419"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}