{"id":15462,"date":"2019-05-25T15:02:09","date_gmt":"2019-05-25T18:02:09","guid":{"rendered":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/?p=15462"},"modified":"2019-05-25T15:02:09","modified_gmt":"2019-05-25T18:02:09","slug":"tribunal-de-contas-do-df-quer-esclarecimentos-sobre-aumento-de-casos-de-dengue-na-capital","status":"publish","type":"post","link":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/tribunal-de-contas-do-df-quer-esclarecimentos-sobre-aumento-de-casos-de-dengue-na-capital\/","title":{"rendered":"Tribunal de Contas do DF quer esclarecimentos sobre aumento de casos de dengue na capital"},"content":{"rendered":"<p>O Tribunal de Contas do DF abriu prazo de 15 dias para a Secretaria de Sa\u00fade se manifestar sobre o aumento do n\u00famero de casos de dengue no DF. Os conselheiros pediram que a pasta apresente esclarecimentos e encaminhe c\u00f3pia de documentos que respaldem essas informa\u00e7\u00f5es. A decis\u00e3o foi tomada com base em representa\u00e7\u00e3o do deputado Leandro Grass (Rede), que aponta ind\u00edcios de neglig\u00eancia nas a\u00e7\u00f5es de combate a doen\u00e7as end\u00eamicas, como as transmitidas pelo mosquito Aedes aegypti. Segundo dados do boletim epidemiol\u00f3gico, o DF registrou, entre janeiro e 11 de maio, 19.812 notifica\u00e7\u00f5es de caso de dengue. As mortes alcan\u00e7aram 16 v\u00edtimas \u2014 15 a mais do que o mesmo per\u00edodo do ano passado. Ontem, o governo criou uma for\u00e7a-tarefa de combate \u00e0 dengue.<\/p>\n<h3>\n<strong>Mais um distrital na equipe de Ibaneis<\/strong><\/h3>\n<p>O governador Ibaneis Rocha (MDB) deve criar uma nova secretaria ou subsecretaria para abrigar mais um distrital em sua equipe. O deputado Iolando (PSC) viaja na pr\u00f3xima semana para S\u00e3o Paulo com o objetivo de conhecer a estrutura e o funcionamento das secretarias estadual e municipal da Pessoa com Defici\u00eancia, foco de sua atua\u00e7\u00e3o parlamentar. Vai acompanhado do chefe de gabinete, Samuel Rodrigues de Sousa, sem \u00f4nus para a C\u00e2mara Legislativa, a n\u00e3o ser os sal\u00e1rios. Iolando est\u00e1 entrando numa \u00e1rea que durante duas d\u00e9cadas foi a base do ex-deputado Ben\u00edcio Tavares (MDB), hoje sem mandato.<\/p>\n<p><strong>Siga o dinheiro<\/strong><\/p>\n<p>R$ 7.926.000<\/p>\n<p>\u00c9 o valor previsto em preg\u00e3o eletr\u00f4nico, por meio de registro de pre\u00e7os, do DER\/DF para contrata\u00e7\u00e3o de empresa para loca\u00e7\u00e3o de pain\u00e9is de mensagens vari\u00e1veis, m\u00f3veis e fixos, com sistema remoto de controle.<\/p>\n<h3><strong>Aliado forte<\/strong><\/h3>\n<p>No primeiro mandato, a deputada Fl\u00e1via Arruda (PR\/DF) conseguiu espa\u00e7o na C\u00e2mara gra\u00e7as \u00e0 ajuda de um amigo e aliado pol\u00edtico, o presidente da Casa, Rodrigo Maia (DEM\/RJ), que a conheceu durante os tempos de primeira-dama do DF, ao lado de Jos\u00e9 Roberto Arruda.<\/p>\n<h3><strong>Mesma causa<\/strong><\/h3>\n<p>O deputado distrital F\u00e1bio F\u00e9lix (PSol) n\u00e3o perde um evento ligado \u00e0 pauta LGBT. Na \u00faltima quinta-feira, ele acompanhou o julgamento no Supremo Tribunal Federal (STF) sobre a criminaliza\u00e7\u00e3o da homofobia ao lado da cantora Daniela Mercury e de sua mulher, Malu Ver\u00e7osa. A artista baiana justificou a presen\u00e7a em plen\u00e1rio: \u201cAo olharem para n\u00f3s, os ministros estar\u00e3o vendo o amor e estar\u00e3o vendo uma fam\u00edlia\u201d. A maioria da Corte j\u00e1 votou a favor da causa.<\/p>\n<h3><strong>Pauta dos empres\u00e1rios<\/strong><\/h3>\n<p>Na presen\u00e7a de empres\u00e1rios, o presidente da Federa\u00e7\u00e3o das Ind\u00fastrias do Distrito Federal (Fibra), Jamal Jorge Bittar (foto), entregar\u00e1 ao presidente da C\u00e2mara Legislativa, deputado Rafael Prudente, e ao governador Ibaneis Rocha a 17\u00aa Agenda Legislativa da Ind\u00fastria do DF, uma pauta de demandas do setor. A cerim\u00f4nia ser\u00e1 quinta-feira, dia 30. Todos os parlamentares, distritais e federais, foram convidados. Ser\u00e1 a primeira visita de Ibaneis \u00e0 Fibra desde que assumiu o Pal\u00e1cio do Buriti.<\/p>\n<h3>\n<strong>Bras\u00edlia exposta em Londres<\/strong><\/h3>\n<p>A exposi\u00e7\u00e3o Bras\u00edlia \u2014 Da utopia \u00e0 capital, que rodou algumas das principais capitais do mundo com a hist\u00f3ria da cidade, vai desembarcar em Londres. A curadora da mostra, Danielle Athayde, se reuniu ontem com o governador Ibaneis Rocha e obteve do chefe do Executivo o compromisso de apoiar a empreitada. O custo de cerca de R$ 350 mil deve ser pago com emendas de parlamentares da C\u00e2mara Legislativa. O governo far\u00e1 a articula\u00e7\u00e3o com os distritais para obter os recursos. O acervo conta com mais de 400 obras passou por Moscou no ano passado, durante a Copa do Mundo, atraindo 11 mil visitantes.<\/p>\n<h3><strong>Interesse no Terceiro Setor<\/strong><\/h3>\n<p>Mulher do ministro da Justi\u00e7a e Seguran\u00e7a P\u00fablica, a advogada Rosangela Wolff Moro n\u00e3o \u00e9 vista nos eventos sociais da Corte brasiliense. Mas \u00e9 presen\u00e7a em compromissos jur\u00eddicos, como no lan\u00e7amento do 10\u00ba volume da s\u00e9rie \u201cTerceiro Setor e Tributa\u00e7\u00e3o\u201d, lan\u00e7ado na \u00faltima quarta-feira no Carpe Diem. A obra \u00e9 um compilado de textos sobre o tema, sob a coordena\u00e7\u00e3o do procurador de Justi\u00e7a Jos\u00e9 Eduardo Sabo Paes. \u201cLeitura obrigat\u00f3ria para o terceiro setor\u201d, disse a advogada que atua na \u00e1rea, em postagem nas redes sociais.<\/p>\n<h3><strong>Aposta de mobiliza\u00e7\u00e3o fria<\/strong><\/h3>\n<p>A manifesta\u00e7\u00e3o de amanh\u00e3 em defesa do governo vai bombar? \u201cBolsonaro tem uma milit\u00e2ncia forte, mas acredito que a manifesta\u00e7\u00e3o ser\u00e1 menor. A mobiliza\u00e7\u00e3o, para acontecer, precisa de um fato, uma dor comum, com uma mensagem \u00fanica e um p\u00fablico espec\u00edfico, minimamente organizado e com lideran\u00e7as identificadas. A oposi\u00e7\u00e3o conseguiu unir esses elementos na defesa do or\u00e7amento da Educa\u00e7\u00e3o. O chamamento para o dia 26 ainda n\u00e3o deixou esses elementos claros e dividiu as for\u00e7as de lideran\u00e7as. Muitas delas n\u00e3o t\u00eam interesse no desgaste com o Congresso\u201d, afirma Fabr\u00edcio Moser, especialista em Mobiliza\u00e7\u00e3o Pol\u00edtica. Moser trabalha h\u00e1 mais de 20 anos na \u00e1rea e coordenou a equipe de mobiliza\u00e7\u00e3o da campanha do tucano Geraldo Alckmin \u00e0 Presid\u00eancia.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Tribunal de Contas do DF abriu prazo de 15 dias para a Secretaria de Sa\u00fade se manifestar sobre o aumento do n\u00famero de casos de dengue no DF. Os conselheiros pediram que a pasta apresente esclarecimentos e encaminhe c\u00f3pia de documentos que respaldem essas informa\u00e7\u00f5es. A decis\u00e3o foi tomada com base em representa\u00e7\u00e3o do [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":15463,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"wpb_read_more":[],"footnotes":""},"categories":[234],"tags":[1807,1806,1805,389,1346,138],"class_list":["post-15462","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cb-poder","tag-acoes-contra-a-dengue","tag-campanha-contra-a-dengue","tag-correio-braziliense","tag-dengue","tag-eixo-capital","tag-saude"],"_links":{"self":[{"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/posts\/15462","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/comments?post=15462"}],"version-history":[{"count":1,"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/posts\/15462\/revisions"}],"predecessor-version":[{"id":15464,"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/posts\/15462\/revisions\/15464"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/media\/15463"}],"wp:attachment":[{"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/media?parent=15462"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/categories?post=15462"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/tags?post=15462"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}