{"id":15616,"date":"2019-06-11T07:58:33","date_gmt":"2019-06-11T10:58:33","guid":{"rendered":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/?p=15616"},"modified":"2019-06-11T09:44:51","modified_gmt":"2019-06-11T12:44:51","slug":"varios-procuradores-inclusive-janot-foram-hackeados","status":"publish","type":"post","link":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/varios-procuradores-inclusive-janot-foram-hackeados\/","title":{"rendered":"V\u00e1rios procuradores, inclusive Janot, foram hackeados"},"content":{"rendered":"<h6><strong>Coluna Eixo Capital\/Por Ana Maria Campos<\/strong><\/h6>\n<p>H\u00e1 semanas, procuradores envolvidos em investiga\u00e7\u00f5es importantes sabiam que seus telefones haviam sido hackeados.<\/p>\n<p>&nbsp;<\/p>\n<p>Pelo menos quatro integrantes do Minist\u00e9rio P\u00fablico esperavam o que estava por vir, entre os quais, o ex-procurador-geral da Rep\u00fablica Rodrigo Janot, que chegou a denunciar o epis\u00f3dio pelas redes sociais.<\/p>\n<p>&nbsp;<\/p>\n<p>Em 24 de abril, ele postou: \u201cAmigos, meu telefone foi clonado ou hackeado. Hacker muito proativo. J\u00e1 tentou acessar minha conta Apple, Telegram, conta banc\u00e1ria e por a\u00ed vai. Tem muito interesse em meus bancos de informa\u00e7\u00e3o. Vamos enfrentar. Temos algumas desconfian\u00e7as\u201d.<\/p>\n<p>&nbsp;<\/p>\n<p>O Telegram, apontado como mais seguro do que o WhatsApp, \u00e9 o grande alvo. Por isso, h\u00e1 quem acredite numa atua\u00e7\u00e3o de tecnologia fora do pa\u00eds, da China ou R\u00fassia. Mas n\u00e3o se descartam tamb\u00e9m m\u00e9todos mais rudimentares.<\/p>\n<p>&nbsp;<\/p>\n<p>Independentemente do conte\u00fado das conversas, que n\u00e3o tratam de corrup\u00e7\u00e3o, desvio de recursos, nem de benef\u00edcios privados, \u00e9 surreal imaginar que di\u00e1logos particulares podem ser expostos dessa forma. Ousados, hackers chegaram a mostrar a um dos procuradores que tinham invadido, exibindo um print da tela.<\/p>\n<h2><strong>Presidente da OAB\/DF aponta conluio<\/strong><\/h2>\n<p>O presidente da OAB\/DF, D\u00e9lio Lins e Silva J\u00fanior, participou ontem da reuni\u00e3o em que o Conselho Federal da entidade decidiu recomendar o afastamento do ministro da Justi\u00e7a e Seguran\u00e7a P\u00fablica, S\u00e9rgio Moro, e do procurador Deltan Dallagnol da coordena\u00e7\u00e3o da for\u00e7a-tarefa da Lava-Jato em Curitiba.<\/p>\n<p>&nbsp;<\/p>\n<p>Criminalista, D\u00e9lio afirma que os advogados sempre reclamaram de um suposto \u201cconluio\u201d entre integrantes do Minist\u00e9rio P\u00fablico e ju\u00edzes. \u201cSempre suspeitamos dessas medidas combinadas. Isso n\u00e3o acontece n\u00e3o s\u00f3 na Lava-Jato. Mas nunca foi t\u00e3o escancarado\u201d, aponta.<\/p>\n<h2><strong>Em defesa de Moro<\/strong><\/h2>\n<p>O secret\u00e1rio executivo da Secretaria de Seguran\u00e7a P\u00fablica do DF, Alessandro Moretti, que \u00e9 delegado da Pol\u00edcia Federal, foi uma das vozes de apoio ao ministro da Justi\u00e7a e Seguran\u00e7a P\u00fablica, S\u00e9rgio Moro, e ao procurador Deltan Dallagnol, coordenador da for\u00e7a-tarefa da Lava-Jato em Curitiba.<\/p>\n<p>&nbsp;<\/p>\n<p>Pelo Twitter, ele postou: \u201cNunca foi f\u00e1cil combater o crime organizado. Retalia\u00e7\u00f5es sempre v\u00eam e o crime n\u00e3o respeita qualquer regra. J\u00e1 vivemos isso nas grandes opera\u00e7\u00f5es da PF. Na Lava-Jato, tudo \u00e9 superlativo. O jogo ser\u00e1 baixo\u201d.<\/p>\n<h2><strong>Ex-s\u00f3cio<\/strong><\/h2>\n<p>Nomeado pelo governador Ibaneis Rocha para a fun\u00e7\u00e3o de chefe da Unidade de Pessoal da Assessoria Jur\u00eddico Legislativa, do Gabinete da Secretaria de Fazenda, Planejamento, Or\u00e7amento e Gest\u00e3o, Odasir Piacini Neto n\u00e3o \u00e9 mais s\u00f3cio de seu escrit\u00f3rio de advocacia.<\/p>\n<h2><strong>Novo procurador-geral do MP de Contas<\/strong><\/h2>\n<p>O governador Ibaneis Rocha nomeou o procurador Marcos Felipe Pinheiro Lima para o cargo de procurador-geral do Minist\u00e9rio P\u00fablico junto ao Tribunal de Contas do DF.<\/p>\n<p>&nbsp;<\/p>\n<p>Ele vai suceder a procuradora <a href=\"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/procuradora-do-mp-de-contas-do-df-critica-falta-de-autonomia-financeira\/\">Cl\u00e1udia Fernanda de Oliveira Pereira<\/a>, que deixa o cargo depois de quatro anos de mandato. Entre as mais recentes representa\u00e7\u00f5es assinadas por Marcos Felipe, est\u00e1 a que pede a suspens\u00e3o dos efeitos do cancelamento do edital do Fundo de Apoio \u00e0 Cultura (FAP).<\/p>\n<h2><strong>Rollemberg: \u201cA CEB no meu governo foi considerada exemplo\u201d<\/strong><\/h2>\n<p>O ex-governador Rodrigo Rollemberg (PSB) sustenta que, em sua gest\u00e3o, a CEB foi considerada exemplo de gest\u00e3o pela Ag\u00eancia Nacional de Energia El\u00e9trica (Aneel). \u201cSubiu mais de 20 posi\u00e7\u00f5es no ranking de qualidade de servi\u00e7o\u201d, afirma.<\/p>\n<p>&nbsp;<\/p>\n<p>Segundo Rollemberg, a venda das participa\u00e7\u00f5es nas subsidi\u00e1rias de gera\u00e7\u00e3o de energia ajudaria no abatimento da d\u00edvida da holding e ainda sobraria para investimentos. \u201cO governo (atual) est\u00e1 sendo desonesto intelectualmente, pois mentem e n\u00e3o sabem fazer contas. Nunca houve aporte na gest\u00e3o Rollemberg\u201d, diz.<\/p>\n<h2><strong>Contingenciamento na educa\u00e7\u00e3o<\/strong><\/h2>\n<p>Em tempos de cortes de recursos nas universidades brasileiras, o DF n\u00e3o fica atr\u00e1s quando se trata da execu\u00e7\u00e3o or\u00e7ament\u00e1ria do Programa de Descentraliza\u00e7\u00e3o Administrativa e Financeira, o PDAF.<\/p>\n<p>&nbsp;<\/p>\n<p>Apesar de uma dota\u00e7\u00e3o autorizada de R$ 221,4 milh\u00f5es entre recursos institucionais (R$ 118 milh\u00f5es) e de emendas parlamentares (R$ 102 milh\u00f5es) para a melhoria das escolas p\u00fablicas do DF, at\u00e9 o dia 5 de junho, s\u00f3 foram empenhados R$ 63,7 milh\u00f5es, sendo apenas R$ 1 milh\u00e3o de emendas parlamentares.<\/p>\n<p>&nbsp;<\/p>\n<p>Ou seja, somente 28,7% dos recursos autorizados para a Educa\u00e7\u00e3o foram empenhados este ano. Os dados fazem parte de um levantamento do gabinete do deputado distrital Leandro Grass (Rede).<\/p>\n<h2><strong>C\u00e2mara gourmet<\/strong><\/h2>\n<p>A C\u00e2mara Legislativa vai construir um restaurante em suas depend\u00eancias. A Casa abriu licita\u00e7\u00e3o para contratar empresa especializada no neg\u00f3cio e tamb\u00e9m na implanta\u00e7\u00e3o de um abrigo de ambul\u00e2ncia e uma pra\u00e7a do servidor. O custo estimado do neg\u00f3cio \u00e9 R$ 2.122.321,18.<\/p>\n<h2><strong>S\u00f3 papos<\/strong><\/h2>\n<blockquote><p>\u201cH\u00e1 anos, muitos de n\u00f3s alertamos que a inconstitucionalidade democr\u00e1tica poderia se afogar na promiscuidade entre pol\u00edticos, ju\u00edzes, empres\u00e1rios, policiais. A Lava-Jato, que desvendou e coibiu esta promuscuidade, parece ter ca\u00eddo nela tamb\u00e9m\u201d<\/p><\/blockquote>\n<p style=\"text-align: right\"><strong>Ex-senador Cristovam Buarque (Cidadania\/DF)<\/strong><\/p>\n<blockquote><p>\u201cA atua\u00e7\u00e3o s\u00f3rdida daqueles que vierem a se aproveitar da a\u00e7\u00e3o do &#8216;hacker&#8217; para deturpar fatos, apresentar fatos retirados de contexto e falsificar integral ou parcialmente informa\u00e7\u00f5es atende interesses inconfess\u00e1veis de criminosos atingidos pela Lava-Jato\u201d<\/p><\/blockquote>\n<p style=\"text-align: right\"><strong>Procurador Deltan Dallagnol, coordenador da for\u00e7a-tarefa da Lava-Jato em Curitiba, reproduzindo nota assinada pelo grupo<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Coluna Eixo Capital\/Por Ana Maria Campos H\u00e1 semanas, procuradores envolvidos em investiga\u00e7\u00f5es importantes sabiam que seus telefones haviam sido hackeados. &nbsp; Pelo menos quatro integrantes do Minist\u00e9rio P\u00fablico esperavam o que estava por vir, entre os quais, o ex-procurador-geral da Rep\u00fablica Rodrigo Janot, que chegou a denunciar o epis\u00f3dio pelas redes sociais. &nbsp; Em 24 [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":15617,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"wpb_read_more":[],"footnotes":""},"categories":[234],"tags":[],"class_list":["post-15616","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cb-poder"],"_links":{"self":[{"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/posts\/15616","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/comments?post=15616"}],"version-history":[{"count":3,"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/posts\/15616\/revisions"}],"predecessor-version":[{"id":15622,"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/posts\/15616\/revisions\/15622"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/media\/15617"}],"wp:attachment":[{"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/media?parent=15616"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/categories?post=15616"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/tags?post=15616"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}