{"id":15689,"date":"2019-06-18T07:37:48","date_gmt":"2019-06-18T10:37:48","guid":{"rendered":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/?p=15689"},"modified":"2019-06-18T07:37:48","modified_gmt":"2019-06-18T10:37:48","slug":"em-caso-de-suspeicao-de-moro-lava-jato-pode-afundar","status":"publish","type":"post","link":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/em-caso-de-suspeicao-de-moro-lava-jato-pode-afundar\/","title":{"rendered":"Em caso de suspei\u00e7\u00e3o de Moro, Lava-Jato pode afundar"},"content":{"rendered":"<h6><strong>Coluna Eixo Capital\/Por Ana Maria Campos<\/strong><\/h6>\n<p>Procuradores da Rep\u00fablica avaliam que o maior rombo no casco da Lava-Jato pode sair do Supremo Tribunal Federal (STF) e n\u00e3o do Congresso. Se a 2\u00aa Turma declarar a suspei\u00e7\u00e3o do ex-juiz S\u00e9rgio Moro no processo do tr\u00edplex, a opera\u00e7\u00e3o poder\u00e1 afundar. Ser\u00e1 um precedente para outros r\u00e9us questionarem a instru\u00e7\u00e3o de seus processos na 13\u00aa Vara Criminal de Curitiba.<\/p>\n<h2><strong>Absolvi\u00e7\u00e3o no DF<\/strong><\/h2>\n<p>Na Opera\u00e7\u00e3o Vit\u00f3ria de Pirro, desdobramento da Lava-Jato que levou \u00e0 condena\u00e7\u00e3o do ex-senador Gim Argello, o ent\u00e3o juiz S\u00e9rgio Moro deu demonstra\u00e7\u00f5es de que n\u00e3o concordava com todas as acusa\u00e7\u00f5es da for\u00e7a-tarefa de Curitiba. Na den\u00fancia, o Minist\u00e9rio P\u00fablico Federal pediu a condena\u00e7\u00e3o de Val\u00e9rio Neves, Paulo Roxo e do filho do ex-parlamentar, Jorge Argello J\u00fanior, mas Moro os absolveu por entender que n\u00e3o estavam envolvidos na trama. Gim, <a href=\"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/beneficiado-por-indulto-gim-deixa-a-prisao\/\">agora perdoado por indulto<\/a>, foi acusado de receber dinheiro de empreiteiras contratadas pela Petrobras, em troca de apoio na CPI do Congresso que tratou do assunto.<\/p>\n<h2><strong>Estrat\u00e9gia se repete<\/strong><\/h2>\n<p>A tentativa de apontar suspei\u00e7\u00e3o de acusadores e ju\u00edzes \u00e9 uma estrat\u00e9gia que se repete. Na Opera\u00e7\u00e3o Caixa de Pandora, advogados representaram ao Conselho Nacional do Minist\u00e9rio P\u00fablico (CNMP) e ao Conselho Nacional de Justi\u00e7a (CNJ) contra promotores e o juiz que tiveram um di\u00e1logo captado pelo gravador da sala de audi\u00eancias do Tribunal de Justi\u00e7a do DF. Eles conversavam sobre a pertin\u00eancia da per\u00edcia no gravador usado por Durval Barbosa, sob monitoramento da Pol\u00edcia Federal, para registrar conversas com integrantes do governo. Os casos foram arquivados pelos dois conselhos.<\/p>\n<h2>\n<strong>Apoio moral<\/strong><\/h2>\n<p>A deputada Bia Kicis (PSL-DF) promete acompanhar na Comiss\u00e3o de Constitui\u00e7\u00e3o e Justi\u00e7a (CCJ) do Senado a oitiva do ministro da Justi\u00e7a e Seguran\u00e7a P\u00fablica, S\u00e9rgio Moro.<\/p>\n<h2>\n<strong>Sil\u00eancio<\/strong><\/h2>\n<p>Algumas personalidades que poderiam, mas ainda n\u00e3o abriram a boca publicamente sobre o epis\u00f3dio do vazamento de conversas de chats provavelmente invadidos por hackers: o ex-presidente do STF Joaquim Barbosa, relator do processo do mensal\u00e3o; o ex-procurador-geral da Rep\u00fablica Rodrigo Janot, que durante quatro anos atuou como coordenador da Lava-Jato nos processos do STF.<\/p>\n<h2><strong>Agora, sim<\/strong><\/h2>\n<p>O empres\u00e1rio Jos\u00e9 Humberto Pires finalmente aceitou o convite para assumir oficialmente a Secretaria de Governo na equipe do governador Ibaneis Rocha. O ato de nomea\u00e7\u00e3o deve ser publicado no Di\u00e1rio Oficial do DF nos pr\u00f3ximos dias, numa reestrutura\u00e7\u00e3o da Casa Civil, que ser\u00e1 comandada pelo advogado Valdet\u00e1rio Andrade Monteiro.<\/p>\n<p>Desculpa atr\u00e1s de desculpa<\/p>\n<p>Para o ex-secret\u00e1rio da Receita Federal Everardo Maciel, desde 1998, sempre se encontra um motivo para o Congresso n\u00e3o votar a reforma da Previd\u00eancia. Ent\u00e3o n\u00e3o ser\u00e1 novidade se a crise de Moro levar a esse desfecho agora.<\/p>\n<h2><strong>A pergunta que n\u00e3o quer calar\u2026.<\/strong><\/h2>\n<p>S\u00e9rgio Moro ficou menor como ministro da Justi\u00e7a e Seguran\u00e7a P\u00fablica do que era como juiz da Lava-Jato?<\/p>\n<h2>\n<em><strong>S\u00f3 papos<\/strong><\/em><\/h2>\n<blockquote><p>\n\u201cA crise \u00e9 artificial, uma farsa, mas uma mentira repetida mil vezes pode se tornar uma verdade na mente dos brasileiros. Estamos enfrentando um tipo de campanha muito bem orquestrada\u201d<\/p><\/blockquote>\n<p style=\"text-align: right\"><strong>Carlos Fernando dos Santos Lima, procurador regional da Rep\u00fablica aposentado e ex-integrante da for\u00e7a-tarefa da Lava-Jato em Curitiba, em entrevista ao Estad\u00e3o<\/strong><\/p>\n<blockquote><p>\u201cAs den\u00fancias do The Intercept colocam em jogo a credibilidade n\u00e3o somente de S\u00e9rgio Moro, mas tamb\u00e9m de toda a Opera\u00e7\u00e3o Lava-Jato. Todo material divulgado at\u00e9 agora refor\u00e7a que a pris\u00e3o de Lula \u00e9 pol\u00edtica\u201d<\/p><\/blockquote>\n<p style=\"text-align: right\"><strong>Senador Humberto Costa (PT-PE), integrante da CCJ do Senado, onde o juiz S\u00e9rgio Moro vai falar sobre o conte\u00fado das conversas que manteve com procuradores da for\u00e7a-tarefa da Lava-Jato<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Coluna Eixo Capital\/Por Ana Maria Campos Procuradores da Rep\u00fablica avaliam que o maior rombo no casco da Lava-Jato pode sair do Supremo Tribunal Federal (STF) e n\u00e3o do Congresso. Se a 2\u00aa Turma declarar a suspei\u00e7\u00e3o do ex-juiz S\u00e9rgio Moro no processo do tr\u00edplex, a opera\u00e7\u00e3o poder\u00e1 afundar. Ser\u00e1 um precedente para outros r\u00e9us questionarem [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":15690,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"wpb_read_more":[],"footnotes":""},"categories":[234],"tags":[783,61,1765,149],"class_list":["post-15689","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cb-poder","tag-gim-argello","tag-lava-jato","tag-sergio-moro","tag-stf"],"_links":{"self":[{"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/posts\/15689","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/comments?post=15689"}],"version-history":[{"count":1,"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/posts\/15689\/revisions"}],"predecessor-version":[{"id":15691,"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/posts\/15689\/revisions\/15691"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/media\/15690"}],"wp:attachment":[{"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/media?parent=15689"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/categories?post=15689"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/tags?post=15689"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}