{"id":15752,"date":"2019-06-25T15:02:00","date_gmt":"2019-06-25T18:02:00","guid":{"rendered":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/?p=15752"},"modified":"2019-06-25T16:21:04","modified_gmt":"2019-06-25T19:21:04","slug":"distritais-adiam-votacao-do-projeto-que-cria-regiao-administrativa-do-sol-nascente-e-do-por-do-sol","status":"publish","type":"post","link":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/distritais-adiam-votacao-do-projeto-que-cria-regiao-administrativa-do-sol-nascente-e-do-por-do-sol\/","title":{"rendered":"Distritais adiam vota\u00e7\u00e3o do projeto que cria regi\u00e3o administrativa do Sol Nascente e do P\u00f4r do Sol"},"content":{"rendered":"<p><strong>ISA STACCIARINI<\/strong><\/p>\n<p>O Legislativo local adiou para 13 e 14 de agosto a an\u00e1lise do projeto de lei que cria a regi\u00e3o administrativa do Setor Habitacional Sol Nascente e do P\u00f4r do Sol. A delibera\u00e7\u00e3o ocorrer\u00e1 nas sess\u00f5es da C\u00e2mara Mais Perto de Voc\u00ea. &#8220;Vamos levar essa vota\u00e7\u00e3o importante para ser realizada perto da comunidade com a participa\u00e7\u00e3o dos moradores&#8221;, argumentou o presidente da Casa, Rafael Prudente (MDB).<\/p>\n<p>A vota\u00e7\u00e3o da proposta estava prevista para esta ter\u00e7a-feira (25\/6), o que levou dezenas de moradores da regi\u00e3o \u00e0 C\u00e2mara Legislativa no in\u00edcio da tarde. Aproximadamente 200 pessoas aguardavam para entrar na Casa. Entre eles, estavam l\u00edderes comunit\u00e1rios e prefeitos de quadras. O grupo levou faixas, cartazes, fogos de artif\u00edcio e trio el\u00e9trico. Com gritos, pedia a institui\u00e7\u00e3o da regi\u00e3o administrativa e melhorias nas \u00e1reas de educa\u00e7\u00e3o, sa\u00fade e seguran\u00e7a, al\u00e9m de cobrar a presen\u00e7a de parlamentares com falas de &#8220;cad\u00ea os deputados?&#8221;.<\/p>\n<p>Um dos representantes do movimento, Firmino Jos\u00e9 Alves, 45 anos, ressaltou a necessidade de servi\u00e7os p\u00fablicos na regi\u00e3o. &#8220;Queremos dignidade para uma cidade que tem 120 mil habitantes e acabar com o mito que se criou de ser a maior favela da Am\u00e9rica Latina&#8221;, refor\u00e7ou.<\/p>\n<p>Ele ainda enfatizou que a proposi\u00e7\u00e3o trata-se de uma promessa de campanha do governador Ibaneis Rocha (MDB). &#8220;J\u00e1 s\u00e3o seis meses de governo e lutamos para a consolida\u00e7\u00e3o da nossa cidade como regi\u00e3o administrativa&#8221;, disse.<\/p>\n<p>Por volta das 13h, os moradores almo\u00e7avam pratos de galinhada, distribu\u00eddas em marmitas de isopor. Policiais acompanhavam a movimenta\u00e7\u00e3o em uma fila, em frente \u00e0 sede do legislativo local.<\/p>\n<p>\u00c0s 13h20, o deputado Jorge Viana (Podemos) saiu da Casa e se encontrou com os moradores. Ele tirou fotos com os manifestantes e almo\u00e7ou uma das marmitas entregues pelos ativistas. O parlamentar disse ser favor\u00e1vel a cria\u00e7\u00e3o da regi\u00e3o administrativa. &#8220;Sou um apoiador do movimento e um voto favor\u00e1vel. Venho da for\u00e7a popular e sei que quando a popula\u00e7\u00e3o se une pedindo apoio para uma causa os deputados atendem&#8221;, destacou.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>ISA STACCIARINI O Legislativo local adiou para 13 e 14 de agosto a an\u00e1lise do projeto de lei que cria a regi\u00e3o administrativa do Setor Habitacional Sol Nascente e do P\u00f4r do Sol. A delibera\u00e7\u00e3o ocorrer\u00e1 nas sess\u00f5es da C\u00e2mara Mais Perto de Voc\u00ea. &#8220;Vamos levar essa vota\u00e7\u00e3o importante para ser realizada perto da comunidade [&hellip;]<\/p>\n","protected":false},"author":90,"featured_media":15753,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"wpb_read_more":[],"footnotes":""},"categories":[234],"tags":[70,917,1466,136,1674],"class_list":["post-15752","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cb-poder","tag-camara-legislativa","tag-ibaneis-rocha","tag-por-do-sol","tag-projeto","tag-sol-nascente"],"_links":{"self":[{"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/posts\/15752","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/users\/90"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/comments?post=15752"}],"version-history":[{"count":4,"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/posts\/15752\/revisions"}],"predecessor-version":[{"id":15763,"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/posts\/15752\/revisions\/15763"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/media\/15753"}],"wp:attachment":[{"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/media?parent=15752"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/categories?post=15752"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/tags?post=15752"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}