{"id":15813,"date":"2019-06-27T08:13:46","date_gmt":"2019-06-27T11:13:46","guid":{"rendered":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/?p=15813"},"modified":"2019-06-27T08:13:46","modified_gmt":"2019-06-27T11:13:46","slug":"aprovacao-do-projeto-sobre-pagamento-de-pecunias-e-vitoria-do-gdf","status":"publish","type":"post","link":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/aprovacao-do-projeto-sobre-pagamento-de-pecunias-e-vitoria-do-gdf\/","title":{"rendered":"Aprova\u00e7\u00e3o do projeto sobre pagamento de pec\u00fanias \u00e9 vit\u00f3ria do GDF"},"content":{"rendered":"<h6><strong>Coluna Eixo Capital\/Por Ana Maria Campos<\/strong><\/h6>\n<p>O l\u00edder do governo na C\u00e2mara Legislativa, Cl\u00e1udio Abrantes (PDT), estava animado ontem pelo que considerou uma miss\u00e3o cumprida. O Executivo fechou um acordo para aprovar o projeto que trata de licen\u00e7a-pr\u00eamio e pagamento de pec\u00fanias. A mat\u00e9ria foi aprovada com 24 votos no primeiro turno e 23, em segundo turno, com uma aus\u00eancia. Al\u00e9m disso, Ibaneis conseguiu aprovar algo que dois governadores anteriores n\u00e3o conseguiram.<\/p>\n<h2><strong>Mais uma emerg\u00eancia<\/strong><\/h2>\n<p>No Brasil, \u00e9 sempre assim. Reforma sem licita\u00e7\u00e3o, por contrato emergencial, sob o argumento de risco iminente \u00e0 popula\u00e7\u00e3o. Quem vai contestar depois de um epis\u00f3dio como o do ano passado quando caiu um viaduto?<\/p>\n<h2><strong>Fora da pauta<\/strong><\/h2>\n<p>Na semana em que projetos de distritais s\u00e3o votados em acordo, a Mesa Diretora da C\u00e2mara retirou de pauta projeto de resolu\u00e7\u00e3o de autoria do deputado Leandro Grass (Rede) que reconhece as assinaturas digitais em projetos de iniciativa popular. Trata-se de uma forma de facilitar a coleta de apoios a mat\u00e9rias de interesse da sociedade.<\/p>\n<h2><strong>Carreira militar<\/strong><\/h2>\n<p>Caiu na rede: o sargento do Ex\u00e9rcito preso na Espanha em conex\u00e3o a caminho do Jap\u00e3o com 39kg de coca\u00edna escolheu a carreira militar.<\/p>\n<h2><strong>S\u00f3 papos<\/strong><\/h2>\n<blockquote><p>\u201cSe fosse deputado ou senador, S\u00e9rgio Moro j\u00e1 estaria cassado ou preso\u201d<\/p><\/blockquote>\n<p style=\"text-align: right\"><strong>Presidente do Senado, Davi Alcolumbre (DEM-AP)<\/strong><\/p>\n<blockquote><p>\n\u201cInteressante lembrar que o parlamentar que fez a afirma\u00e7\u00e3o enfrenta investiga\u00e7\u00f5es por atos delituosos ao patrim\u00f4nio p\u00fablico, correndo risco de cassa\u00e7\u00e3o\u201d<\/p><\/blockquote>\n<p style=\"text-align: right\"><strong>Roberto Livianu, promotor de Justi\u00e7a de S\u00e3o Paulo<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Coluna Eixo Capital\/Por Ana Maria Campos O l\u00edder do governo na C\u00e2mara Legislativa, Cl\u00e1udio Abrantes (PDT), estava animado ontem pelo que considerou uma miss\u00e3o cumprida. O Executivo fechou um acordo para aprovar o projeto que trata de licen\u00e7a-pr\u00eamio e pagamento de pec\u00fanias. A mat\u00e9ria foi aprovada com 24 votos no primeiro turno e 23, em [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":15814,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"wpb_read_more":[],"footnotes":""},"categories":[234],"tags":[],"class_list":["post-15813","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cb-poder"],"_links":{"self":[{"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/posts\/15813","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/comments?post=15813"}],"version-history":[{"count":1,"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/posts\/15813\/revisions"}],"predecessor-version":[{"id":15815,"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/posts\/15813\/revisions\/15815"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/media\/15814"}],"wp:attachment":[{"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/media?parent=15813"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/categories?post=15813"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/tags?post=15813"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}