{"id":15946,"date":"2019-07-12T14:52:07","date_gmt":"2019-07-12T17:52:07","guid":{"rendered":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/?p=15946"},"modified":"2019-07-12T16:00:52","modified_gmt":"2019-07-12T19:00:52","slug":"mpdft-cumpre-mandado-de-busca-e-apreensao-em-escritorio-parlamentar-de-roberio-negreiros","status":"publish","type":"post","link":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/mpdft-cumpre-mandado-de-busca-e-apreensao-em-escritorio-parlamentar-de-roberio-negreiros\/","title":{"rendered":"MPDFT cumpre mandado de busca e apreens\u00e3o em escrit\u00f3rio parlamentar de Rob\u00e9rio Negreiros"},"content":{"rendered":"<p><span style=\"font-weight: 400\">O Minist\u00e9rio P\u00fablico do Distrito Federal e Territ\u00f3rios (MPDFT) deflagrou, nesta sexta-feira (17\/07), a 2\u00aa fase da Opera\u00e7\u00e3o Absentia (aus\u00eancia em latim). Os investigadores cumpriram mandado de busca e apreens\u00e3o no escrit\u00f3rio parlamentar do distrital Rob\u00e9rio Negreiros (PSD), localizado no Edif\u00edcio Ven\u00e2ncio III, no Conic. Custeado com recursos da verba indenizat\u00f3ria, paga pela C\u00e2mara Legislativa, o im\u00f3vel \u00e9 alugado de um advogado, pelo valor mensal de R$ 2.366,00, com contrato firmado at\u00e9 dezembro.<\/span><\/p>\n<p>&nbsp;<\/p>\n<blockquote><p><span style=\"font-weight: 400\">A Opera\u00e7\u00e3o apura a falsifica\u00e7\u00e3o de mais de 50 folhas de ponto pelo deputado na C\u00e2mara Legislativa, com a ajuda do servidor Arl\u00e9cio Alexandre Gazal, no per\u00edodo compreendido entre 2011 e 2019. Na 1\u00aa fase, realizada na \u00faltima semana, o MPDFT e a Pol\u00edcia Civil recolheram <\/span><span style=\"font-weight: 400\">c\u00f3pias de documentos relacionados \u00e0 homologa\u00e7\u00e3o de atestados m\u00e9dicos, \u00e0 folha de presen\u00e7a e \u00e0 verba indenizat\u00f3ria. Se confirmadas as suspeitas, os dois devem responder por peculato e falsidade ideol\u00f3gica.\u00a0<\/span><\/p><\/blockquote>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400\">As medidas est\u00e3o sob a responsabilidade da Procuradoria-geral de Justi\u00e7a do DF, uma vez que envolvem deputado distrital com foro no Conselho Especial do Tribunal de Justi\u00e7a do DF em caso de a\u00e7\u00f5es criminais. A investiga\u00e7\u00e3o est\u00e1 a cargo tamb\u00e9m do Grupo de Atua\u00e7\u00e3o Especial de Combate ao Crime Organizado (GAECO), com o apoio da Policia Civil do DF.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400\">Em nota, Rob\u00e9rio Negreiros reiterou que \u201cmant\u00e9m uma postura colaborativa com as investiga\u00e7\u00f5es e que est\u00e1\u00a0 \u00e0 disposi\u00e7\u00e3o para quaisquer novos esclarecimentos em qualquer inst\u00e2ncia\u201d. \u201cO questionamento sobre frequ\u00eancia\u00a0 dos senhores deputados da C\u00e2mara j\u00e1 foi aclarado pela Procuradoria Geral da casa e acatado, unanimemente, pela unanimidade da Mesa Diretora\u201d, argumentou.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Minist\u00e9rio P\u00fablico do Distrito Federal e Territ\u00f3rios (MPDFT) deflagrou, nesta sexta-feira (17\/07), a 2\u00aa fase da Opera\u00e7\u00e3o Absentia (aus\u00eancia em latim). Os investigadores cumpriram mandado de busca e apreens\u00e3o no escrit\u00f3rio parlamentar do distrital Rob\u00e9rio Negreiros (PSD), localizado no Edif\u00edcio Ven\u00e2ncio III, no Conic. Custeado com recursos da verba indenizat\u00f3ria, paga pela C\u00e2mara Legislativa, [&hellip;]<\/p>\n","protected":false},"author":90,"featured_media":2526,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"wpb_read_more":[],"footnotes":""},"categories":[234],"tags":[1883,1884,498,102],"class_list":["post-15946","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cb-poder","tag-absentia","tag-escritorio","tag-mpdft","tag-policia-civil"],"_links":{"self":[{"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/posts\/15946","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/users\/90"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/comments?post=15946"}],"version-history":[{"count":3,"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/posts\/15946\/revisions"}],"predecessor-version":[{"id":15949,"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/posts\/15946\/revisions\/15949"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/media\/2526"}],"wp:attachment":[{"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/media?parent=15946"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/categories?post=15946"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/tags?post=15946"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}