{"id":16044,"date":"2019-07-26T07:51:07","date_gmt":"2019-07-26T10:51:07","guid":{"rendered":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/?p=16044"},"modified":"2019-07-26T07:51:07","modified_gmt":"2019-07-26T10:51:07","slug":"distrital-explica-projetos-de-lei-relacionados-a-animais-domesticos","status":"publish","type":"post","link":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/distrital-explica-projetos-de-lei-relacionados-a-animais-domesticos\/","title":{"rendered":"Distrital explica projetos de lei relacionados a animais dom\u00e9sticos"},"content":{"rendered":"<h2><em><strong>\u00c0 QUEIMA-ROUPA<\/strong><\/em><\/h2>\n<p>Deputado distrital Daniel Donizet (PSDB)<\/p>\n<p><strong>O senhor \u00e9 autor de projetos de lei relacionados a animais dom\u00e9sticos e fez campanha com esse tema. Por que esse enfoque?<\/strong><\/p>\n<p>Encabecei essa bandeira porque, at\u00e9 ent\u00e3o, n\u00e3o vi nenhum outro parlamentar atuando nessa causa. Hoje v\u00e1rias fam\u00edlias t\u00eam, pelo menos, um animal de estima\u00e7\u00e3o. Percebo que nem todas possuem recursos suficientes para cuidar dos pets. Por isso a import\u00e2ncia de se investir no Hospital Veterin\u00e1rio e tamb\u00e9m de criar projetos que possam ajudar quem, por exemplo, n\u00e3o tem carro, mas precisa levar o animal para uma consulta. Por isso, a ideia do projeto de lei que autoriza a levar animais no transporte p\u00fablico do DF.<\/p>\n<p><strong>Acredita que o governador Ibaneis Rocha vai sancionar seu projeto que autoriza o transporte de animais de pequeno porte nos \u00f4nibus do DF?<\/strong><\/p>\n<p>Acredito que sim. O governador tamb\u00e9m apoia essa causa. Creio que a san\u00e7\u00e3o deve sair nos pr\u00f3ximos dias.<\/p>\n<p><strong>Como surgiu essa ideia?<\/strong><\/p>\n<p>Essa ideia surgiu porque tenho visitado v\u00e1rios abrigos, institui\u00e7\u00f5es ligadas \u00e0 causa animal e o Hospital Veterin\u00e1rio, al\u00e9m de as pessoas irem at\u00e9 meu gabinete e me procurarem com esse tipo de demanda. Estudei o assunto com minha equipe t\u00e9cnica e percebemos que era poss\u00edvel criar esse tipo de medida. Lembrando que o animal deve pesar, no m\u00e1ximo, at\u00e9 12 kg, n\u00e3o pode colocar em risco os demais passageiros, n\u00e3o pode ser pe\u00e7onhento ou feroz, deve estar em caixas apropriadas e n\u00e3o pode ser levado em hor\u00e1rio de pico. Na pr\u00e1tica essa lei vai atender c\u00e3es e gatos. As regulamenta\u00e7\u00f5es devem sair at\u00e9 30 dias depois da san\u00e7\u00e3o.<\/p>\n<p><strong>Por que inserir conte\u00fado sobre prote\u00e7\u00e3o animal no curr\u00edculo das escolas p\u00fablicas, como disp\u00f5e um dos seus projetos de lei?<\/strong><\/p>\n<p>A gente percebe muitos maus-tratos a animais. Esse tipo de situa\u00e7\u00e3o \u00e9 recorrente na imprensa e tamb\u00e9m nas den\u00fancias que n\u00f3s recebemos. \u00c9 importante debater esse assunto desde cedo com as crian\u00e7as nas escolas. Isso para que elas saibam o que s\u00e3o maus-tratos, evitem esse tipo de pr\u00e1tica e at\u00e9 saibam onde e como denunciar esses abusos.<\/p>\n<p><strong>Vai voltar para a administra\u00e7\u00e3o regional do Gama ou j\u00e1 deu seu trabalho como encerrado?<\/strong><\/p>\n<p>Acredito que, neste momento, posso contribuir mais na C\u00e2mara Legislativa. A Administra\u00e7\u00e3o do Gama est\u00e1 em boas m\u00e3os sob o comando do Jos\u00e9 Elias.<\/p>\n<p><strong>O senhor foi eleito com o discurso de apoio ao ent\u00e3o candidato Jair Bolsonaro. Qual a sua opini\u00e3o sobre o governo Bolsonaro?<\/strong><\/p>\n<p>Acho que o atual governo est\u00e1 trabalhando bem. \u00c9 a favor da reforma da Previd\u00eancia, tem investido em setores importantes como seguran\u00e7a e vem combatendo um grande mal que sempre prejudicou nossa pol\u00edtica, que \u00e9 a corrup\u00e7\u00e3o. Se mostra um presidente honesto, transparente e com disposi\u00e7\u00e3o para mudar o Brasil.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00c0 QUEIMA-ROUPA Deputado distrital Daniel Donizet (PSDB) O senhor \u00e9 autor de projetos de lei relacionados a animais dom\u00e9sticos e fez campanha com esse tema. Por que esse enfoque? Encabecei essa bandeira porque, at\u00e9 ent\u00e3o, n\u00e3o vi nenhum outro parlamentar atuando nessa causa. Hoje v\u00e1rias fam\u00edlias t\u00eam, pelo menos, um animal de estima\u00e7\u00e3o. Percebo que [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":15440,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"wpb_read_more":[],"footnotes":""},"categories":[234],"tags":[1899,1795],"class_list":["post-16044","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cb-poder","tag-animais-domesticos","tag-daniel-donizet"],"_links":{"self":[{"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/posts\/16044","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/comments?post=16044"}],"version-history":[{"count":1,"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/posts\/16044\/revisions"}],"predecessor-version":[{"id":16045,"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/posts\/16044\/revisions\/16045"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/media\/15440"}],"wp:attachment":[{"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/media?parent=16044"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/categories?post=16044"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/tags?post=16044"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}