{"id":16087,"date":"2019-08-01T07:43:43","date_gmt":"2019-08-01T10:43:43","guid":{"rendered":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/?p=16087"},"modified":"2019-08-01T07:43:43","modified_gmt":"2019-08-01T10:43:43","slug":"beneficiaria-de-casa-popular-obtem-direito-de-vender-imovel-antes-do-prazo","status":"publish","type":"post","link":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/beneficiaria-de-casa-popular-obtem-direito-de-vender-imovel-antes-do-prazo\/","title":{"rendered":"Benefici\u00e1ria de casa popular obt\u00e9m direito de vender im\u00f3vel antes do prazo"},"content":{"rendered":"<h6><strong>Coluna Eixo Capital\/Por Ana Maria Campos<\/strong><\/h6>\n<p>A pol\u00edtica habitacional do Distrito Federal estabelece que os im\u00f3veis cedidos pelos programas do GDF n\u00e3o podem ser vendidos por um prazo de 10 anos. Para driblar essa regra, muitos benefici\u00e1rios repassam as casas e apartamentos com contratos de gaveta, o que gerou questionamentos do Minist\u00e9rio P\u00fablico. Agora, uma decis\u00e3o da Justi\u00e7a abriu brecha para a livre negocia\u00e7\u00e3o dessas resid\u00eancias. A Vara de Registros P\u00fablicos do Tribunal de Justi\u00e7a autorizou a benefici\u00e1ria de um im\u00f3vel no Setor Jardins Mangueiral a negociar seu apartamento sete anos depois de ser contemplada pelo governo. \u201cSe o direito subjetivo da propriedade \u00e9 o mais amplo dentre todos os direitos reais, soa irrazo\u00e1vel impedir o propriet\u00e1rio de dispor livremente de seu im\u00f3vel, ainda que por breve lapso temporal. N\u00e3o existe propriedade sem o atributo da disposi\u00e7\u00e3o\u201d, defendeu o juiz Ricardo Norio Daitoku.<\/p>\n<h2>\n<strong>Risco de desvirtuamento<\/strong><\/h2>\n<p>A primeira propriet\u00e1ria comprou o im\u00f3vel em 2011, com financiamento da Caixa Econ\u00f4mica e, em 2018, o repassou por meio de escritura p\u00fablica de compra e venda. Mas, no momento do registro, o cart\u00f3rio questionou a transfer\u00eancia, com base na legisla\u00e7\u00e3o habitacional que estabelece a &#8220;inalienabilidade do im\u00f3vel a terceiros pelo prazo de 10 anos&#8221;. O caso foi parar na Justi\u00e7a. No processo, o promotor Nelson Faraco de Freitas, da Promotoria de Registros P\u00fablicos, argumentou que a mudan\u00e7a de entendimento poderia \u201cdesvirtuar o objetivo social do programa\u201d. Mas o TJ deu ganho de causa \u00e0 vendedora. A advogada Jaqueline Marques Toro, que atuou no processo, argumentou que bastaria a quita\u00e7\u00e3o do financiamento habitacional para que a propriet\u00e1ria pudesse negociar o im\u00f3vel. A tese prevaleceu e o processo j\u00e1 transitou em julgado.<\/p>\n<h2>\n<strong>Fiscaliza\u00e7\u00e3o<\/strong><\/h2>\n<p>O Minist\u00e9rio P\u00fablico vinha cobrando do governo rigor para evitar a venda de im\u00f3veis de programas habitacionais antes do prazo de 10 anos. A Promotoria de Justi\u00e7a de Defesa do Patrim\u00f4nio P\u00fablico e Social chegou a expedir recomenda\u00e7\u00e3o para que o GDF retomasse im\u00f3veis negociados antes de uma d\u00e9cada.<\/p>\n<h2>\n<strong>Fim de f\u00e9rias<\/strong><\/h2>\n<p>O recesso parlamentar acaba oficialmente hoje e, na primeira reuni\u00e3o do col\u00e9gio de l\u00edderes do semestre, os distritais devem avaliar a inclus\u00e3o em pauta de an\u00e1lise de 26 vetos, a homologa\u00e7\u00e3o de conv\u00eanios de ICMS, al\u00e9m do debate sobre a oitiva do presidente e do vice da Junta Comercial, que foram escolhidos sem um debate pr\u00e9vio na CLDF.<\/p>\n<h2><strong>Efeito Rob\u00e9rio<\/strong><\/h2>\n<p>O esc\u00e2ndalo envolvendo o deputado distrital Rob\u00e9rio Negreiros (PSD), que assinou as folhas de presen\u00e7a de dias em que estava nos Estados Unidos, deixou os parlamentares cautelosos. O distrital Eduardo Pedrosa (PTC) viajou \u00e0 Europa com a namorada no \u00faltimo dia 23 e s\u00f3 volta na pr\u00f3xima segunda-feira. Ele pediu licen\u00e7a \u00e0 Mesa Diretora para se ausentar do pa\u00eds e abriu m\u00e3o do sal\u00e1rio de hoje a segunda-feira, j\u00e1 que as f\u00e9rias terminaram. Segundo a assessoria, ele trabalhou durante o recesso.<\/p>\n<h2>\n<strong>Comitiva da Cidadania<\/strong><\/h2>\n<p>O governador Ibaneis Rocha levou ontem uma comitiva do GDF para reuni\u00e3o com o ministro da Cidadania, Osmar Terra. A meta do encontro era tratar da amplia\u00e7\u00e3o do contraturno escolar na rede p\u00fablica. Mas os integrantes do primeiro escal\u00e3o do governo t\u00eam a miss\u00e3o de buscar recursos e meios para executar projetos em parceria com o governo federal, em todas as \u00e1reas. Al\u00e9m de Ibaneis, participaram do encontro os secret\u00e1rios de Fazenda, Andr\u00e9 Clemente; de Justi\u00e7a, Gustavo Rocha; de Cultura, Ad\u00e3o C\u00e2ndido, e de Rela\u00e7\u00f5es Institucionais, V\u00edtor Paulo. \u201cO encontro foi perfeito. Uma visita bastante produtiva\u201d, resumiu Ibaneis. Ser\u00e1 formado um grupo de trabalho no minist\u00e9rio para colocar em pr\u00e1tica todos os projetos do DF que est\u00e3o em an\u00e1lise.<\/p>\n<h2><strong>DF no debate sobre a reforma tribut\u00e1ria<\/strong><\/h2>\n<p>O Distrito Federal sediou ontem uma reuni\u00e3o de secret\u00e1rios estaduais de Fazenda de todo o pa\u00eds. O chefe da pasta de S\u00e3o Paulo, o ex-ministro Henrique Meirelles, defendeu a aprova\u00e7\u00e3o da reforma tribut\u00e1ria no Congresso Nacional ainda neste ano. O grupo pediu a participa\u00e7\u00e3o dos estados na consolida\u00e7\u00e3o do texto.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Coluna Eixo Capital\/Por Ana Maria Campos A pol\u00edtica habitacional do Distrito Federal estabelece que os im\u00f3veis cedidos pelos programas do GDF n\u00e3o podem ser vendidos por um prazo de 10 anos. Para driblar essa regra, muitos benefici\u00e1rios repassam as casas e apartamentos com contratos de gaveta, o que gerou questionamentos do Minist\u00e9rio P\u00fablico. Agora, uma [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":16088,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"wpb_read_more":[],"footnotes":""},"categories":[234],"tags":[],"class_list":["post-16087","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cb-poder"],"_links":{"self":[{"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/posts\/16087","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/comments?post=16087"}],"version-history":[{"count":1,"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/posts\/16087\/revisions"}],"predecessor-version":[{"id":16089,"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/posts\/16087\/revisions\/16089"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/media\/16088"}],"wp:attachment":[{"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/media?parent=16087"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/categories?post=16087"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/tags?post=16087"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}