{"id":16195,"date":"2019-08-14T08:49:42","date_gmt":"2019-08-14T11:49:42","guid":{"rendered":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/?p=16195"},"modified":"2019-08-14T08:49:42","modified_gmt":"2019-08-14T11:49:42","slug":"multa-paga-por-luiz-estevao-ao-mp-e-usada-para-reformar-escola","status":"publish","type":"post","link":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/multa-paga-por-luiz-estevao-ao-mp-e-usada-para-reformar-escola\/","title":{"rendered":"Multa paga por Luiz Estev\u00e3o ao MP \u00e9 usada para reformar escola"},"content":{"rendered":"<h6><strong>Coluna Eixo Capital\/Por Ana Maria Campos<\/strong><\/h6>\n<p>As imagens acima mostram como \u00e9 importante o trabalho dos \u00f3rg\u00e3os de controle no combate aos desvios de recursos, improbidade administrativa e corrup\u00e7\u00e3o. Uma multa cobrada do senador cassado Luiz Estev\u00e3o pela Promotoria de Defesa do Patrim\u00f4nio P\u00fablico e Social (Prodep) mudou a realidade das crian\u00e7as que frequentam o Centro de Ensino Ponte Alta de Baixo, no Gama.<\/p>\n<p>A escola inaugurou a quadra poliesportiva e a pista de atletismo constru\u00eddas com recursos de multa aplicada em condena\u00e7\u00e3o em processos de improbidade administrativa. O valor tamb\u00e9m foi usado para a cobertura da \u00e1rea interna da escola. O col\u00e9gio que funciona h\u00e1 40 anos recebe 240 alunos da educa\u00e7\u00e3o infantil ao 9\u00ba ano e os estudantes nunca tiveram espa\u00e7o adequado para praticar esportes. V\u00e1rios desenhos feitos pelas crian\u00e7as emocionaram os promotores de Justi\u00e7a. Os alunos agradecem o Minist\u00e9rio P\u00fablico pela iniciativa.<\/p>\n<h2>\n<strong>Pagamento de impostos mais f\u00e1cil e r\u00e1pido<\/strong><\/h2>\n<p>Em tempos de pol\u00edtica para ampliar a arrecada\u00e7\u00e3o, a Secretaria de Fazenda, Planejamento, Or\u00e7amento e Gest\u00e3o tem bolado algumas estrat\u00e9gias para receber mais rapidamente os impostos devidos. Desde abril, por exemplo, est\u00e1 mais pr\u00e1tico calcular e pagar o imposto de heran\u00e7a e doa\u00e7\u00e3o, como \u00e9 conhecido o Imposto sobre Transmiss\u00e3o Causa Mortis e Doa\u00e7\u00e3o de Quaisquer Bens ou Direitos (ITCD). N\u00e3o \u00e9 mais necess\u00e1rio comparecer a uma ag\u00eancia da Receita, abrir um processo e aguardar sua tramita\u00e7\u00e3o, o que poderia levar at\u00e9 90 dias. O contribuinte pode emitir o boleto de pagamento pela internet. Para isso, basta acessar o portal ww.receita.fazenda.df.gov.br, preencher a declara\u00e7\u00e3o eletr\u00f4nica e um sistema desenvolvido pela secretaria calcula automaticamente o valor do imposto e gera o boleto de pagamento.<\/p>\n<h2>\n<strong>Bolsonaro exonera Fona<\/strong><\/h2>\n<p>Durou pouco a passagem do jornalista Paulo Fona pelo governo Bolsonaro. Nomeado na semana passada para o cargo de secret\u00e1rio de Imprensa da Presid\u00eancia da Rep\u00fablica, o ex-secret\u00e1rio de Comunica\u00e7\u00e3o do governo Rollemberg foi comunicado ontem de que estaria fora. Bolsonaro considerou o passado de Fona como ex-militante do PT. Fona trabalhou em v\u00e1rios ve\u00edculos de comunica\u00e7\u00e3o e em governos de diferentes partidos. Al\u00e9m de Rollemberg, Fona trabalhou com Joaquim Roriz (ent\u00e3o no MDB), com Yeda Crusius (PSDB) e Ronaldo Caiado (DEM).<\/p>\n<h2>\n<strong>Unidos para prestigiar novo advogado<\/strong><\/h2>\n<p>Advers\u00e1rios nas duas \u00faltimas elei\u00e7\u00f5es para o comando da OAB-DF, D\u00e9lio Lins e Silva J\u00fanior e Juliano Costa Couto se uniram para entregar a carteira da ordem ao novo advogado da cidade Gustavo Costa Couto. Filho do ex-presidente da OAB-DF, o jovem advogado passou no exame e j\u00e1 est\u00e1 advogando. A ca\u00e7ula de Juliano, Manuela, quem sabe um dia siga os mesmos passos, tamb\u00e9m participou da festa.<\/p>\n<h2>\n<strong>Cobran\u00e7a antes do vencimento<\/strong><\/h2>\n<p>A Secretaria de Fazenda, Planejamento, Or\u00e7amento e Gest\u00e3o adotou tamb\u00e9m estrat\u00e9gia de mercado para \u201clembrar\u201d os contribuintes de que a parcela do IPTU est\u00e1 para vencer. Antes mesmo do prazo estabelecido para pagamento, o \u00f3rg\u00e3o envia e-mail informando que a data est\u00e1 chegando. Esta \u00e9 uma forma educada de cobran\u00e7a.<\/p>\n<h2><strong><em>S\u00f3 papos<\/em><\/strong><\/h2>\n<blockquote><p>O que estamos vendo \u00e9 uma escalada autorit\u00e1ria, que come\u00e7a exatamente assim, com o uso pol\u00edtico das pol\u00edcias. Vamos enfrentar essa pr\u00e1tica e fazer este embate em todas as frentes, judicial, midi\u00e1tica, pol\u00edtica, at\u00e9 a verdade prevalecer.<\/p><\/blockquote>\n<p style=\"text-align: right\"><strong>Presidente do PT, Gleisi Hoffmann<\/strong><\/p>\n<blockquote><p>\nA Gleisi se supera, s\u00e9rio! Gleisi diz que PT vai processar Moro por \u00e1udio do PCC. Um bandido (PT) falando de outro bandido (PCC)&#8230; \u00c9 tipo novela mexicana rsrs<\/p><\/blockquote>\n<p style=\"text-align: right\"><strong>Deputado estadual Fernando Franscischini (PSL-PR)<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Coluna Eixo Capital\/Por Ana Maria Campos As imagens acima mostram como \u00e9 importante o trabalho dos \u00f3rg\u00e3os de controle no combate aos desvios de recursos, improbidade administrativa e corrup\u00e7\u00e3o. Uma multa cobrada do senador cassado Luiz Estev\u00e3o pela Promotoria de Defesa do Patrim\u00f4nio P\u00fablico e Social (Prodep) mudou a realidade das crian\u00e7as que frequentam o [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":16197,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"wpb_read_more":[],"footnotes":""},"categories":[234],"tags":[1927,1928,324,498],"class_list":["post-16195","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cb-poder","tag-escola","tag-gama","tag-luiz-estevao","tag-mpdft"],"_links":{"self":[{"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/posts\/16195","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/comments?post=16195"}],"version-history":[{"count":1,"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/posts\/16195\/revisions"}],"predecessor-version":[{"id":16198,"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/posts\/16195\/revisions\/16198"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/media\/16197"}],"wp:attachment":[{"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/media?parent=16195"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/categories?post=16195"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/tags?post=16195"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}