{"id":16337,"date":"2019-08-23T07:39:08","date_gmt":"2019-08-23T10:39:08","guid":{"rendered":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/?p=16337"},"modified":"2019-08-23T07:39:08","modified_gmt":"2019-08-23T10:39:08","slug":"tribunal-de-justica-recebe-denuncia-contra-diretores-da-taurus","status":"publish","type":"post","link":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/tribunal-de-justica-recebe-denuncia-contra-diretores-da-taurus\/","title":{"rendered":"Tribunal de Justi\u00e7a recebe den\u00fancia contra diretores da Taurus"},"content":{"rendered":"<h6><strong>Coluna Eixo Capital\/Por Ana Maria campos<\/strong><\/h6>\n<p>A 2\u00aa Turma Criminal do Tribunal de Justi\u00e7a do DF recebeu, por unanimidade, den\u00fancia contra diretores e representantes comerciais da Forja Taurus, fabricante de armas, por crimes contra as rela\u00e7\u00f5es de consumo. Cinco pessoas foram denunciadas pelo N\u00facleo de Controle Externo da Atividade Policial (Ncap) do Minist\u00e9rio P\u00fablico do Distrito Federal e Territ\u00f3rios (MPDFT) depois que uma investiga\u00e7\u00e3o apontou que a Pol\u00edcia Civil do DF foi induzida a erro a comprar armas de fogo defeituosas para seus integrantes que expuseram suas vidas em servi\u00e7o.<\/p>\n<p>Os diretores da empresa teriam vendido pistolas calibre .40 impr\u00f3prias para consumo, o que ficou evidenciado em acidentes ocorridos com policiais civis. Os desembargadores analisaram recurso do MPDFT contra decis\u00e3o do juiz Newton Ara\u00fajo, da 7\u00aa Vara Criminal, que havia rejeitado o recebimento da den\u00fancia, com base no artigo 395 do C\u00f3digo de Processo Penal, sob o fundamento de que n\u00e3o h\u00e1 justa causa para processar os representantes da Taurus. Agora, a a\u00e7\u00e3o penal come\u00e7ar\u00e1 a tramitar e os r\u00e9us ter\u00e3o possibilidade de apresentar defesa, assim como a acusa\u00e7\u00e3o poder\u00e1 defender as provas anexadas no processo.<\/p>\n<h2>\n<strong>Disparos acidentais<\/strong><\/h2>\n<p>A investiga\u00e7\u00e3o do NCAP apresenta nove laudos periciais que apontam diversos tipos de defeitos no lote de armas adquirido pela Pol\u00edcia Civil do DF, que levaram a disparos acidentais. H\u00e1 ainda 18 ocorr\u00eancias, sendo 13 no DF que registram incidentes em casos de queda no ch\u00e3o. Al\u00e9m da a\u00e7\u00e3o penal, os promotores do NCAP ajuizaram tamb\u00e9m uma a\u00e7\u00e3o civil p\u00fablica para cobrar os preju\u00edzos aos cofres p\u00fablicos. Todas as armas defeituosas foram substitu\u00eddas.<\/p>\n<h2>\n<strong>Distrital recebe atendimento m\u00e9dico<\/strong><\/h2>\n<p>Depois de Chico Vigilante (PT) e J\u00falia Lucy (Novo), o deputado Jo\u00e3o Cardoso (Avante) foi hospitalizado ontem. Ele passou mal na C\u00e2mara Legislativa e foi levado para atendimento no Santa L\u00facia. Teve fraqueza nas pernas e passava ontem por exames. Aliados pol\u00edticos do distrital dizem que Cardoso tem trabalhado exageradamente. Come\u00e7a antes de o Sol nascer e s\u00f3 chega em casa bem tarde.<\/p>\n<h2><strong>Siga o dinheiro<\/strong><\/h2>\n<p><em>R$ 96.510.593<\/em><\/p>\n<p>\u00c9 o valor previsto em preg\u00e3o eletr\u00f4nico da Secretaria de Educa\u00e7\u00e3o para confec\u00e7\u00e3o e distribui\u00e7\u00e3o de kits de uniforme escolar para estudantes da rede p\u00fablica de ensino do DF.<\/p>\n<h2><strong>A pergunta que n\u00e3o quer calar\u2026.<\/strong><\/h2>\n<p>Quem, afinal, o presidente Jair Bolsonaro vai nomear para a Procuradoria-Geral da Rep\u00fablica?<\/p>\n<h2>\n<strong>Faltou convencimento<\/strong><\/h2>\n<p>No meio pol\u00edtico, muita gente analisa nos bastidores que houve uma falha na Secretaria de Educa\u00e7\u00e3o no processo de discuss\u00e3o sobre a gest\u00e3o compartilhada com a PM na CEF 407 de Samambaia e no Gisno, as duas escolas que disseram n\u00e3o ao modelo de militariza\u00e7\u00e3o. Faltou um trabalho do governo com as fam\u00edlias para apontar as vantagens, o que levou a uma desvantagem do governo para os professores, com apoio do sindicato da categoria.<\/p>\n<h2>\n<strong>Quase R$ 2 bilh\u00f5es sem cobertura<\/strong><\/h2>\n<p>Em seu voto no relat\u00f3rio sobre as contas do \u00faltimo ano do governo Rollemberg, o conselheiro Manoel de Andrade, que votou contra a aprova\u00e7\u00e3o, apresenta um levantamento para justificar sua posi\u00e7\u00e3o. Segundo ele, em quatro anos, a administra\u00e7\u00e3o realizou despesas no montante de R$ 1,98 bilh\u00e3o sem cobertura contratual. O ano em que este procedimento atingiu maior cifra foi 2016, quando o governo pagou R$ 722,6 milh\u00f5es sem lastro. O relator das contas, conselheiro Renato Rainha, ressaltou, no entanto, que no ano em quest\u00e3o, 2018, houve uma expressiva redu\u00e7\u00e3o com a destina\u00e7\u00e3o de R$ 265,7 milh\u00f5es para gastos nessas circunst\u00e2ncias.<\/p>\n<h2><strong>TRE-DF nega abuso de poder pol\u00edtico na campanha de Rollemberg<\/strong><\/h2>\n<p>O Tribunal Regional Eleitoral (TRE-DF) rejeitou por unanimidade representa\u00e7\u00e3o do ex-deputado Alberto Fraga (DEM-DF) ajuizada contra Rodrigo Rollemberg por abuso de poder pol\u00edtico. A a\u00e7\u00e3o alegava que uma reuni\u00e3o no Condom\u00ednio Solar de Bras\u00edlia, realizada em setembro de 2018, teria sido usada com finalidade eleitoral. O ent\u00e3o governador esteve no loteamento, no Lago Sul, para tratar do andamento dos trabalhos de regulariza\u00e7\u00e3o dos muros e das portarias. O plen\u00e1rio do TRE-DF considerou que n\u00e3o h\u00e1 provas de qualquer ilicitude apresentada pelo advers\u00e1rio de Rollemberg na \u00faltima elei\u00e7\u00e3o.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Coluna Eixo Capital\/Por Ana Maria campos A 2\u00aa Turma Criminal do Tribunal de Justi\u00e7a do DF recebeu, por unanimidade, den\u00fancia contra diretores e representantes comerciais da Forja Taurus, fabricante de armas, por crimes contra as rela\u00e7\u00f5es de consumo. Cinco pessoas foram denunciadas pelo N\u00facleo de Controle Externo da Atividade Policial (Ncap) do Minist\u00e9rio P\u00fablico do [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":15422,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"wpb_read_more":[],"footnotes":""},"categories":[234],"tags":[498,1264],"class_list":["post-16337","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cb-poder","tag-mpdft","tag-taurus"],"_links":{"self":[{"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/posts\/16337","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/comments?post=16337"}],"version-history":[{"count":1,"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/posts\/16337\/revisions"}],"predecessor-version":[{"id":16339,"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/posts\/16337\/revisions\/16339"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/media\/15422"}],"wp:attachment":[{"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/media?parent=16337"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/categories?post=16337"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs2.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/tags?post=16337"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}