{"id":18829,"date":"2021-05-14T19:25:04","date_gmt":"2021-05-14T22:25:04","guid":{"rendered":"https:\/\/blogs2.correiobraziliense.com.br\/vicente\/?p=18829"},"modified":"2021-05-14T22:05:56","modified_gmt":"2021-05-15T01:05:56","slug":"tecnicos-da-economia-ministros-militares-sao-os-mais-gananciosos","status":"publish","type":"post","link":"https:\/\/blogs2.correiobraziliense.com.br\/vicente\/tecnicos-da-economia-ministros-militares-sao-os-mais-gananciosos\/","title":{"rendered":"T\u00e9cnicos da Economia: &#8220;Ministros militares s\u00e3o os mais gananciosos&#8221;"},"content":{"rendered":"<h2>A insatisfa\u00e7\u00e3o \u00e9 grande no Minist\u00e9rio da Economia, sobretudo, na Secretaria de Gest\u00e3o e Desenvolvimento Pessoal, de onde saiu a portaria 4.975, de 29 de abril, que burlou a Constitui\u00e7\u00e3o e criou o teto duplex para os sal\u00e1rios pagos pelo setor p\u00fablico. T\u00e9cnicos da pasta dizem que a regra s\u00f3 foi mudada porque &#8220;os ministros militares s\u00e3o gananciosos&#8221;.<\/h2>\n<p>&nbsp;<\/p>\n<p>No entender dos t\u00e9cnicos, n\u00e3o fosse a press\u00e3o dos ministros militares, o Pal\u00e1cio do Planalto n\u00e3o teria obrigado <a href=\"https:\/\/blogs2.correiobraziliense.com.br\/vicente\/palacio-do-planalto-obrigou-paulo-guedes-a-liberar-a-farra-de-salarios\/\">o ministro Paulo Guedes a passar por cima de suas convic\u00e7\u00f5es<\/a> e desrespeitar o que diz a Constitui\u00e7\u00e3o, que limita o teto salarial do setor p\u00fablico aos rendimentos recebidos pelos ministros do Supremo Tribunal Federal, de\u00a0R$ 39.293,32.<\/p>\n<p>&nbsp;<\/p>\n<p>Os t\u00e9cnicos do Minist\u00e9rio da Economia lembram que, no caso do ministro da Casa Civil, Luiz Eduardo Ramos, o contracheque ter\u00e1 aumento de 69% (R$ 27 mil), para R$ 66,4 mil. O ministro da Defesa, Walter Braga Netto, embolsar\u00e1 R$ 62 mil, ou R$ 22,8 mil a mais (alta de 58%). Ministro do Gabinete de Seguran\u00e7a Institucional, Augusto Heleno engordar\u00e1 a conta banc\u00e1ria em R$ 23,8 mil (mais 60%), com sal\u00e1rio de R$ 63 mil.<\/p>\n<p>&nbsp;<\/p>\n<p>A farra dos sal\u00e1rios beneficia, tamb\u00e9m, o presidente Jair Bolsonaro e o vice-presidente, Hamilton Mour\u00e3o. No caso de Bolsonaro, o aumento no contracheque ser\u00e1 de R$ 2.300, para R$ 41,6 mil. Mour\u00e3o passar\u00e1 a ganhar 62% mais, ou seja, R$ 63,5 mil.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Adapta\u00e7\u00f5es convenientes<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>Segundo os t\u00e9cnicos do Minist\u00e9rio da Economia, os ministros militares n\u00e3o se conformavam em ter que abrir m\u00e3o da maior parte dos rendimentos como generais, que, somados aos ganhos dos cargos no governo, entravam no abate teto. Agora, pela nova regra, o limite constitucional vale para cada contracheque. O que n\u00e3o exceder a R$ 39.239,32 pode ser somado e ir para a conta dos beneficiados.<\/p>\n<p>&nbsp;<\/p>\n<p>Os t\u00e9cnicos acrescentam, ainda, que o governo est\u00e1 alegando que a farra salarial est\u00e1 suportada por decis\u00f5es do Supremo. N\u00e3o \u00e9 bem assim. Houve, de acordo com os servidores, uma adapta\u00e7\u00e3o conveniente de posicionamentos do Supremo, com aval da Advocacia-Geral da Uni\u00e3o (AGU)<\/p>\n<p>&nbsp;<\/p>\n<p><em>Bras\u00edlia, 19h01min<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A insatisfa\u00e7\u00e3o \u00e9 grande no Minist\u00e9rio da Economia, sobretudo, na Secretaria de Gest\u00e3o e Desenvolvimento Pessoal, de onde saiu a portaria 4.975, de 29 de abril, que burlou a Constitui\u00e7\u00e3o e criou o teto duplex para os sal\u00e1rios pagos pelo setor p\u00fablico. T\u00e9cnicos da pasta dizem que a regra s\u00f3 foi mudada porque &#8220;os ministros [&hellip;]<\/p>\n","protected":false},"author":22,"featured_media":14408,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"wpb_read_more":[],"footnotes":""},"categories":[600],"tags":[926,589,2526,2787,5456],"class_list":["post-18829","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economia","tag-brasilia","tag-economia","tag-poder","tag-politica","tag-tecnicos-da-economia-ministros-militares-sao-os-mais-gananciosos"],"_links":{"self":[{"href":"https:\/\/blogs2.correiobraziliense.com.br\/vicente\/wp-json\/wp\/v2\/posts\/18829","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs2.correiobraziliense.com.br\/vicente\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs2.correiobraziliense.com.br\/vicente\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs2.correiobraziliense.com.br\/vicente\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs2.correiobraziliense.com.br\/vicente\/wp-json\/wp\/v2\/comments?post=18829"}],"version-history":[{"count":2,"href":"https:\/\/blogs2.correiobraziliense.com.br\/vicente\/wp-json\/wp\/v2\/posts\/18829\/revisions"}],"predecessor-version":[{"id":18836,"href":"https:\/\/blogs2.correiobraziliense.com.br\/vicente\/wp-json\/wp\/v2\/posts\/18829\/revisions\/18836"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs2.correiobraziliense.com.br\/vicente\/wp-json\/wp\/v2\/media\/14408"}],"wp:attachment":[{"href":"https:\/\/blogs2.correiobraziliense.com.br\/vicente\/wp-json\/wp\/v2\/media?parent=18829"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs2.correiobraziliense.com.br\/vicente\/wp-json\/wp\/v2\/categories?post=18829"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs2.correiobraziliense.com.br\/vicente\/wp-json\/wp\/v2\/tags?post=18829"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}